{"id":5488,"date":"2013-05-13T09:04:44","date_gmt":"2013-05-13T07:04:44","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5488"},"modified":"2025-01-23T10:25:05","modified_gmt":"2025-01-23T09:25:05","slug":"extremadura-democratiza-el-acceso-a-la-supercomputacion","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/","title":{"rendered":"Extremadura democratiza el acceso a la supercomputaci\u00f3n"},"content":{"rendered":"<p>La revista internacional\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.idg.es\/computerworld\/\">COMPUTERWORLD<\/a>\u00a0publica el art\u00edculo titulado \u00abExtremadura democratiza el acceso a la supercomputaci\u00f3n\u00bb en el que se destaca la labor realizada por la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a>\u00a0y su centro\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>\u00a0como entidades dinamizadoras del sector TI de la regi\u00f3n.<\/p>\n<p>Adem\u00e1s, se analizan las caracter\u00edsticas t\u00e9cnicas de la infraestructura del\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/lusitania\/\">Supercomputador LUSITANIA<\/a>\u00a0y las distintas \u00e1reas de investigaci\u00f3n de los\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/\">projects<\/a>\u00a0que se ejecutan desde los inicios del Centro C\u00e9nitS.<\/p>\n<p>La edici\u00f3n espa\u00f1ola de la revista\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.idg.es\/computerworld\/\">COMPUTERWORLD<\/a>\u00a0publica este art\u00edculo en relaci\u00f3n a la distinci\u00f3n que la revista internacional realiz\u00f3 en\u00a0<strong>Washington DC<\/strong>\u00a0entregando a la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a>\u00a0la laureada que la reconoc\u00eda como finalista en la categor\u00eda\u00a0<em>Economic Opportunity<\/em>\u00a0en la convocatoria\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/reconocimieno-internacional-computaex-y-cenits\/\">21st Century Achievement Award ComputerWorld Honors Program<\/a>\u00a0a la que se presentaron m\u00e1s de 1.000 candidaturas de organizaciones TI procedentes de todo el mundo.<\/p>\n<p>Puede acceder al art\u00edculo completo desde la siguiente direcci\u00f3n:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/enlaces\/publicaciones\/extremadura-democratiza-acceso-supercomputacion\/\">Extremadura democratiza el acceso a la supercomputaci\u00f3n<\/a><\/li>\n<\/ul>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/reconocimieno-internacional-computaex-y-cenits\/\">Reconocimieno internacional de COMPUTAEX y C\u00e9nitS<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/descripcion-la-fundacion-computaex-premiada-en-edicion-2011-del-computerworld-honors-program\/\">La Fundaci\u00f3n COMPUTAEX premiada en la edici\u00f3n de 2011 del \u00abComputerworld Honors Program\u00bb<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/revista-computerworld-destaca-centro-cenits-en-materia-supercomputacion\/\">La revista COMPUTERWORLD destaca el Centro C\u00e9nitS en materia de supercomputaci\u00f3n<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/descripcion-la-fundacion-computaex-finalista-en-21st-century-achievement-award-del-computerworld-honors-pr\/\">La Fundaci\u00f3n COMPUTAEX finalista en el 21st Century Achievement Award del ComputerWorld Honors Program<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La revista internacional\u00a0COMPUTERWORLD\u00a0publica el art\u00edculo titulado \u00abExtremadura democratiza el acceso a la supercomputaci\u00f3n\u00bb en el que se destaca la labor realizada por la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0y su centro\u00a0C\u00e9nitS\u00a0como entidades dinamizadoras del sector &#8230;<\/p>","protected":false},"author":1,"featured_media":5490,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-5488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-supercomputacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extremadura democratiza el acceso a la supercomputaci\u00f3n - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extremadura democratiza el acceso a la supercomputaci\u00f3n - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"La revista internacional\u00a0COMPUTERWORLD\u00a0publica el art\u00edculo titulado \u00abExtremadura democratiza el acceso a la supercomputaci\u00f3n\u00bb en el que se destaca la labor realizada por la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0y su centro\u00a0C\u00e9nitS\u00a0como entidades dinamizadoras del sector ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-13T07:04:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T09:25:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/01\/logocomputerworld.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"32\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Extremadura democratiza el acceso a la supercomputaci\u00f3n\",\"datePublished\":\"2013-05-13T07:04:44+00:00\",\"dateModified\":\"2025-01-23T09:25:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/\"},\"wordCount\":233,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logocomputerworld.jpg\",\"articleSection\":[\"Supercomputaci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/\",\"name\":\"Extremadura democratiza el acceso a la supercomputaci\u00f3n - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logocomputerworld.jpg\",\"datePublished\":\"2013-05-13T07:04:44+00:00\",\"dateModified\":\"2025-01-23T09:25:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logocomputerworld.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logocomputerworld.jpg\",\"width\":185,\"height\":32},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/supercomputacion\\\/extremadura-democratiza-el-acceso-a-la-supercomputacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Extremadura democratiza el acceso a la supercomputaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extremadura democratiza el acceso a la supercomputaci\u00f3n - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/","og_locale":"en_US","og_type":"article","og_title":"Extremadura democratiza el acceso a la supercomputaci\u00f3n - Fundaci\u00f3n COMPUTAEX","og_description":"La revista internacional\u00a0COMPUTERWORLD\u00a0publica el art\u00edculo titulado \u00abExtremadura democratiza el acceso a la supercomputaci\u00f3n\u00bb en el que se destaca la labor realizada por la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0y su centro\u00a0C\u00e9nitS\u00a0como entidades dinamizadoras del sector ...","og_url":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2013-05-13T07:04:44+00:00","article_modified_time":"2025-01-23T09:25:05+00:00","og_image":[{"width":185,"height":32,"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/01\/logocomputerworld.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#article","isPartOf":{"@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Extremadura democratiza el acceso a la supercomputaci\u00f3n","datePublished":"2013-05-13T07:04:44+00:00","dateModified":"2025-01-23T09:25:05+00:00","mainEntityOfPage":{"@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/"},"wordCount":233,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logocomputerworld.jpg","articleSection":["Supercomputaci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/","url":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/","name":"Extremadura democratiza el acceso a la supercomputaci\u00f3n - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#primaryimage"},"image":{"@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logocomputerworld.jpg","datePublished":"2013-05-13T07:04:44+00:00","dateModified":"2025-01-23T09:25:05+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logocomputerworld.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logocomputerworld.jpg","width":185,"height":32},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/supercomputacion\/extremadura-democratiza-el-acceso-a-la-supercomputacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Extremadura democratiza el acceso a la supercomputaci\u00f3n"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=5488"}],"version-history":[{"count":1,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5488\/revisions"}],"predecessor-version":[{"id":5491,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5488\/revisions\/5491"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/5490"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=5488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=5488"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=5488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}