{"id":5301,"date":"2013-02-11T08:29:56","date_gmt":"2013-02-11T07:29:56","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5301"},"modified":"2025-01-23T09:50:08","modified_gmt":"2025-01-23T08:50:08","slug":"la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/","title":{"rendered":"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n"},"content":{"rendered":"<p>The\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.fcsc.es\/\">Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Castilla y Le\u00f3n<\/a>\u00a0y la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a>\u00a0han firmado un convenio de colaboraci\u00f3n con el objeto de compartir experiencias y elaborar proyectos conjuntos en el \u00e1mbito de la I+D+i, la formaci\u00f3n y la divulgaci\u00f3n cient\u00edfica.<\/p>\n<p>Ambas fundaciones constituyen en la actualidad elementos fundamentales en el apoyo al desarrollo de programas de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica en sus respectivas Comunidades Aut\u00f3nomas y Espa\u00f1a mediante el uso del c\u00e1lculo intensivo.<\/p>\n<p>La FCSCL tiene por objeto la promoci\u00f3n de acciones de innovaci\u00f3n en el mundo de la Sociedad del Conocimiento y en el \u00e1rea del c\u00e1lculo intensivo, las comunicaciones y los servicios avanzados a fin de contribuir al desarrollo econ\u00f3mico de la Comunidad de Castilla y Le\u00f3n y a la mejora de la competitividad de las empresas.<\/p>\n<p>M\u00e1s informaci\u00f3n:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.fcsc.es\/\">FCSCL<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a><\/li>\n<\/ul>\n<p>Nota de prensa:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/convenios\/20130204-fundacion-centro-supercomputacion-castilla-leon\/\">FCSCL y COMPUTAEX<\/a><\/li>\n<\/ul>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/\/en\/gobex.es\/salaprensa\/view\/press\/press\/detalle.php\/?hl=es&amp;id=7846\">Las fundaciones que gestionan los servicios p\u00fablicos de supercomputaci\u00f3n de Extremadura y Castilla y Le\u00f3n firman un convenio de colaboraci\u00f3n &#8211; GobEx<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.europapress.es\/extremadura\/noticia-fundaciones-gestionan-servicios-supercomputacion-extremadura-castilla-leon-firman-convenio-20130210130706.html\">Las fundaciones que gestionan los servicios de supercomputaci\u00f3n de Extremadura y Castilla y Le\u00f3n firman un convenio &#8211; EuropaPress<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.abc.es\/agencias\/noticia.asp?noticia=1350912\">Extremadura y Castilla y Le\u00f3n estrechan su colaboraci\u00f3n proyectos I+D+i &#8211; ABC<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/\/en\/noticias.lainformacion.com\/ciencia-y-tecnologia\/ciencias-aplicadas\/las-fundaciones-que-gestionan-los-servicios-de-supercomputacion-de-extremadura-y-castilla-y-leon-firman-un-convenio_dnxSmpgaXiur9Epgbd6w82\/\">Las fundaciones que gestionan los servicios de supercomputaci\u00f3n de Extremadura y Castilla y Le\u00f3n firman un convenio &#8211; lainformacion.com<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.teinteresa.es\/extremadura\/badajoz\/descripcion-la-fundaciones-supercomputacion-Extremadura-Castilla-Leon_0_863314076.html\">Las fundaciones que gestionan los servicios p\u00fablicos de supercomputaci\u00f3n de Extremadura y Castilla y Le\u00f3n firman un convenio de colaboraci\u00f3n &#8211; teinteresa.es<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.extremaduradehoy.com\/periodico\/ultima_hora\/las_fundaciones_que_gestionan_los_servicios_supercomputacion_extremadura-178243.html\">Las fundaciones que gestionan los servicios de supercomputaci\u00f3n de Extremadura y Castilla y Le\u00f3n firman un convenio &#8211; Extremadura de HOY<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.que.es\/badajoz\/201302101307-fundaciones-gestionan-servicios-supercomputacion-extremadura-epi.html\">Las fundaciones que gestionan los servicios de supercomputaci\u00f3n de Extremadura y Castilla y Le\u00f3n firman un convenio &#8211; Qu\u00e9!<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La\u00a0Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Castilla y Le\u00f3n\u00a0y la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0han firmado un convenio de colaboraci\u00f3n con el objeto de compartir experiencias y elaborar proyectos conjuntos en el \u00e1mbito de la &#8230;<\/p>","protected":false},"author":1,"featured_media":5304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-5301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colaboracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"La\u00a0Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Castilla y Le\u00f3n\u00a0y la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0han firmado un convenio de colaboraci\u00f3n con el objeto de compartir experiencias y elaborar proyectos conjuntos en el \u00e1mbito de la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-11T07:29:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T08:50:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"62\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n\",\"datePublished\":\"2013-02-11T07:29:56+00:00\",\"dateModified\":\"2025-01-23T08:50:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-fcscl.jpg\",\"articleSection\":[\"Colaboraci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/\",\"name\":\"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-fcscl.jpg\",\"datePublished\":\"2013-02-11T07:29:56+00:00\",\"dateModified\":\"2025-01-23T08:50:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-fcscl.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo-fcscl.jpg\",\"width\":185,\"height\":62},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/","og_locale":"en_US","og_type":"article","og_title":"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n - Fundaci\u00f3n COMPUTAEX","og_description":"La\u00a0Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Castilla y Le\u00f3n\u00a0y la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0han firmado un convenio de colaboraci\u00f3n con el objeto de compartir experiencias y elaborar proyectos conjuntos en el \u00e1mbito de la ...","og_url":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2013-02-11T07:29:56+00:00","article_modified_time":"2025-01-23T08:50:08+00:00","og_image":[{"width":185,"height":62,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n","datePublished":"2013-02-11T07:29:56+00:00","dateModified":"2025-01-23T08:50:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/"},"wordCount":331,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg","articleSection":["Colaboraci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/","url":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/","name":"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg","datePublished":"2013-02-11T07:29:56+00:00","dateModified":"2025-01-23T08:50:08+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg","width":185,"height":62},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=5301"}],"version-history":[{"count":1,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5301\/revisions"}],"predecessor-version":[{"id":5305,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5301\/revisions\/5305"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/5304"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=5301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=5301"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=5301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}