{"id":5226,"date":"2013-07-11T08:11:52","date_gmt":"2013-07-11T06:11:52","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5226"},"modified":"2025-01-23T09:54:44","modified_gmt":"2025-01-23T08:54:44","slug":"cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/","title":{"rendered":"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida"},"content":{"rendered":"<p>Desde julio de 2009, el\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n<\/a>\u00a0(C\u00e9nitS) ha dado cobertura a 50\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/\">proyectos de investigaci\u00f3n<\/a>\u00a0en el \u00e1mbito de las\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/ciencias-tierra\/\">Ciencias de la Tierra<\/a>,\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/ciencias-vida\/\">Ciencias de la Vida<\/a>\u00a0and\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/ciencias-informaticas\/\">Ciencias Inform\u00e1ticas y de Comunicaciones<\/a>. Durante este tiempo, C\u00e9nitS tambi\u00e9n ha colaborado con m\u00faltiples empresas, instituciones y otros centros tecnol\u00f3gicos en el desarrollo de proyectos de innovaci\u00f3n y en propuestas de proyecto destinadas a convocatorias competitivas regionales, nacionales e internacionales.<\/p>\n<p>El trabajo realizado este a\u00f1o ha dado su fruto en estos dos \u00faltimos meses, tras confirmarse la concesi\u00f3n de cuatro proyectos de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/240613-computaex-trabaja-proyecto-educativo-sobre-green-ict-nivel-europeo\/\">e-InfraNET Sustainability Training and Educational Resource (EISTER)<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/280613-fundacion-computaex-colabora-proyecto-europeo-desarrollo-infraestructuras-tecnologic\/\">Desarrollo de una red de infraestructuras federadas para la generaci\u00f3n de servicios de virtualizaci\u00f3n de puestos de trabajo (FI4VDI)<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/040713-computaex-participa-proyecto-nacional-sobre-centros-datos-sostenibles\/\">Smart Green Data Center (SGDATACENTER)<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/modernizacion-e-innovacion-tecnologica-con-base-tic-sectores-estrategicos-tradicionales\/\">Modernizaci\u00f3n e Innovaci\u00f3n Tecnol\u00f3gica con base TIC en sectores estrat\u00e9gicos y tradicionales (MITTIC)<\/a><\/li>\n<\/ul>\n<p>The\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/computaex\/\">COMPUTAEX Foundation<\/a>, encargada de la explotaci\u00f3n y gesti\u00f3n de C\u00e9nitS y el\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/lusitania\/\">supercomputador LUSITANIA<\/a>, recoge la trayectoria del centro en las\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/memoria-anual\/\">memorias anuales<\/a>, donde se puede consultar informaci\u00f3n extendida sobre\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/\">projects<\/a>,\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/convenios\/\">convenios de colaboraci\u00f3n<\/a>,\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/enlaces\/publicaciones\/\">publicaciones<\/a>\u00a0o\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/enlaces\/casos-exito\/\">casos de \u00e9xito<\/a>, entre otros puntos de inter\u00e9s.<\/p>","protected":false},"excerpt":{"rendered":"<p>Desde julio de 2009, el\u00a0Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n\u00a0(C\u00e9nitS) ha dado cobertura a 50\u00a0proyectos de investigaci\u00f3n\u00a0en el \u00e1mbito de las\u00a0Ciencias de la Tierra,\u00a0Ciencias de la Vida\u00a0y\u00a0Ciencias Inform\u00e1ticas &#8230;<\/p>","protected":false},"author":1,"featured_media":5227,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-5226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-supercomputacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Desde julio de 2009, el\u00a0Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n\u00a0(C\u00e9nitS) ha dado cobertura a 50\u00a0proyectos de investigaci\u00f3n\u00a0en el \u00e1mbito de las\u00a0Ciencias de la Tierra,\u00a0Ciencias de la Vida\u00a0y\u00a0Ciencias Inform\u00e1ticas ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-11T06:11:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T08:54:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/supercomputador-lusitania.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"123\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida\",\"datePublished\":\"2013-07-11T06:11:52+00:00\",\"dateModified\":\"2025-01-23T08:54:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/\"},\"wordCount\":240,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/supercomputador-lusitania.jpg\",\"articleSection\":[\"Supercomputaci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/\",\"name\":\"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/supercomputador-lusitania.jpg\",\"datePublished\":\"2013-07-11T06:11:52+00:00\",\"dateModified\":\"2025-01-23T08:54:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/supercomputador-lusitania.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/supercomputador-lusitania.jpg\",\"width\":185,\"height\":123},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/","og_locale":"en_US","og_type":"article","og_title":"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida - Fundaci\u00f3n COMPUTAEX","og_description":"Desde julio de 2009, el\u00a0Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n\u00a0(C\u00e9nitS) ha dado cobertura a 50\u00a0proyectos de investigaci\u00f3n\u00a0en el \u00e1mbito de las\u00a0Ciencias de la Tierra,\u00a0Ciencias de la Vida\u00a0y\u00a0Ciencias Inform\u00e1ticas ...","og_url":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2013-07-11T06:11:52+00:00","article_modified_time":"2025-01-23T08:54:44+00:00","og_image":[{"width":185,"height":123,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/supercomputador-lusitania.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida","datePublished":"2013-07-11T06:11:52+00:00","dateModified":"2025-01-23T08:54:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/"},"wordCount":240,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/supercomputador-lusitania.jpg","articleSection":["Supercomputaci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/","url":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/","name":"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/supercomputador-lusitania.jpg","datePublished":"2013-07-11T06:11:52+00:00","dateModified":"2025-01-23T08:54:44+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/supercomputador-lusitania.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/supercomputador-lusitania.jpg","width":185,"height":123},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/supercomputacion\/cenits-y-el-supercomputador-lusitania-abordan-medio-centenar-de-proyectos-en-sus-primeros-cuatro-anos-de-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"C\u00e9nitS y el supercomputador LUSITANIA abordan medio centenar de proyectos en sus primeros cuatro a\u00f1os de vida"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=5226"}],"version-history":[{"count":1,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5226\/revisions"}],"predecessor-version":[{"id":5228,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/5226\/revisions\/5228"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/5227"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=5226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=5226"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=5226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}