{"id":4621,"date":"2017-04-04T09:11:19","date_gmt":"2017-04-04T07:11:19","guid":{"rendered":"http:\/\/10.128.3.28\/?p=4621"},"modified":"2025-01-23T09:08:12","modified_gmt":"2025-01-23T08:08:12","slug":"impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/","title":{"rendered":"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC"},"content":{"rendered":"<p>El pasado 23 de marzo, en el marco del 60 aniversario del Tratado de Roma, siete pa\u00edses de la Uni\u00f3n Europea (Espa\u00f1a, Alemania, Francia, Italia, Luxemburgo, Pa\u00edses Bajos y Portugal) firmaron en Roma la declaraci\u00f3n EuroHPC, cuyo objetivo es que Europa albergue en 2022 supercomputadores de nueva generaci\u00f3n.<\/p>\n<p>La iniciativa considera las recomendaciones de la Comisi\u00f3n Europea sobre supercomputaci\u00f3n en tecnolog\u00eda exascale, la cual permite realizar un trill\u00f3n de operaciones por segundo, alcanzando velocidades mil veces mayores que las que ofrecen los supercomputadores actuales. As\u00ed, se pretende impulsar dicha tecnolog\u00eda en Europa, asegurando la adquisici\u00f3n de los supercomputadores del futuro al mismo tiempo que se ampliar\u00e1n las posibilidades de las empresas y las administraciones p\u00fablicas para acceder a los mismos. Esto tendr\u00e1 un importante efecto en distintas \u00e1reas cient\u00edfico-tecnol\u00f3gicas, como la medicina, la industria farmace\u00fatica y la biotecnolog\u00eda, agroindustria, nuevos materiales, energ\u00eda, seguridad y comunicaciones, entre muchas otras.<\/p>\n<p>La hoja de ruta a seguir durante los pr\u00f3ximos a\u00f1os, as\u00ed como la propia movilizaci\u00f3n de fondos europeos que supondr\u00e1 el impulso para esta tecnolog\u00eda, ser\u00e1n definidos a trav\u00e9s de un foro, previsto por la declaraci\u00f3n EuroHPC. La\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.bsc.es\/res-intranet\/\" target=\"_blank\" rel=\"noopener\">Red Espa\u00f1ola de Supercomputaci\u00f3n<\/a>, de la que forma parte la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/descripcion-la-fundacion\">Fundaci\u00f3n COMPUTAEX<\/a>, jugar\u00e1 un papel clave en la implementaci\u00f3n de este acuerdo, que permitir\u00e1 a Espa\u00f1a situarse en la vanguardia de la supercomputaci\u00f3n.<\/p>\n<p>M\u00e1s informaci\u00f3n:<\/p>\n<ul>\n<li>Acuerdo de colaboraci\u00f3n, firmado por los siete pa\u00edses europeos [<a class=\"views-ajax-processed-processed\" href=\"http:\/ec.europa.eu\/information_society\/newsroom\/image\/document\/2017-12\/signature_hpc_43815.pdf\" target=\"_blank\" rel=\"noopener\">pdf<\/a>]<\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"https:\/ec.europa.eu\/digital-single-market\/en\/news\/eu-ministers-commit-digitising-europe-high-performance-computing-power\" target=\"_blank\" rel=\"noopener\">EU ministers commit to digitising Europe with high-performance computing power<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 23 de marzo, en el marco del 60 aniversario del Tratado de Roma, siete pa\u00edses de la Uni\u00f3n Europea (Espa\u00f1a, Alemania, Francia, Italia, Luxemburgo, Pa\u00edses Bajos y Portugal) &#8230;<\/p>","protected":false},"author":1,"featured_media":3949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-4621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-supercomputacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"El pasado 23 de marzo, en el marco del 60 aniversario del Tratado de Roma, siete pa\u00edses de la Uni\u00f3n Europea (Espa\u00f1a, Alemania, Francia, Italia, Luxemburgo, Pa\u00edses Bajos y Portugal) ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-04T07:11:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T08:08:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20220114_seminario-res.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"101\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC\",\"datePublished\":\"2017-04-04T07:11:19+00:00\",\"dateModified\":\"2025-01-23T08:08:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/\"},\"wordCount\":288,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220114_seminario-res.jpg\",\"articleSection\":[\"Supercomputaci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/\",\"name\":\"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220114_seminario-res.jpg\",\"datePublished\":\"2017-04-04T07:11:19+00:00\",\"dateModified\":\"2025-01-23T08:08:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220114_seminario-res.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220114_seminario-res.jpg\",\"width\":185,\"height\":101},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/","og_locale":"en_US","og_type":"article","og_title":"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC - Fundaci\u00f3n COMPUTAEX","og_description":"El pasado 23 de marzo, en el marco del 60 aniversario del Tratado de Roma, siete pa\u00edses de la Uni\u00f3n Europea (Espa\u00f1a, Alemania, Francia, Italia, Luxemburgo, Pa\u00edses Bajos y Portugal) ...","og_url":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2017-04-04T07:11:19+00:00","article_modified_time":"2025-01-23T08:08:12+00:00","og_image":[{"width":185,"height":101,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20220114_seminario-res.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC","datePublished":"2017-04-04T07:11:19+00:00","dateModified":"2025-01-23T08:08:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/"},"wordCount":288,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220114_seminario-res.jpg","articleSection":["Supercomputaci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/","url":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/","name":"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220114_seminario-res.jpg","datePublished":"2017-04-04T07:11:19+00:00","dateModified":"2025-01-23T08:08:12+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220114_seminario-res.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220114_seminario-res.jpg","width":185,"height":101},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/supercomputacion\/impulso-europeo-a-la-supercomputacion-con-la-firma-de-la-declaracion-eurohpc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Impulso europeo a la Supercomputaci\u00f3n con la Firma de la Declaraci\u00f3n EuroHPC"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/4621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=4621"}],"version-history":[{"count":1,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/4621\/revisions"}],"predecessor-version":[{"id":4622,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/4621\/revisions\/4622"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3949"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=4621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=4621"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=4621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}