{"id":3910,"date":"2022-01-16T11:31:49","date_gmt":"2022-01-16T10:31:49","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3910"},"modified":"2025-01-24T09:34:31","modified_gmt":"2025-01-24T08:34:31","slug":"convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/","title":{"rendered":"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones"},"content":{"rendered":"<p><a class=\"views-ajax-processed-processed\" href=\"\/descripcion-la-fundacion\">COMPUTAEX<\/a>\u00a0participa, en el marco del proyecto\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/eurocc-spain.res.es\/\" target=\"_blank\" rel=\"noopener\">EuroCC<\/a>, en una\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/eurocc-spain.res.es\/convocatoria-eurocc-spain-testbed\/\" target=\"_blank\" rel=\"noopener\">convocatoria<\/a>\u00a0a trav\u00e9s de la cual ofrece acceso sin coste a empresas y administraciones p\u00fablicas espa\u00f1olas a recursos de c\u00f3mputo de alto rendimiento (HPC, High-Performance Computing) de\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.cenits.es\/cenits\">C\u00e9nitS<\/a>.<\/p>\n<p>Estos recursos deber\u00e1n ser destinados por los beneficiarios a la realizaci\u00f3n de actividades de I+D+i, tales como pruebas de concepto, ensayos de escalabilidad, proyectos piloto o evaluaci\u00f3n de aplicaciones inform\u00e1ticas, entre otras. Asimismo, estas actividades deben ser financiables bajo las condiciones impuestas por la\u00a0<em>European High-Performance Computing Joint Undertaking<\/em>\u00a0(<a class=\"views-ajax-processed-processed\" href=\"https:\/eurohpc-ju.europa.eu\/\" target=\"_blank\" rel=\"noopener\">EuroHPC JU<\/a>) y el Programa Horizonte 2020 (<a class=\"views-ajax-processed-processed\" href=\"https:\/ec.europa.eu\/programmes\/horizon2020\/\" target=\"_blank\" rel=\"noopener\">H2020<\/a>) de la Comisi\u00f3n Europea. Quedar\u00e1n as\u00ed excluidos procesos de producci\u00f3n o explotaci\u00f3n pertenecientes a la propia actividad empresarial del solicitante.<\/p>\n<p>La presente convocatoria oferta un total de 24 actividades de I+D+i entre los centros de supercomputaci\u00f3n participantes. En concreto, C\u00e9nitS-COMPUTAEX ofrece un total de 5 actividades, con un total de 40 horas de asesoramiento por actividad, y ofreciendo los siguientes servicios relacionados con el Supercomputador\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.cenits.es\/lusitania-III\">LUSITANIA III<\/a>: 50K horas de CPU, 256 procesadores simult\u00e1neos, 100 horas de GPU, 4 GPUs simult\u00e1neas y 5TB de almacenamiento.<\/p>\n<p>El acceso a los recursos disponibles tendr\u00e1 una duraci\u00f3n m\u00e1xima de 3 meses, por lo que esta convocatoria no es adecuada para el desarrollo de grandes proyectos con alta exigencia de recursos.<\/p>\n<p>El\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/eurocc-spain.res.es\/inscripcion-jornada\/\" target=\"_blank\" rel=\"noopener\">formulario de solicitud<\/a>\u00a0debe ser enviado a\u00a0<a class=\"spamspan views-ajax-processed-processed\" href=\"mailto:eurocc-testbed@cesga.es\">eurocc-testbed@cesga.es<\/a>, indicando en el asunto \u201cSOLICITUD + nombre de la empresa\/administraci\u00f3n solicitante\u201d. Una vez recibido, se asignar\u00e1 personal para la valoraci\u00f3n de la propuesta, teniendo en cuenta criterios de viabilidad t\u00e9cnica en los l\u00edmites de recursos y plazos marcados, as\u00ed como la justificaci\u00f3n del uso de HPC para la actividad propuesta.<\/p>\n<p>La recepci\u00f3n de solicitudes ser\u00e1 ininterrumpida hasta agotar los recursos ofertados, con un plazo estimado de respuesta de 2 semanas.<\/p>\n<p>Ver\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/20211013_infografia-eurocc-testbed\/\" target=\"_blank\" rel=\"noopener\">infograf\u00eda de la convocatoria<\/a>.<br \/>\nVer\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/eurocc-spain.res.es\/wp-content\/uploads\/2021\/10\/Convocatoria_EuroCC_Spain_testbed_v1_30092021.pdf\" target=\"_blank\" rel=\"noopener\">bases de la convocatoria<\/a>.<br \/>\nVer\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/eurocc-spain.res.es\/wp-content\/uploads\/2021\/10\/Formulario_EuroCC_Spain_testbed_v1_28092021.pdf\" target=\"_blank\" rel=\"noopener\">formulario de inscripci\u00f3n<\/a>.<br \/>\nVer\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/eurocc-spain.res.es\/convocatoria-eurocc-spain-testbed\/\" target=\"_blank\" rel=\"noopener\">web de la convocatoria<\/a>.<\/p>\n<p>M\u00e1s informaci\u00f3n:<\/p>\n<ul>\n<li>COMPUTAEX ofrecer\u00e1 servicios gratuitos de supercomputaci\u00f3n a empresas y administraciones p\u00fablicas a trav\u00e9s del programa EuroCC Spain Testbed [<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.juntaex.es\/comunicacion\/noticia&amp;idPub=36310\" target=\"_blank\" rel=\"noopener\">Junta de Extremadura<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.extremadura.com\/noticias\/2022\/04\/07\/computaex-ofrecera-servicios-gratuitos-de-supercomputacion-a-empresas-y-administraciones-publicas-a-traves-del-programa-eurocc-spain-testbed\" target=\"_blank\" rel=\"noopener\">Extremadura.com<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.noticiasextremadura.es\/computaex-ofrecera-servicios-gratuitos-de-supercomputacion-a-empresas-y-administraciones-publicas-a-traves-del-programa-eurocc-spain-testbed\/\" target=\"_blank\" rel=\"noopener\">Noticias Extremadura<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/digitalextremadura.com\/computaex-ofrecera-servicios-gratuitos-de-supercomputacion-a-empresas-y-administraciones-publicas-a-traves-del-programa-eurocc-spain-testbed\/\" target=\"_blank\" rel=\"noopener\">Digital Extremadura<\/a>].<\/li>\n<li>Computaex ofrecer\u00e1 servicios gratuitos supercomputaci\u00f3n con programa EuroCC Spain Testbed [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.regiondigital.com\/noticias\/tecnologia\/360803-computaex-ofrecera-servicios-gratuitos-supercomputacion-con-programa-eurocc-spain-testbed.html\" target=\"_blank\" rel=\"noopener\">Regi\u00f3n Digital<\/a>].<\/li>\n<li>Computaex ofrecer\u00e1 servicios gratuitos de supercomputaci\u00f3n [<a class=\"views-ajax-processed-processed\" href=\"https:\/avuelapluma.es\/computaex-ofrecera-servicios-gratuitos-de-supercomputacion\/\" target=\"_blank\" rel=\"noopener\">Avuelapluma<\/a>].<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>COMPUTAEX\u00a0participa, en el marco del proyecto\u00a0EuroCC, en una\u00a0convocatoria\u00a0a trav\u00e9s de la cual ofrece acceso sin coste a empresas y administraciones p\u00fablicas espa\u00f1olas a recursos de c\u00f3mputo de alto rendimiento (HPC, &#8230;<\/p>","protected":false},"author":1,"featured_media":3911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-3910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"COMPUTAEX\u00a0participa, en el marco del proyecto\u00a0EuroCC, en una\u00a0convocatoria\u00a0a trav\u00e9s de la cual ofrece acceso sin coste a empresas y administraciones p\u00fablicas espa\u00f1olas a recursos de c\u00f3mputo de alto rendimiento (HPC, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-16T10:31:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T08:34:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20220405_eurocc_testbed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones\",\"datePublished\":\"2022-01-16T10:31:49+00:00\",\"dateModified\":\"2025-01-24T08:34:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/\"},\"wordCount\":412,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220405_eurocc_testbed.jpg\",\"articleSection\":[\"Proyectos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/\",\"name\":\"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220405_eurocc_testbed.jpg\",\"datePublished\":\"2022-01-16T10:31:49+00:00\",\"dateModified\":\"2025-01-24T08:34:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220405_eurocc_testbed.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220405_eurocc_testbed.jpg\",\"width\":185,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/","og_locale":"en_US","og_type":"article","og_title":"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones - Fundaci\u00f3n COMPUTAEX","og_description":"COMPUTAEX\u00a0participa, en el marco del proyecto\u00a0EuroCC, en una\u00a0convocatoria\u00a0a trav\u00e9s de la cual ofrece acceso sin coste a empresas y administraciones p\u00fablicas espa\u00f1olas a recursos de c\u00f3mputo de alto rendimiento (HPC, ...","og_url":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2022-01-16T10:31:49+00:00","article_modified_time":"2025-01-24T08:34:31+00:00","og_image":[{"width":185,"height":185,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20220405_eurocc_testbed.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones","datePublished":"2022-01-16T10:31:49+00:00","dateModified":"2025-01-24T08:34:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/"},"wordCount":412,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220405_eurocc_testbed.jpg","articleSection":["Proyectos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/","url":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/","name":"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220405_eurocc_testbed.jpg","datePublished":"2022-01-16T10:31:49+00:00","dateModified":"2025-01-24T08:34:31+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220405_eurocc_testbed.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220405_eurocc_testbed.jpg","width":185,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/proyectos\/convocatoria-de-proyectos-testbed-para-el-acceso-gratuito-de-empresas-y-administraciones-publicas-a-recursos-de-computacion-de-altas-prestaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Convocatoria de proyectos testbed para el acceso gratuito de empresas y administraciones p\u00fablicas a recursos de computaci\u00f3n de altas prestaciones"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=3910"}],"version-history":[{"count":3,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3910\/revisions"}],"predecessor-version":[{"id":6292,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3910\/revisions\/6292"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3911"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=3910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=3910"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=3910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}