{"id":3850,"date":"2022-09-08T10:43:37","date_gmt":"2022-09-08T08:43:37","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3850"},"modified":"2025-01-22T12:44:48","modified_gmt":"2025-01-22T11:44:48","slug":"la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/","title":{"rendered":"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios."},"content":{"rendered":"<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Durante los d\u00edas 14 y 15 de septiembre, la Red Espa\u00f1ola de Supercomputaci\u00f3n (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.res.es\/\" target=\"_blank\" rel=\"noopener\">RES<\/a>) celebrar\u00e1 en C\u00e1ceres su\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.res.es\/es\/eventos\/16th-users-conference\" target=\"_blank\" rel=\"noopener\">16\u00aa Conferencia de Usuarios<\/a>, con el objetivo principal de compartir conocimientos y experiencias en el uso de la computaci\u00f3n de alto rendimiento. El evento se desarrollar\u00e1 en la sede de\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/cenits\">C\u00e9nitS<\/a>, el Centro Extreme\u00f1o de Investigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n, y ser\u00e1 organizado conjuntamente por la Fundaci\u00f3n\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/descripcion-la-fundacion\">COMPUTAEX<\/a>\u00a0y el Centro Extreme\u00f1o de Tecnolog\u00edas Avanzadas\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.ceta-ciemat.es\/\" target=\"_blank\" rel=\"noopener\">CETA-CIEMAT<\/a>, como miembros de la RES.<\/p>\n<p>La inauguraci\u00f3n tendr\u00e1 lugar el mi\u00e9rcoles 14 a las 12:00 horas y contar\u00e1 con la presencia del\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.juntaex.es\/con02\/consejero-de-economia-ciencia-y-agenda-digital\" target=\"_blank\" rel=\"noopener\">Consejero de Econom\u00eda Ciencia y Agenda Digital<\/a>, Don Rafael Espa\u00f1a Santamar\u00eda, y el Subdirector General de Grandes Instalaciones Cient\u00edfico-T\u00e9cnicas del\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.ciencia.gob.es\/\" target=\"_blank\" rel=\"noopener\">Ministerio de Ciencia e Innovaci\u00f3n<\/a>,\u00a0Don Jos\u00e9 Ignacio Doncel Moreno.<\/p>\n<p>La RES organiza anualmente estas jornadas para comunicar sus novedades y ofrecer informaci\u00f3n de inter\u00e9s sobre sus recursos y el ecosistema europeo en HPC. Estos eventos suponen, por tanto, un espacio de encuentro para investigadores, usuarios, t\u00e9cnicos de apoyo, y los propios comit\u00e9s de la RES.<\/p>\n<p>La conferencia se desarrollar\u00e1 durante 2 d\u00edas, comenzando el mi\u00e9rcoles 14, con sesiones plenarias y conferencias t\u00e9cnicas y cient\u00edficas, que ser\u00e1n desarrolladas por destacados especialistas en supercomputaci\u00f3n. El jueves 15, se ofrecer\u00e1n sesiones centradas en temas cient\u00edficos y t\u00e9cnicos relacionados con la computaci\u00f3n de alto rendimiento y finalizar\u00e1 con una entrega de premios a la contribuci\u00f3n cient\u00edfica m\u00e1s relevante.<\/p>\n<p>Las jornadas incluyen adem\u00e1s una visita guiada al casco antiguo medieval de C\u00e1ceres, as\u00ed como una cena de gala.<\/p>\n<p>Informaci\u00f3n adicional y programa del evento:<\/p>\n<ul>\n<li>Web de la\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.res.es\/es\/eventos\/16th-users-conference\" target=\"_blank\" rel=\"noopener\">16\u00aa Conferencia de Usuarios de la RES<\/a>.<\/li>\n<\/ul>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li>Unos 120 expertos del uso de la computaci\u00f3n de alto rendimiento se dar\u00e1n cita este mi\u00e9rcoles y jueves en C\u00e1ceres [<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.juntaex.es\/comunicacion\/noticia&amp;idPub=37623\" target=\"_blank\" rel=\"noopener\">Junta de Extremadura<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.noticiasextremadura.es\/unos-120-expertos-del-uso-de-la-computacion-de-alto-rendimiento-se-daran-cita-este-miercoles-y-jueves-en-caceres\/\" target=\"_blank\" rel=\"noopener\">Noticias Extremadura<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.diariodemerida.es\/unos-120-expertos-del-uso-de-la-computacion-de-alto-rendimiento-se-daran-cita-este-miercoles-y-jueves-en-caceres\/\">Diario de M\u00e9rida<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.extremadura.com\/noticias\/2022\/09\/13\/unos-120-expertos-del-uso-de-la-computacion-de-alto-rendimiento-se-daran-cita-este-miercoles-y-jueves-en-caceres\" target=\"_blank\" rel=\"noopener\">Extremadura.com<\/a>].<\/li>\n<li>Rafael Espa\u00f1a destaca la importancia de la colaboraci\u00f3n p\u00fablica y privada en el sector de la supercomputaci\u00f3n para el alcance de la sociedad [<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.juntaex.es\/comunicacion\/noticia?idPub=37638\" target=\"_blank\" rel=\"noopener\">Junta de Extremadura<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/noticiasdecaceres.com\/2022\/09\/15\/rafael-espana-destaca-la-importancia-de-la-colaboracion-publica-y-privada-en-el-sector-de-la-supercomputacion-para-el-alcance-de-la-sociedad\/\" target=\"_blank\" rel=\"noopener\">Noticias de C\u00e1ceres<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.badajozdirecto.com\/region\/2022-09-14\/extremadura\/regional\/23888\/rafael-espana-destaca-la-importancia-de-la-colaboracion-publica-y-privada-en-el-sector-de-la-supercomputacion-para-el-alcance-de-la-sociedad.html\" target=\"_blank\" rel=\"noopener\">Badajoz Directo<\/a>].<\/li>\n<li>Un centenar de expertos se re\u00fane en C\u00e1ceres para analizar la importancia de la supercomputaci\u00f3n en la gesti\u00f3n de crisis [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.europapress.es\/extremadura\/noticia-centenar-expertos-reune-caceres-analizar-importancia-supercomputacion-gestion-crisis-20220914153939.html\" target=\"_blank\" rel=\"noopener\">Europa Press<\/a>].<\/li>\n<li>El investigador de la UEx Joaqu\u00edn S\u00e1nchez Espinosa, premiado como usuario destacado de las infraestructuras de supercomputaci\u00f3n [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.radiointerior.es\/2022\/09\/14\/el-investigador-de-la-uex-joaquin-sanchez-espinosa-premiado-como-usuario-destacado-de-las-infraestructuras-de-supercomputacion\/\" target=\"_blank\" rel=\"noopener\">Radio Interior<\/a>].<\/li>\n<li>Un centenar de expertos analizan la importancia de la supercomputaci\u00f3n en gesti\u00f3n crisis [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.regiondigital.com\/noticias\/tecnologia\/367693-un-centenar-de-expertos-analizan-la-importancia-de-la-supercomputacion-en-gestion-crisis.html\" target=\"_blank\" rel=\"noopener\">Regi\u00f3n Digital<\/a>].<\/li>\n<li>La red espa\u00f1ola de supercomputaci\u00f3n celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios [<a class=\"views-ajax-processed-processed\" href=\"https:\/orbitanavalmoral.com\/red-espanola-supercomputacion-caceres-16a-conferencia-usuarios\" target=\"_blank\" rel=\"noopener\">\u00d3rbita Navalmoral<\/a>].<\/li>\n<li>El investigador de la UEx Joaqu\u00edn Espinosa recibe un premio de la Red Espa\u00f1ola de Supercomputaci\u00f3n [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.hoy.es\/extremadura\/investigador-joaquin-espinosa-20220922105544-nt.html\" target=\"_blank\" rel=\"noopener\">Diario Hoy<\/a>].<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-gal-imagenn field-type-image field-label-hidden\">\n<table>\n<tbody>\n<tr class=\"grid-field-row odd\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0228.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0228.jpg?itok=xRNSnfL7\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0249.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0249.jpg?itok=lFanL6D_\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0262.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0262.jpg?itok=hNPqagSy\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row even\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0270.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0270.jpg?itok=UD_vGAU7\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0309.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0309.jpg?itok=VlPZ_qV-\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0315.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0315.jpg?itok=H6owYaXV\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row odd\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0384.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0384.jpg?itok=R64ykgq1\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0431.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0431.jpg?itok=5USnVTyw\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0299.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0299.jpg?itok=EoOHSnOz\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row even\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0385.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0385.jpg?itok=NLElAU8h\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0441.jpg\" data-colorbox-gallery=\"gallery-node-2250-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot; La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\" La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0441.jpg?itok=w4zQWDl1\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante los d\u00edas 14 y 15 de septiembre, la Red Espa\u00f1ola de Supercomputaci\u00f3n (RES) celebrar\u00e1 en C\u00e1ceres su\u00a016\u00aa Conferencia de Usuarios, con el objetivo principal de compartir conocimientos y experiencias &#8230;<\/p>","protected":false},"author":1,"featured_media":3853,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[],"class_list":["post-3850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-participaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios. - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios. - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Durante los d\u00edas 14 y 15 de septiembre, la Red Espa\u00f1ola de Supercomputaci\u00f3n (RES) celebrar\u00e1 en C\u00e1ceres su\u00a016\u00aa Conferencia de Usuarios, con el objetivo principal de compartir conocimientos y experiencias ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-08T08:43:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T11:44:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20220909_jures2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios.\",\"datePublished\":\"2022-09-08T08:43:37+00:00\",\"dateModified\":\"2025-01-22T11:44:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220909_jures2022.jpg\",\"articleSection\":[\"Participaciones\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/\",\"name\":\"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios. - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220909_jures2022.jpg\",\"datePublished\":\"2022-09-08T08:43:37+00:00\",\"dateModified\":\"2025-01-22T11:44:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220909_jures2022.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20220909_jures2022.jpg\",\"width\":185,\"height\":117},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/participaciones\\\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios.\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios. - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/","og_locale":"en_US","og_type":"article","og_title":"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios. - Fundaci\u00f3n COMPUTAEX","og_description":"Durante los d\u00edas 14 y 15 de septiembre, la Red Espa\u00f1ola de Supercomputaci\u00f3n (RES) celebrar\u00e1 en C\u00e1ceres su\u00a016\u00aa Conferencia de Usuarios, con el objetivo principal de compartir conocimientos y experiencias ...","og_url":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2022-09-08T08:43:37+00:00","article_modified_time":"2025-01-22T11:44:48+00:00","og_image":[{"width":185,"height":117,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20220909_jures2022.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios.","datePublished":"2022-09-08T08:43:37+00:00","dateModified":"2025-01-22T11:44:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/"},"wordCount":491,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220909_jures2022.jpg","articleSection":["Participaciones"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/","url":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/","name":"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios. - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220909_jures2022.jpg","datePublished":"2022-09-08T08:43:37+00:00","dateModified":"2025-01-22T11:44:48+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220909_jures2022.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20220909_jures2022.jpg","width":185,"height":117},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/participaciones\/la-red-espanola-de-supercomputacion-res-celebra-en-caceres-su-16a-conferencia-de-usuarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"La Red Espa\u00f1ola de Supercomputaci\u00f3n (RES), celebra en C\u00e1ceres su 16\u00aa Conferencia de Usuarios."}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=3850"}],"version-history":[{"count":1,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3850\/revisions"}],"predecessor-version":[{"id":3854,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3850\/revisions\/3854"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3853"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=3850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=3850"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=3850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}