{"id":3825,"date":"2022-10-27T10:39:37","date_gmt":"2022-10-27T08:39:37","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3825"},"modified":"2025-01-22T12:36:05","modified_gmt":"2025-01-22T11:36:05","slug":"computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/","title":{"rendered":"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda"},"content":{"rendered":"<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Esta semana han comenzado las actividades de\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"http:\/\/\/en\/4ieplus.spilab.es\/workshop-2022\/\" target=\"_blank\" rel=\"noopener\">IWoG 2022<\/a><\/u>, el workshop internacional sobre gerontotecnolog\u00eda, que en su quinta edici\u00f3n ha sido organizado conjuntamente por la Escuela de Enfermer\u00eda de la\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.uevora.pt\/\" target=\"_blank\" rel=\"noopener\">Universidad de \u00c9vora<\/a><\/u>\u00a0(Portugal), la Fundaci\u00f3n\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a><\/u>\u00a0y el laboratorio\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/spilab.es\/\" target=\"_blank\" rel=\"noopener\">SPILab<\/a><\/u>\u00a0of the\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.unex.es\/\" target=\"_blank\" rel=\"noopener\">Universidad de Extremadura<\/a><\/u>.<\/p>\n<p>Adem\u00e1s de distintas sesiones previas, el workshop contar\u00e1 con dos jornadas principales que se celebrar\u00e1n, los d\u00edas 17 y 18 de noviembre, en \u00c9vora (Portugal) y en el Centro de Cirug\u00eda de M\u00ednima Invasi\u00f3n Jes\u00fas Us\u00f3n (<u><a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.ccmijesususon.com\/\" target=\"_blank\" rel=\"noopener\">CCMIJU<\/a><\/u>) de C\u00e1ceres, donde se ubica actualmente la sede social de COMPUTAEX.<\/p>\n<p>El mi\u00e9rcoles 26 de octubre se celebr\u00f3 la primera jornada de este workshop con importantes ponencias, destacando especialmente las ofrecidas por Tommi Mikkonen y\u00a0Majid Haghparast (<u><a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.jyu.fi\/en\" target=\"_blank\" rel=\"noopener\">Universidad de Jyv\u00e4skyl\u00e4<\/a><\/u>, Finlandia), Enrique Moguel (Universidad de Extremadura) y Javier S\u00e1nchez y Daniel Talav\u00e1n (t\u00e9cnicos de apoyo a la I+D+I de\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a><\/u>).<\/p>\n<p>Durante los \u00faltimos 50 a\u00f1os, el desarrollo socioecon\u00f3mico ha ido acompa\u00f1ado de grandes descensos de la natalidad y aumentos equivalentes en la esperanza de vida. Esto ha originado un r\u00e1pido envejecimiento de la poblaci\u00f3n. No obstante, aunque este aumento de la longevidad conlleva multitud de posibilidades tanto para las personas mayores como para el entorno en el que viven, el grado de sus aportaciones a la sociedad depende en gran medida de su salud. Adem\u00e1s, pese a que en la mayor\u00eda de los pa\u00edses desarrollados los ancianos viven sus \u00faltimos a\u00f1os con relativa buena salud, muchos sufren o corren el riesgo de sufrir dificultades cognitivas y f\u00edsicas.<\/p>\n<p>En consecuencia, actualmente uno de los retos sociales m\u00e1s importantes reside en conseguir que nuestros mayores puedan disfrutar de mejores condiciones de salud. De este modo, IWoG se centra en afrontar este reto desde m\u00faltiples perspectivas, mejorando la calidad de vida de los ancianos gracias, tanto a la tecnolog\u00eda, como a una correcta gesti\u00f3n del conocimiento y la provisi\u00f3n de respuestas espec\u00edficas y r\u00e1pidas a los respectivos desaf\u00edos, entre otros.<\/p>\n<p>IWoG se enmarca en el Proyecto Interreg\u00a0<u><a class=\"views-ajax-processed-processed\" href=\"http:\/\/\/en\/4ieplus.spilab.es\/\">4IE+<\/a><\/u>, Instituto Internacional de Investigaci\u00f3n e Innovaci\u00f3n del Envejecimiento, cuyo objetivo principal es analizar los aspectos biom\u00e9dicos, funcionales y psicol\u00f3gicos del envejecimiento en el contexto de las zonas rurales de las regiones de Extremadura y Alentejo en Portugal, con l\u00edneas de trabajo focalizadas en la innovaci\u00f3n para la salud de los ancianos, las problem\u00e1ticas y desaf\u00edos sociales contempor\u00e1neos del envejecimiento, las pol\u00edticas p\u00fablicas para el envejecimiento y las soluciones tecnol\u00f3gicas para una sociedad envejecida.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-gal-imagenn field-type-image field-label-hidden\">\n<table>\n<tbody>\n<tr class=\"grid-field-row odd\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/20221026_114531.jpg\" data-colorbox-gallery=\"gallery-node-2257-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/20221026_114531.jpg?itok=0yR_221y\" alt=\"\" width=\"220\" height=\"165\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/20221026_114602.jpg\" data-colorbox-gallery=\"gallery-node-2257-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/20221026_114602.jpg?itok=vrOvol60\" alt=\"\" width=\"220\" height=\"165\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img-20221026-wa0004.jpg\" data-colorbox-gallery=\"gallery-node-2257-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img-20221026-wa0004.jpg?itok=e_Ufsrt8\" alt=\"\" width=\"220\" height=\"166\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row even\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img-20221026-wa0003.jpg\" data-colorbox-gallery=\"gallery-node-2257-jKp4XATukRk\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img-20221026-wa0003.jpg?itok=khHFeI0n\" alt=\"\" width=\"220\" height=\"165\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Esta semana han comenzado las actividades de\u00a0IWoG 2022, el workshop internacional sobre gerontotecnolog\u00eda, que en su quinta edici\u00f3n ha sido organizado conjuntamente por la Escuela de Enfermer\u00eda de la\u00a0Universidad de &#8230;<\/p>","protected":false},"author":1,"featured_media":3826,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[],"class_list":["post-3825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-participaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Esta semana han comenzado las actividades de\u00a0IWoG 2022, el workshop internacional sobre gerontotecnolog\u00eda, que en su quinta edici\u00f3n ha sido organizado conjuntamente por la Escuela de Enfermer\u00eda de la\u00a0Universidad de ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T08:39:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T11:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.eu\/wp-content\/uploads\/2025\/01\/20221027_iwog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda\",\"datePublished\":\"2022-10-27T08:39:37+00:00\",\"dateModified\":\"2025-01-22T11:36:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/\"},\"wordCount\":462,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20221027_iwog.png\",\"articleSection\":[\"Participaciones\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/\",\"url\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/\",\"name\":\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20221027_iwog.png\",\"datePublished\":\"2022-10-27T08:39:37+00:00\",\"dateModified\":\"2025-01-22T11:36:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20221027_iwog.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20221027_iwog.png\",\"width\":185,\"height\":126},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/participaciones\\\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/","og_locale":"en_US","og_type":"article","og_title":"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda - Fundaci\u00f3n COMPUTAEX","og_description":"Esta semana han comenzado las actividades de\u00a0IWoG 2022, el workshop internacional sobre gerontotecnolog\u00eda, que en su quinta edici\u00f3n ha sido organizado conjuntamente por la Escuela de Enfermer\u00eda de la\u00a0Universidad de ...","og_url":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2022-10-27T08:39:37+00:00","article_modified_time":"2025-01-22T11:36:05+00:00","og_image":[{"width":185,"height":126,"url":"https:\/\/www.computaex.eu\/wp-content\/uploads\/2025\/01\/20221027_iwog.png","type":"image\/png"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#article","isPartOf":{"@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda","datePublished":"2022-10-27T08:39:37+00:00","dateModified":"2025-01-22T11:36:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/"},"wordCount":462,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20221027_iwog.png","articleSection":["Participaciones"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/","url":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/","name":"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20221027_iwog.png","datePublished":"2022-10-27T08:39:37+00:00","dateModified":"2025-01-22T11:36:05+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20221027_iwog.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20221027_iwog.png","width":185,"height":126},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.eu\/participaciones\/computaex-participa-en-la-organizacion-de-iwog-2022-el-quinto-workshop-internacional-sobre-gerontotecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"COMPUTAEX participa en la organizaci\u00f3n de IWoG 2022, el quinto workshop internacional sobre gerontotecnolog\u00eda"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=3825"}],"version-history":[{"count":1,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3825\/revisions"}],"predecessor-version":[{"id":3827,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3825\/revisions\/3827"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3826"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=3825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=3825"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=3825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}