{"id":3774,"date":"2023-01-27T10:31:03","date_gmt":"2023-01-27T09:31:03","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3774"},"modified":"2026-05-26T11:23:01","modified_gmt":"2026-05-26T09:23:01","slug":"jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/","title":{"rendered":"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023"},"content":{"rendered":"<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Entre el 20 y el 24 de marzo, se celebrar\u00e1 en toda Espa\u00f1a la\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/transparencia.gob.es\/transparencia\/transparencia_Home\/index\/Gobierno-abierto\/sensibilizacion-formacion\/SemanaAA.html\" target=\"_blank\" rel=\"noopener\">Semana de la Administraci\u00f3n Abierta<\/a>, una iniciativa cuyo objetivo principal es acercar las Administraciones P\u00fablicas a la ciudadan\u00eda y ofrecer\u00a0eventos en torno a los principios del Gobierno Abierto: transparencia, rendici\u00f3n de cuentas, participaci\u00f3n ciudadana, integridad p\u00fablica y colaboraci\u00f3n. En Espa\u00f1a, la Semana de la Administraci\u00f3n Abierta es coordinada e impulsada por la\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/funcionpublica.hacienda.gob.es\/gobernanza-publica.html\" target=\"_blank\" rel=\"noopener\">Direcci\u00f3n General de Gobernanza P\u00fablica<\/a>, con la colaboraci\u00f3n del\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/transparencia.gob.es\/transparencia\/transparencia_Home\/index\/Gobierno-abierto\/foro-GA.html\" target=\"_blank\" rel=\"noopener\">Foro de Gobierno Abierto<\/a>.<\/p>\n<p><a class=\"views-ajax-processed-processed\" href=\"\/descripcion-la-fundacion\">COMPUTAEX<\/a>\u00a0se suma a esta iniciativa organizando el evento \u00abJornada de puertas abiertas de la Fundaci\u00f3n COMPUTAEX\u00bb, gracias al cual ser\u00e1 posible visitar las instalaciones del Centro Extreme\u00f1o de Investigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n. En la jornada se celebrar\u00e1 una ponencia en la que se presentar\u00e1n el centro y los proyectos desarrollados, abarcando, estos \u00faltimos, varias \u00e1reas de la inform\u00e1tica y la investigaci\u00f3n: supercomputaci\u00f3n, computaci\u00f3n cu\u00e1ntica, biotecnolog\u00eda aplicada a la salud, inteligencia artificial, etc. Adem\u00e1s sera posible visitar el\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.cenits.es\/noticias\/20052022-kyndryl-produce-video-noticia-sobre-nuevo-centro-procesamiento-datos-cenits\">Centro de Procesamiento de Datos (CPD)<\/a>\u00a0de la Fundaci\u00f3n COMPUTAEX.<\/p>\n<p>Este evento tendr\u00e1 lugar el martes 21 de marzo, a partir de las 10:00 horas, en la sede social de COMPUTAEX en C\u00e1ceres (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.cenits.es\/contacto\">Carretera Nacional 521, Km 41,8 &#8211; 10.071 &#8211; C\u00e1ceres<\/a>).<\/p>\n<p>M\u00e1s informaci\u00f3n:<\/p>\n<ul>\n<li>Semana de la Administraci\u00f3n Abierta [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.ciencia.gob.es\/Secc-Servicios\/Transparencia-y-gobierno-abierto\/SAA2023.html\" target=\"_blank\" rel=\"noopener\">Ministerio de Ciencia e Innovaci\u00f3n<\/a>].<\/li>\n<li>Buscador de eventos de la Semana de la Administraci\u00f3n Abierta [<a class=\"views-ajax-processed-processed\" href=\"https:\/transparencia.gob.es\/transparencia\/transparencia_Home\/index\/Gobierno-abierto\/sensibilizacion-formacion\/SemanaAA\/EventosSAA2023.html\" target=\"_blank\" rel=\"noopener\">Portal de transparencia. Administraci\u00f3n General del Estado<\/a>].<\/li>\n<\/ul>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li>COMPUTAEX celebra ma\u00f1ana una jornada de puertas abiertas con motivo de la Semana de la Administraci\u00f3n Abierta [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.juntaex.es\/w\/jornada-de-puertas-abiertas-de-cenits\" target=\"_blank\" rel=\"noopener\">Junta de Extremadura<\/a>].<\/li>\n<li>COMPUTAEX celebra este martes una jornada de puertas abiertas con motivo de la Semana de la Administraci\u00f3n Abierta [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.europapress.es\/extremadura\/noticia-computaex-celebra-martes-jornada-puertas-abiertas-motivo-semana-administracion-abierta-20230320095208.html\" target=\"_blank\" rel=\"noopener\">Europa Press<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.cope.es\/actualidad\/espana\/noticias\/computaex-celebra-este-martes-una-jornada-puertas-abiertas-con-motivo-semana-administracion-abierta-20230320_2612889\" target=\"_blank\" rel=\"noopener\">Cope<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.lavanguardia.com\/local\/extremadura\/20230320\/8838044\/computaex-celebra-martes-jornada-puertas-abiertas-motivo-semana-administracion-abierta.html\" target=\"_blank\" rel=\"noopener\">La Vanguardia<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.noticiasde.es\/extremadura\/badajoz\/computaex-celebra-este-martes-una-jornada-de-puertas-abiertas-con-motivo-de-la-semana-de-la-administracion-abierta\/\" target=\"_blank\" rel=\"noopener\">NoticiasDe<\/a>] [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.extremaduradiario.com\/ex\/2023\/03\/20\/computaex-celebra-este-martes-una-jornada-de-puertas-abiertas-con-motivo-de-la-semana-de-la-administracion-abierta\/\" target=\"_blank\" rel=\"noopener\">Extremadura Diario<\/a>].<\/li>\n<li>COMPUTAEX celebra jornada de puertas abiertas por la Semana de la Administraci\u00f3n Abierta [<a class=\"views-ajax-processed-processed\" href=\"https:\/regiondigital.com\/noticias\/tecnologia\/376544-computaex-celebra-jornada-de-puertas-abiertas-por-la-semana-de-la-administracion-abierta.html\" target=\"_blank\" rel=\"noopener\">Regi\u00f3n Digital<\/a>].<\/li>\n<li>COMPUTAEX celebra una jornada de puertas abiertas con motivo de la Semana de la Administraci\u00f3n Abierta [<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.diariodemerida.es\/computaex-celebra-una-jornada-de-puertas-abiertas-con-motivo-de-la-semana-de-la-administracion-abierta\/\" target=\"_blank\" rel=\"noopener\">Diario de M\u00e9rida<\/a>].<\/li>\n<\/ul>\n<p>Esta actuaci\u00f3n tambi\u00e9n se enmarca en el proyecto \u201cExtremadura EDIH T4E: Tech for Efficiency\u201d (ID del proyecto: 101083667), dentro de la iniciativa European Digital Innovation Hubs, convocatoria: DIGITAL-2021-EDIH-01, cofinanciado por\u00a0el Fondo Europeo de Desarrollo Regional (FEDER), la Comisi\u00f3n Europea y el Real Decreto 174\/2023, de 14 de marzo, por el que se regula la concesi\u00f3n directa de subvenciones a centros de innovaci\u00f3n digital dentro del Programa de Apoyo a los Digital Innovation Hubs (PADIH), en el marco del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia.\n<\/p><\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-gal-imagenn field-type-image field-label-hidden\">\n<table>\n<tbody>\n<tr class=\"grid-field-row odd\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0911.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0911.jpg?itok=RluRPSA8\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0912_2.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0912_2.jpg?itok=R525qpXI\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0914.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0914.jpg?itok=MP_054pZ\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row even\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0916.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0916.jpg?itok=uEJcub7c\" alt=\"\" width=\"220\" height=\"120\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0924_2.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0924_2.jpg?itok=A3WNfxWz\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0930.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0930.jpg?itok=M745_fuy\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row odd\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0938.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0938.jpg?itok=aGJORVW9\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0947.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0947.jpg?itok=UAC1znib\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0952.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0952.jpg?itok=pd0aKbz0\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<tr class=\"grid-field-row even\">\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0954.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0954.jpg?itok=UhmoD1ly\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<td class=\"grid-field-col\"><a class=\"colorbox views-ajax-processed-processed\" title=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\" href=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/galeria_imagenes\/img_0956.jpg\" data-colorbox-gallery=\"gallery-node-2300-dxUc1xODUTg\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/medium\/public\/galeria_imagenes\/img_0956.jpg?itok=dhGiHVrz\" alt=\"\" width=\"220\" height=\"147\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 20 y el 24 de marzo, se celebrar\u00e1 en toda Espa\u00f1a la\u00a0Semana de la Administraci\u00f3n Abierta, una iniciativa cuyo objetivo principal es acercar las Administraciones P\u00fablicas a la &#8230;<\/p>","protected":false},"author":1,"featured_media":3775,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-3774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visitas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023 - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023 - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Entre el 20 y el 24 de marzo, se celebrar\u00e1 en toda Espa\u00f1a la\u00a0Semana de la Administraci\u00f3n Abierta, una iniciativa cuyo objetivo principal es acercar las Administraciones P\u00fablicas a la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T09:31:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T09:23:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20230127_saa2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"102\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\",\"datePublished\":\"2023-01-27T09:31:03+00:00\",\"dateModified\":\"2026-05-26T09:23:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/\"},\"wordCount\":455,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20230127_saa2023.jpg\",\"articleSection\":[\"Visitas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/\",\"name\":\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023 - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20230127_saa2023.jpg\",\"datePublished\":\"2023-01-27T09:31:03+00:00\",\"dateModified\":\"2026-05-26T09:23:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20230127_saa2023.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20230127_saa2023.jpg\",\"width\":185,\"height\":102},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/visitas\\\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023 - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/","og_locale":"en_US","og_type":"article","og_title":"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023 - Fundaci\u00f3n COMPUTAEX","og_description":"Entre el 20 y el 24 de marzo, se celebrar\u00e1 en toda Espa\u00f1a la\u00a0Semana de la Administraci\u00f3n Abierta, una iniciativa cuyo objetivo principal es acercar las Administraciones P\u00fablicas a la ...","og_url":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2023-01-27T09:31:03+00:00","article_modified_time":"2026-05-26T09:23:01+00:00","og_image":[{"width":185,"height":102,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20230127_saa2023.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023","datePublished":"2023-01-27T09:31:03+00:00","dateModified":"2026-05-26T09:23:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/"},"wordCount":455,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20230127_saa2023.jpg","articleSection":["Visitas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/","url":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/","name":"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023 - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20230127_saa2023.jpg","datePublished":"2023-01-27T09:31:03+00:00","dateModified":"2026-05-26T09:23:01+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20230127_saa2023.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20230127_saa2023.jpg","width":185,"height":102},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/visitas\/jornada-de-puertas-abiertas-en-computaex-con-motivo-de-la-semana-de-la-administracion-abierta-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Jornada de puertas abiertas en COMPUTAEX con motivo de la Semana de la Administraci\u00f3n Abierta 2023"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=3774"}],"version-history":[{"count":2,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3774\/revisions"}],"predecessor-version":[{"id":11881,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3774\/revisions\/11881"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3775"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=3774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=3774"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=3774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}