{"id":3589,"date":"2024-06-28T09:51:48","date_gmt":"2024-06-28T07:51:48","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3589"},"modified":"2026-04-06T14:23:18","modified_gmt":"2026-04-06T12:23:18","slug":"daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/","title":{"rendered":"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3589\" class=\"elementor elementor-3589\">\n\t\t\t\t<div class=\"elementor-element elementor-element-214a0b95 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"214a0b95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4602349b elementor-widget elementor-widget-text-editor\" data-id=\"4602349b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\"><div class=\"field-items\"><div class=\"field-item even\"><p>El Investigador de la Fundaci\u00f3n\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/\">COMPUTAEX<\/a>\u00a0D. Daniel Flores-Martin, junto a los investigadores de la Universidad de Extremadura (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.unex.es\/\">UEX<\/a>), D. Javier Berrocal y D. Francisco D\u00edaz-Barrancas, han sido galardonados con el\u00a0<em>Premio al mejor art\u00edculo corto<\/em>\u00a0de las Jornadas de Ciencia e Ingenier\u00eda de Servicios (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/sistedes2024.spilab.es\/jcis\/\">JCIS<\/a>), en\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/sistedes2024.spilab.es\/\">SISTEDES 2024<\/a>, la Conferencia de la Sociedad de Ingenier\u00eda de Software y Tecnolog\u00edas de Desarrollo de Software, por su trabajo titulado \u00ab<a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/hdl.handle.net\/11705\/JCIS\/2024\/10\/\"><em>Aprendizaje Federado en Dispositivos de Realidad Virtual Aut\u00f3nomos<\/em><\/a>\u00ab. Este reconocimiento destaca por la importancia y relevancia del trabajo, que explora las posibilidades de integrar el Aprendizaje Federado con la Realidad Virtual, marcando un avance significativo en la convergencia de estas tecnolog\u00edas. Las jornadas se han celebrado en el marco de VII Congreso Espa\u00f1ol de Inform\u00e1tica (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.congresocedi.es\/\">CEDI 2024<\/a>), celebrado en A Coru\u00f1a, del 17 al 21 de junio.<\/p><p>El Aprendizaje Federado ha destacado en la \u00faltima d\u00e9cada por su capacidad para entrenar modelos de aprendizaje autom\u00e1tico utilizando datos distribuidos, todo mientras se preserva la privacidad de los datos individuales. Esta caracter\u00edstica es particularmente crucial en una era donde la privacidad y la seguridad de los datos son de m\u00e1xima prioridad. Por otro lado, la Realidad Virtual ha evolucionado para permitir a los usuarios experimentar entornos inmersivos altamente personalizados. La combinaci\u00f3n de estas dos tecnolog\u00edas promete no solo mejorar la privacidad, sino tambi\u00e9n crear aplicaciones m\u00e1s sofisticadas, personalizadas, y adaptables.<\/p><p>En este trabajo, los autores han explorado c\u00f3mo el Aprendizaje Federado puede ser utilizado para entrenar modelos de aprendizaje autom\u00e1tico directamente en dispositivos de Realidad Virtual aut\u00f3nomos, eliminando la necesidad de conexiones constantes a la nube o a equipos inform\u00e1ticos externos. Este enfoque descentralizado permite mantener los datos localmente en los dispositivos de los usuarios, asegurando as\u00ed una mayor privacidad y facilitando la colaboraci\u00f3n en tiempo real en entornos virtuales. El potencial de los dispositivos de Realidad Virtual para manejar tareas computacionales complejas de manera eficiente es cada vez mayor. Por ello, en este trabajo se ha evaluado el rendimiento de los modelos de aprendizaje autom\u00e1tico en t\u00e9rminos de tiempo de ejecuci\u00f3n y consumo de bater\u00eda para diferentes dispositivos de Realidad Virtual (<em>Meta Quest<\/em>), destacando los avances tecnol\u00f3gicos que permiten a este tipo de dispositivos expandir sus capacidades m\u00e1s all\u00e1 de los l\u00edmites hasta ahora conocidos.<\/p><p>El trabajo tambi\u00e9n ha identificado desaf\u00edos importantes, particularmente en relaci\u00f3n con la gesti\u00f3n de la complejidad de los modelos neuronales. Los resultados sugieren que la integraci\u00f3n de Aprendizaje Federado y Realidad Virtual podr\u00eda revolucionar la forma en que se desarrollan y mejoran los modelos de aprendizaje autom\u00e1tico sin afectar dr\u00e1sticamente al consumo de recursos. La interactividad y la inmersi\u00f3n proporcionadas por la Realidad Virtual pueden enriquecer tanto los modelos locales como globales.<br \/>El reconocimiento en las Jornadas JCIS subraya el impacto de los autores en el campo de la tecnolog\u00eda emergente. Este avance no solo tiene implicaciones para el desarrollo de aplicaciones de Realidad Virtual m\u00e1s sofisticadas y personalizadas, sino que tambi\u00e9n promete expandir los l\u00edmites de la colaboraci\u00f3n y la privacidad en el \u00e1mbito del aprendizaje autom\u00e1tico distribuido.<br \/>Art\u00edculo:<br \/>Flores-Martin, D., D\u00edaz-Barrancas, F., Berrocal, J.: Aprendizaje Federado en Dispositivos de Realidad Virtual Aut\u00f3nomos. In: Resinas, M. (ed.) Actas de las XIX Jornadas de Ciencia e Ingenier\u00eda de Servicios (JCIS 2024). Sistedes (2024).<br \/><a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/hdl.handle.net\/11705\/JCIS\/2024\/10\/\">https:\/hdl.handle.net\/11705\/JCIS\/2024\/10<\/a><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7557fc elementor-widget elementor-widget-image-gallery\" data-id=\"b7557fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-3589 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b7557fc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NTMsInVybCI6Imh0dHA6XC9cL2NvbXB1dGFleC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDRcLzIwMjQwNjI2X1ByZW1pby1EYW5pZWwtU2lzdGVkZXMxLmpwZyIsInNsaWRlc2hvdyI6ImI3NTU3ZmMifQ%3D%3D\" href='http:\/\/computaex.es\/wp-content\/uploads\/2026\/04\/20240626_Premio-Daniel-Sistedes1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/computaex.es\/wp-content\/uploads\/2026\/04\/20240626_Premio-Daniel-Sistedes1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b7557fc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NTQsInVybCI6Imh0dHA6XC9cL2NvbXB1dGFleC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDRcLzIwMjQwNjI2X1ByZW1pby1EYW5pZWwtU2lzdGVkZXMyLmpwZyIsInNsaWRlc2hvdyI6ImI3NTU3ZmMifQ%3D%3D\" href='http:\/\/computaex.es\/wp-content\/uploads\/2026\/04\/20240626_Premio-Daniel-Sistedes2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/computaex.es\/wp-content\/uploads\/2026\/04\/20240626_Premio-Daniel-Sistedes2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b7557fc\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE0NTUsInVybCI6Imh0dHA6XC9cL2NvbXB1dGFleC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDRcLzIwMjQwNjI2X1ByZW1pby1EYW5pZWwtU2lzdGVkZXMzLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJiNzU1N2ZjIn0%3D\" href='http:\/\/computaex.es\/wp-content\/uploads\/2026\/04\/20240626_Premio-Daniel-Sistedes3-scaled.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/computaex.es\/wp-content\/uploads\/2026\/04\/20240626_Premio-Daniel-Sistedes3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Investigador de la Fundaci\u00f3n\u00a0COMPUTAEX\u00a0D. Daniel Flores-Martin, junto a los investigadores de la Universidad de Extremadura (UEX), D. Javier Berrocal y D. Francisco D\u00edaz-Barrancas, han sido galardonados con el\u00a0Premio al &#8230;<\/p>","protected":false},"author":1,"featured_media":3590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[],"class_list":["post-3589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"El Investigador de la Fundaci\u00f3n\u00a0COMPUTAEX\u00a0D. Daniel Flores-Martin, junto a los investigadores de la Universidad de Extremadura (UEX), D. Javier Berrocal y D. Francisco D\u00edaz-Barrancas, han sido galardonados con el\u00a0Premio al ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T07:51:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T12:23:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/computaex.es\/wp-content\/uploads\/2025\/01\/20240626_premio_daniel_sistedes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"123\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica\",\"datePublished\":\"2024-06-28T07:51:48+00:00\",\"dateModified\":\"2026-04-06T12:23:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/\"},\"wordCount\":602,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20240626_premio_daniel_sistedes.jpg\",\"articleSection\":[\"Premios\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/\",\"url\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/\",\"name\":\"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20240626_premio_daniel_sistedes.jpg\",\"datePublished\":\"2024-06-28T07:51:48+00:00\",\"dateModified\":\"2026-04-06T12:23:18+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20240626_premio_daniel_sistedes.jpg\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20240626_premio_daniel_sistedes.jpg\",\"width\":185,\"height\":123},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/computaex.es\\\/premios\\\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/","og_locale":"en_US","og_type":"article","og_title":"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica - Fundaci\u00f3n COMPUTAEX","og_description":"El Investigador de la Fundaci\u00f3n\u00a0COMPUTAEX\u00a0D. Daniel Flores-Martin, junto a los investigadores de la Universidad de Extremadura (UEX), D. Javier Berrocal y D. Francisco D\u00edaz-Barrancas, han sido galardonados con el\u00a0Premio al ...","og_url":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2024-06-28T07:51:48+00:00","article_modified_time":"2026-04-06T12:23:18+00:00","og_image":[{"width":185,"height":123,"url":"http:\/\/computaex.es\/wp-content\/uploads\/2025\/01\/20240626_premio_daniel_sistedes.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#article","isPartOf":{"@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica","datePublished":"2024-06-28T07:51:48+00:00","dateModified":"2026-04-06T12:23:18+00:00","mainEntityOfPage":{"@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/"},"wordCount":602,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20240626_premio_daniel_sistedes.jpg","articleSection":["Premios"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/","url":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/","name":"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#primaryimage"},"image":{"@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20240626_premio_daniel_sistedes.jpg","datePublished":"2024-06-28T07:51:48+00:00","dateModified":"2026-04-06T12:23:18+00:00","breadcrumb":{"@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20240626_premio_daniel_sistedes.jpg","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20240626_premio_daniel_sistedes.jpg","width":185,"height":123},{"@type":"BreadcrumbList","@id":"http:\/\/computaex.es\/premios\/daniel-flores-investigador-de-la-fundacion-computaex-galardonado-en-el-vii-congreso-espanol-de-informatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Daniel Flores, Investigador de la Fundaci\u00f3n COMPUTAEX, galardonado en el VII Congreso Espa\u00f1ol de Inform\u00e1tica"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=3589"}],"version-history":[{"count":4,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3589\/revisions"}],"predecessor-version":[{"id":11463,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3589\/revisions\/11463"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3590"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=3589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=3589"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=3589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}