{"id":3178,"date":"2024-03-18T08:12:43","date_gmt":"2024-03-18T07:12:43","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3178"},"modified":"2025-01-22T10:34:57","modified_gmt":"2025-01-22T09:34:57","slug":"convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex","status":"publish","type":"post","link":"http:\/\/52.47.32.16\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/","title":{"rendered":"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3178\" class=\"elementor elementor-3178\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e4440 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d6e4440\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec5f04f elementor-widget elementor-widget-text-editor\" data-id=\"ec5f04f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Fundaci\u00f3n COMPUTAEX oferta cuatro puestos de trabajo que se desarrollar\u00e1n dentro del Plan complementario de Biotecnolog\u00eda aplicada a la salud.\u00a0Todos los detalles de la convocatoria pueden ser consultados en las\u00a0bases:<\/p><p>\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 &#8211;\u00a0<a href=\"http:\/\/10.128.3.28\/empleo\/\">T\u00e9cnico\/a PPCC (Ref. 2024-1).<\/a><\/p><p>El objetivo general del Plan complementario de Biotecnolog\u00eda aplicada a salud es el desarrollo de herramientas para diagn\u00f3stico, pron\u00f3stico y terapias avanzadas, o dirigidas, en medicina personalizada. Este plan pretende superar las limitaciones de las primeras aproximaciones para medicina personalizada. Para tal fin, se han definido los siguientes objetivos:<\/p><ul><li>Incrementar el conocimiento de los efectos de todas las variantes posibles en los genomas, transcriptomas, proteomas humanos y de pat\u00f3genos.<\/li><li>Profundizar en el estudio de la expresi\u00f3n g\u00e9nica a nivel celular individual, esencial para desarrollar nuevos sistemas avanzados de diagn\u00f3stico y pron\u00f3stico e identificar nuevas dianas terap\u00e9uticas.<\/li><li>Desarrollar nuevas terapias personalizadas y dirigidas como los nanof\u00e1rmacos, as\u00ed como t\u00e9cnicas avanzadas de cirug\u00eda mediante el desarrollo de modelos de enfermedad precl\u00ednicos que aprovechen el potencial de los sistemas biomim\u00e9ticos y los biomodelos.<\/li><\/ul><p>COMPUTAEX participa en la L\u00ednea de Actuaci\u00f3n 2,\u00a0 implementaci\u00f3n y an\u00e1lisis de bases de datos en medicina de precisi\u00f3n, en la que contribuye con la integraci\u00f3n y an\u00e1lisis de datos, mediante la implementaci\u00f3n de modelos de datos para medicina de precisi\u00f3n y el desarrollo de herramientas de an\u00e1lisis y visualizaci\u00f3n de datos.<\/p><p>La medicina de precisi\u00f3n est\u00e1 supeditada a la obtenci\u00f3n y estudio de amplias bases de datos experimentales que permitan la caracterizaci\u00f3n fisiopatol\u00f3gica de la poblaci\u00f3n. Uno de los objetivos de esta l\u00ednea es la construcci\u00f3n de bases de datos a partir de muestras de biofluidos y tejidos de cohortes no orientadas y\/o de cohortes orientadas a determinadas patolog\u00edas: COVID-19, enfermedades metab\u00f3licas, c\u00e1ncer (p.e. glioblastoma y c\u00e1ncer de pr\u00f3stata), enfermedades del sistema nervioso central, patolog\u00edas cardiacas y reproductivas. Esto permitir\u00e1, por un lado, la caracterizaci\u00f3n de la poblaci\u00f3n general y por otro, complementar estudios enfocados a enfermedades concretas. Por otro lado, se realizar\u00e1n an\u00e1lisis de modificaciones gen\u00f3micas, epigen\u00e9ticas, metabol\u00f3micas, prote\u00f3micas y transcript\u00f3micas de las muestras de pacientes m\u00e1s all\u00e1 de la identificaci\u00f3n inicial de mutaciones y polimorfismos, como, por ejemplo, an\u00e1lisis masivos de c\u00e9lula individual (single cell). Para poder analizar todos estos datos se desarrollar\u00e1n innovadoras soluciones de integraci\u00f3n, minado y tratamiento de datos.<\/p><p>El desarrollo de esta l\u00ednea permitir\u00e1 la integraci\u00f3n y contextualizaci\u00f3n de los datos gracias a los avances tecnol\u00f3gicos aportado por las plataformas integrales de an\u00e1lisis -\u00f3micas (metabol\u00f3mica, prote\u00f3mica, flux\u00f3mica, microbi\u00f3tica y gen\u00f3mica), de la potencia de c\u00e1lculo y capacidad para desentra\u00f1ar la complejidad de la inteligencia artificial, y de la informaci\u00f3n mecan\u00edstica basada en la biolog\u00eda estructural obtenida por BREM, para as\u00ed favorecer la identificaci\u00f3n de huellas biol\u00f3gicas validadas (biomarcadores) de manera personalizada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-621050f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"621050f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45dfb9d elementor-widget elementor-widget-text-editor\" data-id=\"45dfb9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Sources of funding:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ba289e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7ba289e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c95370b elementor-widget elementor-widget-image-gallery\" data-id=\"c95370b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-3178 gallery-columns-1 gallery-size-1536x1536'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c95370b\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzIyMywidXJsIjoiaHR0cHM6XC9cL2NvbXB1dGFleC5ldVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL2xvZ29zLWV1Z29ibWlucmVzaWxlbmNpYS0xLmpwZyIsInNsaWRlc2hvdyI6ImM5NTM3MGIifQ%3D%3D\" href='https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-eugobminresilencia-1.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"957\" height=\"71\" src=\"https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-eugobminresilencia-1.jpg\" class=\"attachment-1536x1536 size-1536x1536\" alt=\"\" srcset=\"https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-eugobminresilencia-1.jpg 957w, https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-eugobminresilencia-1-300x22.jpg 300w, https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-eugobminresilencia-1-768x57.jpg 768w\" sizes=\"(max-width: 957px) 100vw, 957px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-562db04 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"562db04\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8649158 elementor-widget elementor-widget-text-editor\" data-id=\"8649158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este Plan ha sido cofinanciado por el Ministerio de Ciencia e Innovaci\u00f3n con fondos de la Uni\u00f3n Europea NextGenerationEU (PRTR-C17.I1) y las siguientes Comunidades Aut\u00f3nomas:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-363d2ae e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"363d2ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8183f2 elementor-widget elementor-widget-image\" data-id=\"f8183f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"159\" src=\"https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-pcb-regiones-1-1024x203.png\" class=\"attachment-large size-large wp-image-3224\" alt=\"\" srcset=\"https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-pcb-regiones-1-1024x203.png 1024w, https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-pcb-regiones-1-300x59.png 300w, https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-pcb-regiones-1-768x152.png 768w, https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-pcb-regiones-1-1536x304.png 1536w, https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/logos-pcb-regiones-1.png 1738w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n COMPUTAEX oferta cuatro puestos de trabajo que se desarrollar\u00e1n dentro del Plan complementario de Biotecnolog\u00eda aplicada a la salud.\u00a0Todos los detalles de la convocatoria pueden ser consultados en &#8230;<\/p>","protected":false},"author":1,"featured_media":3252,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-3178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ofertas-de-empleo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"La Fundaci\u00f3n COMPUTAEX oferta cuatro puestos de trabajo que se desarrollar\u00e1n dentro del Plan complementario de Biotecnolog\u00eda aplicada a la salud.\u00a0Todos los detalles de la convocatoria pueden ser consultados en ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-18T07:12:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T09:34:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"628\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\\\/a PPCC en la Fundaci\u00f3n COMPUTAEX\",\"datePublished\":\"2024-03-18T07:12:43+00:00\",\"dateModified\":\"2025-01-22T09:34:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/\"},\"wordCount\":573,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview.png\",\"articleSection\":[\"Ofertas de empleo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/\",\"url\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/\",\"name\":\"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\\\/a PPCC en la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview.png\",\"datePublished\":\"2024-03-18T07:12:43+00:00\",\"dateModified\":\"2025-01-22T09:34:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#primaryimage\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview.png\",\"width\":628,\"height\":397},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/ofertas-de-empleo\\\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\\\/a PPCC en la Fundaci\u00f3n COMPUTAEX\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"http:\\\/\\\/52.47.32.16\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/","og_locale":"en_US","og_type":"article","og_title":"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX","og_description":"La Fundaci\u00f3n COMPUTAEX oferta cuatro puestos de trabajo que se desarrollar\u00e1n dentro del Plan complementario de Biotecnolog\u00eda aplicada a la salud.\u00a0Todos los detalles de la convocatoria pueden ser consultados en ...","og_url":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2024-03-18T07:12:43+00:00","article_modified_time":"2025-01-22T09:34:57+00:00","og_image":[{"width":628,"height":397,"url":"https:\/\/computaex.eu\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview.png","type":"image\/png"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#article","isPartOf":{"@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX","datePublished":"2024-03-18T07:12:43+00:00","dateModified":"2025-01-22T09:34:57+00:00","mainEntityOfPage":{"@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/"},"wordCount":573,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview.png","articleSection":["Ofertas de empleo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/","url":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/","name":"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#primaryimage"},"image":{"@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#primaryimage"},"thumbnailUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview.png","datePublished":"2024-03-18T07:12:43+00:00","dateModified":"2025-01-22T09:34:57+00:00","breadcrumb":{"@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#primaryimage","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview.png","width":628,"height":397},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.eu\/en\/ofertas-de-empleo\/convocada-oferta-de-empleo-de-cuatro-puestos-de-tecnico-a-ppcc-en-la-fundacion-computaex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Convocada oferta de empleo de cuatro puestos de T\u00e9cnico\/a PPCC en la Fundaci\u00f3n COMPUTAEX"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"http:\/\/52.47.32.16\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=3178"}],"version-history":[{"count":5,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3178\/revisions"}],"predecessor-version":[{"id":3258,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/posts\/3178\/revisions\/3258"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media\/3252"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=3178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=3178"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=3178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}