{"id":4854,"date":"2025-01-17T10:06:20","date_gmt":"2025-01-17T09:06:20","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=4854"},"modified":"2025-08-28T10:14:47","modified_gmt":"2025-08-28T08:14:47","slug":"ciencias-informaticas-y-de-comunicaciones","status":"publish","type":"page","link":"http:\/\/52.47.32.16\/en\/ciencias-informaticas-y-de-comunicaciones\/","title":{"rendered":"Ciencias Inform\u00e1ticas y de Comunicaciones"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4854\" class=\"elementor elementor-4854\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d351b29 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d351b29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c59e44 elementor-widget elementor-widget-text-editor\" data-id=\"6c59e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/deteccion-de-ataques-mediante-tecnicas-side-channel-y-de-inteligencia-artificial-en-entornos-iot-dasia-iot\/\">Detecci\u00f3n de Ataques mediante t\u00e9cnicas Side-channel y de Inteligencia Artificial en entornos IoT (DASIA-IoT).<\/a><\/span><\/h2><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Felipe Alejandro Lemus y\u00a0Alejandro Dom\u00ednguez.<\/p><\/div><\/div><\/div><div class=\"form-item form-type-item\"><label>Idioma<\/label>Sin definir<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La eclosi\u00f3n de la tecnolog\u00eda Internet de las cosas ha derivado en el desarrollo de m\u00faltiples aplicaciones en muchos y diversos campos. Las posibilidades brindadas por esta tecnolog\u00eda, en combinaci\u00f3n con las tecnolog\u00edas de comunicaci\u00f3n inal\u00e1mbricas modernas, permiten obtener datos de diversos dispositivos en tiempo real y habilitan una toma de decisiones mejor informada. En el \u00e1mbito de la salud, estos dispositivos proporcionan una informaci\u00f3n valiosa que se traduce en un mejor tratamiento de pacientes y en una utilizaci\u00f3n m\u00e1s eficiente de los recursos sanitarios. A su vez, estos datos son especialmente sensibles y, si bien la tecnolog\u00eda IoT ha experimentado un gran avance, la securizaci\u00f3n de la misma no lo ha hecho en consonancia. El objetivo del presente proyecto es el fortalecimiento de los sistemas IoT especialmente sensibles mediante el an\u00e1lisis y estudio de t\u00e9cnicas de securizaci\u00f3n ya existentes y la aplicaci\u00f3n de t\u00e9cnicas denominadas side-channel combinadas con t\u00e9cnicas de machine learning para implementar un sistema de detecci\u00f3n de intrusiones espec\u00edficas para dispositivos IoT.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/deteccion-de-ataques-mediante-tecnicas-side-channel-y-de-inteligencia-artificial-en-entornos-iot-dasia-iot\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c6b89c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"4c6b89c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35256b9 elementor-widget elementor-widget-text-editor\" data-id=\"35256b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><hr \/><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-miliac\/\">MILIAC<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>C\u00e9nitS-COMPUTAEX team.<\/p><\/div><\/div><\/div><div class=\"form-item form-type-item\"><label>Idioma<\/label>Sin definir<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La inteligencia artificial es la capacidad de un sistema inform\u00e1tico de imitar funciones cognitivas humanas como el aprendizaje o la soluci\u00f3n de problemas, utilizando como base las matem\u00e1ticas y la l\u00f3gica. Los sistemas basados en IA hacen predicciones o realizan acciones bas\u00e1ndose en los patrones identificados en los datos disponibles y poseen la capacidad de aprender de sus errores para ser m\u00e1s precisos. Estas capacidades han transformado a la inteligencia artificial en una de las tecnolog\u00edas m\u00e1s importantes de la actualidad capaz de permear en pr\u00e1cticamente todos los \u00e1mbitos de la sociedad, destacando su papel en el desarrollo empresarial donde se ha consolidado como una fuente de innovaci\u00f3n y tracci\u00f3n.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-miliac\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-714d1bd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"714d1bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9324ca1 elementor-widget elementor-widget-text-editor\" data-id=\"9324ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-qcs-lusitania-quantum-circuit-simulator-as-a-service-on-lusitania-iii\/\">QCS-LUSITANIA (Quantum Circuit Simulator as a Service on LUSITANIA III)<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Pablo Fern\u00e1ndez,\u00a0Juan Antonio P\u00e9rez, Javier Corral y Juan Manuel Murillo. Fundaci\u00f3n COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"form-item form-type-item\"><label>Idioma<\/label>Sin definir<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Resumen del proyecto: La computaci\u00f3n cu\u00e1ntica est\u00e1 atrayendo el inter\u00e9s de una gran parte de la comunidad cient\u00edfica y de la industria por las m\u00faltiples aplicaciones que tiene para atacar aquellos problemas a los que la computaci\u00f3n cl\u00e1sica no proporciona una soluci\u00f3n satisfactoria. En los \u00faltimos a\u00f1os se han producido grandes avances tanto en las \u00e1reas del hardware, creando ordenadores cu\u00e1nticos m\u00e1s potentes cada vez incluso en la escala comercial, como del software proponi\u00e9ndose algoritmos cu\u00e1nticos para resolver problemas a los que los algoritmos cl\u00e1sicos no ofrecen una soluci\u00f3n satisfactoria. De esta forma la computaci\u00f3n cu\u00e1ntica se est\u00e1 convirtiendo en un \u00e1rea clave de desarrollo en el que las grandes potencias (EEUU, China y en Europa, Alemania) est\u00e1n invirtiendo muchos esfuerzos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-qcs-lusitania-quantum-circuit-simulator-as-a-service-on-lusitania-iii\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6652d3a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6652d3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f78e7a6 elementor-widget elementor-widget-text-editor\" data-id=\"f78e7a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-efihpc-entorno-software-para-el-desarrollo-de-codigos-de-programacion-eficientes-en-centros-de-supercomputacion\/\">EfiHPC: Entorno Software para el Desarrollo de C\u00f3digos de programaci\u00f3n eficientes en Centros de Supercomputaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Javier Corral Garc\u00eda, Felipe Lemus Prieto y Juan Manuel Murillo Rodr\u00edguez. Fundaci\u00f3n\u00a0<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><li>Jos\u00e9 Carlos Sancho N\u00fa\u00f1ez. Universidad de Extremadura (<a href=\"https:\/\/www.unex.es\/\" target=\"_blank\" rel=\"noopener\">UEX<\/a>).<\/li><\/ul><\/div><\/div><\/div><div class=\"form-item form-type-item\"><label>Idioma<\/label>Sin definir<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Expertos de m\u00faltiples ramas del conocimiento se enfrentan diariamente a multitud de desaf\u00edos en proyectos cient\u00edficos, t\u00e9cnicos o industriales que requieren el uso de la computaci\u00f3n de alto rendimiento (HPC, High-Performance Computing) para satisfacer adecuadamente sus necesidades. Este tipo de proyectos, ampliamente multidisciplinares y heterog\u00e9neos, demandan una obtenci\u00f3n de resultados con tiempos de ejecuci\u00f3n realmente cr\u00edticos. De este modo, con objeto de alcanzar resultados confiables y emplear eficientemente los recursos de c\u00f3mputo disponibles, muchos de estos profesionales necesitan una importante ayuda adicional que les permita optimizar adecuadamente sus c\u00f3digos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-efihpc-entorno-software-para-el-desarrollo-de-codigos-de-programacion-eficientes-en-centros-de-supercomputacion\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff65ea3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ff65ea3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c146a01 elementor-widget elementor-widget-text-editor\" data-id=\"c146a01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-anemoi2-avances-en-el-modelo-predictivo-de-productividad-y-operatividad-de-parques-eolicos\/\">Anemoi2: avances en el modelo predictivo de productividad y operatividad de parques e\u00f3licos<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Andr\u00e9s Ventura, Javier Corral y Juan Manuel Murrillo. Fundaci\u00f3n COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"form-item form-type-item\"><label>Idioma<\/label>Sin definir<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La excesiva dependencia de nuestra sociedad de los combustibles f\u00f3siles y de las fuentes de energ\u00eda no renovables est\u00e1 en tela de juicio. Algunos estudios se\u00f1alan este uso extensivo de combustibles f\u00f3siles como la principal fuente de emisiones de CO2 y una causa importante del cambio clim\u00e1tico antropog\u00e9nico. En los \u00faltimos 20 a\u00f1os se ha producido un crecimiento lento pero constante del uso de fuentes de energ\u00eda renovables o ecol\u00f3gicas en el contexto de un esfuerzo de gobiernos y empresas por la \u00abdescarbonizaci\u00f3n\u00bb de la econom\u00eda.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-anemoi2-avances-en-el-modelo-predictivo-de-productividad-y-operatividad-de-parques-eolicos\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1feff5 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a1feff5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cd545a elementor-widget elementor-widget-text-editor\" data-id=\"3cd545a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-exqnet-extremadura-quantum-network-infraestructura-de-comunicaciones-cuanticas-fiable-y-segura-para-extremadura\/\">ExQNet (Extremadura Quantum Network): Infraestructura de comunicaciones cu\u00e1nticas fiable y segura para Extremadura<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Daniel Talav\u00e1n y Juan Manuel Murillo. Fundaci\u00f3n COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto ExQNet (Extremadura Quantum Network) se ha centrado en el dise\u00f1o, planificaci\u00f3n, especificaci\u00f3n y evaluaci\u00f3n de una red de comunicaciones cu\u00e1ntica para la interconexi\u00f3n de infraestructuras cr\u00edticas para la futura prestaci\u00f3n de conexiones fiables y seguras usando software cu\u00e1ntico. Buscando la sostenibilidad econ\u00f3mica, se ha analizado y evaluado la creaci\u00f3n de la base de la ExQNet sobre la infraestructura de la actual RCT (Red Cient\u00edfico Tecnol\u00f3gica), con las fibras \u00f3pticas necesarias que permitan dotar la infraestructura m\u00ednima para la migraci\u00f3n de las actuales redes de conmutaci\u00f3n de paquetes (bits) a las comunicaciones cu\u00e1nticas (qubits) que sienten la base de la futura Internet cu\u00e1ntica. Se persigue as\u00ed la posibilidad de interconectar CPDs, supercomputadores, hospitales, centros tecnol\u00f3gicos, institutos de investigaci\u00f3n, universidades, empresas e infraestructuras cr\u00edticas para la seguridad regional y nacional, que \u00e9stas puedan ser aprovechadas para resolver las limitaciones actuales y sus necesidades futuras.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-exqnet-extremadura-quantum-network-infraestructura-de-comunicaciones-cuanticas-fiable-y-segura-para-extremadura\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-787cb5d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"787cb5d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0a953d elementor-widget elementor-widget-text-editor\" data-id=\"d0a953d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-quantum-spain-creacion-de-un-ecosistema-de-computacion-cuantica-para-la-inteligencia-artificial\/\">Quantum Spain: creaci\u00f3n de un ecosistema de computaci\u00f3n cu\u00e1ntica para la Inteligencia Artificial<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Consorcio Barcelona Supercomputing CenterCentro Nacional de Supercomputaci\u00f3n (BSCCNS).<\/li><li>Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Galicia (CESGA).<\/li><li>Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Castilla y Le\u00f3n (SCAYLE).<\/li><li>Universidad de Zaragoza.<\/li><li>Universidad de Valencia.<\/li><li>Fundaci\u00f3n Computaci\u00f3n y Tecnolog\u00edas Avanzadas de Extremadura (COMPUTAEX).<\/li><li>Consorcio Instituto de Astrof\u00edsica de Canarias (IAC).<\/li><li>Consorcio de Servicios Universitarios de Catalu\u00f1a (CSUC).<\/li><li>CIEMAT (Centro de Investigaciones Energ\u00e9ticas, Medioambientales y Tecnol\u00f3gicas).<\/li><li>Navarra de Servicios y Tecnolog\u00edas (NASERTIC).<\/li><li>Universidad Aut\u00f3noma de Madrid.<\/li><li>Universidad de M\u00e1laga.<\/li><li>Universidad de Cantabria.\u00a0<\/li><\/ul><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto Quantum Spain prev\u00e9 la construcci\u00f3n e instalaci\u00f3n del primer ordenador cu\u00e1ntico basado en tecnolog\u00eda europea. El objetivo estrat\u00e9gico del proyecto Quantum Spain, es crear un ecosistema s\u00f3lido de computaci\u00f3n cu\u00e1ntica en Espa\u00f1a.<\/p><p>Quantum Espa\u00f1a involucra a 25 universidades y centros de infraestructuras y supercomputaci\u00f3n, de 14 comunidades aut\u00f3nomas.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-quantum-spain-creacion-de-un-ecosistema-de-computacion-cuantica-para-la-inteligencia-artificial\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17597dc e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"17597dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a363de elementor-widget elementor-widget-text-editor\" data-id=\"5a363de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mipyme-digital\/\">MiPYME Digital<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>C\u00e9nitS-COMPUTAEX team.<\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n han crecido exponencialmente en los \u00faltimos a\u00f1os, aumentando significativamente su presencia en la industria y en las organizaciones que desean avanzar y aumentar la productividad y la eficiencia de sus negocios. La implementaci\u00f3n y el uso de estas tecnolog\u00edas resultan de vital importancia para a\u00f1adir valor a los procesos de las empresas, los cu\u00e1les deben seguir adapt\u00e1ndose al escenario digital e hiperconectado de la sociedad actual.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mipyme-digital\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e62417d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e62417d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcf4cf elementor-widget elementor-widget-text-editor\" data-id=\"6dcf4cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mejora-implementacion-e-implantacion-de-plataforma-de-comunicacion-digital-y-e-learning-en-moodle\/\">Mejora, implementaci\u00f3n e implantacio\u0144 de plataforma de comunicaci\u00f3n digital y e-learning en Moodle<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Fundaci\u00f3n Magdalena Moriche (<a href=\"https:\/\/inteligencialimite.org\/inteligencialimite\/descripcion-la-fundacion-magdalena-moriche\/\" target=\"_blank\" rel=\"noopener\">FMM<\/a>).<\/li><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El programa de Innovaci\u00f3n y Talento (PIT), promovido por la Consejer\u00eda de Educaci\u00f3n y Empleo de la Junta de Extremadura, y destinado a la contrataci\u00f3n de desempleados menores de 30 a\u00f1os, combina la formaci\u00f3n de tecn\u00f3logos con las pr\u00e1cticas profesionales en empresas privadas. As\u00ed, su objetivo es facilitar la inserci\u00f3n laboral de j\u00f3venes y potenciar las capacidades del talento de la regi\u00f3n extreme\u00f1a en las siguientes \u00e1reas estrat\u00e9gicas: agroalimentaria, tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC), turismo, salud, energ\u00edas limpias, investigaci\u00f3n b\u00e1sica, humanidades y ciencias sociales, econom\u00eda verde, econom\u00eda circular y bioeconom\u00eda.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mejora-implementacion-e-implantacion-de-plataforma-de-comunicacion-digital-y-e-learning-en-moodle\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-627e81f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"627e81f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69ce42c elementor-widget elementor-widget-text-editor\" data-id=\"69ce42c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-hiperespectral-intellihsi-aprendizaje-automatico-para-la-optimizacion-de-plataformas-de-supercomputacion-y-soporte-de-aplicaciones-de-imagen-hiperespectral\/\">Hiperespectral IntelliHSI: Aprendizaje Autom\u00e1tico para la Optimizaci\u00f3n de Plataformas de Supercomputaci\u00f3n y soporte de Aplicaciones de Imagen Hiperespectral<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Juan Antonio Rico Gallego, Antonio Plaza Miguel, Javier Plaza Miguel, Juan Carlos D\u00edaz Mart\u00edn, Juan Luis Garc\u00eda Zapata y Carmen Jurado Calvo. Universidad de Extremadura.<\/li><li>Javier Corral Gac\u00eda. C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Las pr\u00e1cticas actuales en computaci\u00f3n de altas prestaciones (HPC) est\u00e1n impulsadas por la optimizaci\u00f3n del rendimiento y el consumo energ\u00e9tico, encontrado una soluci\u00f3n ampliamente aceptada en la arquitectura de tipo cl\u00faster. Adem\u00e1s, las aplicaciones cient\u00edficas tienden a ser ejecutadas en plataformas heterog\u00e9neas, como demuestra el hecho de que 13 de los 25 supercomputadores m\u00e1s r\u00e1pidos del mundo (atendiendo a la lista TOP500 de junio de 2020) se basan en CPUs con m\u00faltiples cores y aceleradores gr\u00e1ficos (GPUs). Tambi\u00e9n los sistemas Cloud ofrecen plataformas innovadoras y rentables para ejecutar aplicaciones paralelas con requerimientos adicionales, como tolerancia a fallos y procesamiento masivo de datos, incluyendo aplicaciones de negocios, big data y aprendizaje autom\u00e1tico. En general, los sistemas paralelos formados por procesadores multi-core y aceleradores, comunic\u00e1ndose a trav\u00e9s de redes de diferentes capacidades, son ahora los sistemas m\u00e1s extendidos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-hiperespectral-intellihsi-aprendizaje-automatico-para-la-optimizacion-de-plataformas-de-supercomputacion-y-soporte-de-aplicaciones-de-imagen-hiperespectral\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec8763f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ec8763f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e16471 elementor-widget elementor-widget-text-editor\" data-id=\"8e16471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-lusitania-iv\/\">LUSITANIA IV<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><span style=\"font-size: 10pt;\"><strong>Researchers:\u00a0<\/strong><\/span><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>C\u00e9nitS-COMPUTAEX team.<\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto LUSITANIA IV persigue aumentar la potencia de c\u00f3mputo del C\u00e9nitS-CPD, el Centro de Proceso de Datos gestionado por C\u00e9nitS, el Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n, donde se han consolidado todas las infraestructuras inform\u00e1ticas y de comunicaciones con que cuenta C\u00e9nitS, para mejorar el servicio com\u00fan de investigaci\u00f3n que el centro ofrece desde 2009.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-lusitania-iv\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ba6fcf e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"8ba6fcf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91c06f4 elementor-widget elementor-widget-text-editor\" data-id=\"91c06f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-anemoi-modelo-predictivo-de-productividad-y-operatividad-de-parques-eolicos-aplicando-analitica-de-datos-y-aprendizaje-automatico\/\">Anemoi: Modelo Predictivo de Productividad y Operatividad de Parques E\u00f3licos Aplicando Anal\u00edtica de Datos y Aprendizaje Autom\u00e1tico<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"https:\/\/www.naturgy.es\/\" target=\"_blank\" rel=\"noopener\">Naturgy<\/a>\u00a0renovables S.L.U.<\/li><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El objetivo general del proyecto \u201cAnemoi: Modelo Predictivo de Productividad y Operatividad de Parques E\u00f3licos Aplicando Anal\u00edtica de Datos y Aprendizaje Autom\u00e1tico\u201d, es analizar los datos extra\u00eddos del parque e\u00f3lico del Merengue que la empresa NATURGY tiene en explotaci\u00f3n en Plasencia. La informaci\u00f3n se extraer\u00e1 de los datos que genera el funcionamiento de los aerogeneradors para identificar y analizar todas las variables que pueden influir en su vida \u00fatil, as\u00ed como en las causas de sus aver\u00edas. Adem\u00e1s, se correlacionar\u00e1n las variables que influyen en la productividad de los aerogeneradores. De este modo, se persigue analizar, modelar e identificar patrones de comportamiento en el funcionamiento de los aerogeneradores que puedan usarse para la predictibilidad del \u00f3ptimo funcionamiento y de la productividad que permita la reducci\u00f3n de incidencias de funcionamiento en el parque y que favorezaca el aumento de vida \u00fatil de los equipos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-anemoi-modelo-predictivo-de-productividad-y-operatividad-de-parques-eolicos-aplicando-analitica-de-datos-y-aprendizaje-automatico\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-635c22b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"635c22b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b4bb30 elementor-widget elementor-widget-text-editor\" data-id=\"5b4bb30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenits-cpd-resilient-datacenter\/\">C\u00e9nitS-CPD: Resilient datacenter<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>C\u00e9nitS-COMPUTAEX team.<\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The \u201cC\u00e9nitS-CPD: Resilient Datacenter\u201d project aims to reinforce, expand, and enhance the Data Processing Center (DPC) managed by the Extremadura Center for Research, Technological Innovation, and Supercomputing (C\u00e9nitS), the main instrument of the Extremadura Public Foundation for Computing and Advanced Technologies (COMPUTAEX), where all the IT and communications tools available to C\u00e9nitS will be consolidated, including the LUSITANIA, LUSITANIA II, and LUSITANIA III supercomputers.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenits-cpd-resilient-datacenter\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d655d0b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d655d0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e26d041 elementor-widget elementor-widget-text-editor\" data-id=\"e26d041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><a href=\"http:\/\/10.128.3.28\/proyecto-mecanismos-para-la-gestion-eficiente-del-plano-de-control-y-del-plano-de-datos-en-redes-moviles-5g\/\"><span style=\"font-size: 14pt;\">Mecanismos para la Gesti\u00f3n Eficiente del Plano de Control y del Plano de Datos en Redes M\u00f3viles 5G<\/span><\/a><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Tesis Doctoral realizada por Jes\u00fas Calle Cancho (C\u00e9nitS-COMPUTAEX).<\/li><li>Directores de la Tesis Doctoral: Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez (C\u00e9nitS-COMPUTAEX) y Javier Carmona Murillo (Universidad de Extremadura).<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En los \u00faltimos a\u00f1os, el incremento exponencial del tr\u00e1fico de datos m\u00f3viles, unido al despliegue de nuevos servicios sobre las redes actuales, han propiciado que los operadores de telecomunicaciones busquen nuevos mecanismos que permitan una gesti\u00f3n eficiente de la red de acuerdo a las demandas espec\u00edficas de los usuarios. Estos mecanismos deben ser capaces de gestionar los recursos de red din\u00e1micamente, proporcionando flexibilidad en el nuevo entorno 5G, a trav\u00e9s de tecnolog\u00edas emergentes. En este contexto, uno de los procesos involucrados en la gesti\u00f3n de la red es el soporte a la movilidad, cuyo principal objetivo es mantener las comunicaciones activas mientras los usuarios se mueven entre redes de acceso diferentes de manera transparente, minimizando el tiempo de desconexi\u00f3n o p\u00e9rdida de servicio.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mecanismos-para-la-gestion-eficiente-del-plano-de-control-y-del-plano-de-datos-en-redes-moviles-5g\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-036a77b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"036a77b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70e9fa0 elementor-widget elementor-widget-text-editor\" data-id=\"70e9fa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-implantacion-de-nuevos-sistemas-de-comunicacion-digital-y-e-learning\/\">Implantaci\u00f3n de nuevos sistemas de comunicaci\u00f3n digital y e-learning<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Fundaci\u00f3n Magdalena Moriche (<a href=\"https:\/\/inteligencialimite.org\/inteligencialimite\/descripcion-la-fundacion-magdalena-moriche\/\" target=\"_blank\" rel=\"noopener\">FMM<\/a>).<\/li><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El programa de Innovaci\u00f3n y Talento (PIT), promovido por la Consejer\u00eda de Educaci\u00f3n y Empleo de la Junta de Extremadura, y destinado a la contrataci\u00f3n de desempleados menores de 30 a\u00f1os, combina la formaci\u00f3n de tecn\u00f3logos con las pr\u00e1cticas profesionales en empresas privadas. As\u00ed, su objetivo es facilitar la inserci\u00f3n laboral de j\u00f3venes y potenciar las capacidades del talento de la regi\u00f3n extreme\u00f1a en las siguientes \u00e1reas estrat\u00e9gicas: agroalimentaria, tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC), turismo, salud, energ\u00edas limpias, investigaci\u00f3n b\u00e1sica, humanidades y ciencias sociales, econom\u00eda verde, econom\u00eda circular y bioeconom\u00eda.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-implantacion-de-nuevos-sistemas-de-comunicacion-digital-y-e-learning\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3da568 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f3da568\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-188a475 elementor-widget elementor-widget-text-editor\" data-id=\"188a475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-eurocc-national-competence-centres-in-the-framework-of-eurohpc\/\">EUROCC National Competence Centres in the framework of EuroHPC<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>33 national competence centres from Europe.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>High-Performance Computing, as a key tool for science and industry, has steadily grown over the past three decades into a mature technology that supports many of Europe\u2019s most important sectors. In many parts of the European\u00a0economy, including engineering, health, climate and energy, usage of computer aided design coupled to modelling and simulation continues to grow rapidly. The software applications used in these sectors drive innovation. In many areas from academia, industry but also public administration, the use of iterative modelling and simulation &#8211; including data management, analysis and visualisation &#8211; is becoming more and more important. HPC alone or HPC in combination with HPDA and AI provide the means to tackle not only large, complex problems but also to widen further the use and uptake of these technologies in academia, public administration and industry. Thus a symbiotic cooperation needs to be established, where the stakeholders of HPC infrastructures, services and expertise are enabled to improve their service portfolio on base of the customers\u2019 needs and thus to help the end users with a maximum of efficiency in their respective domain.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-eurocc-national-competence-centres-in-the-framework-of-eurohpc\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a09759 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3a09759\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-063d651 elementor-widget elementor-widget-text-editor\" data-id=\"063d651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-t4e-dih-technologies-for-efficiency-digital-innovation-hub-extremadura\/\">T4E DIH: Technologies for Efficiency Digital Innovation Hub Extremadura<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Fundaci\u00f3n\u00a0Fundecyt Parque Cient\u00edfico y Tecnol\u00f3gico de Extremadura (<a href=\"http:\/\/www.fundecyt-pctex.es\/\" target=\"_blank\" rel=\"noopener\">Fundecyt-PCTEx<\/a>).<\/li><li><a href=\"http:\/\/www.dip-badajoz.es\/\">Diputaci\u00f3n de Badajoz<\/a>.<\/li><li><a href=\"http:\/\/www.dip-caceres.es\/\">Diputaci\u00f3n de C\u00e1ceres<\/a>.<\/li><li>Universidad de Extremadura (<a href=\"http:\/\/www.unex.es\/\" target=\"_blank\" rel=\"noopener\">UEX<\/a>).<\/li><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><li>Asociaci\u00f3n Empresarial Extreme\u00f1a de Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n,\u00a0<a href=\"http:\/\/www.aextic.com\/\" target=\"_blank\" rel=\"noopener\">AEXTIC<\/a>.<\/li><li><a href=\"http:\/\/www.energiaextremadura.org\/\">Cluster de la Energ\u00eda de Extremadura<\/a>.<\/li><li><a href=\"http:\/\/cicytex.juntaex.es\/es\/\">CICYTEX<\/a>.<\/li><li><a href=\"http:\/\/www.feval.com\/\">FEVAL<\/a><\/li><li><a href=\"http:\/\/www.camaracaceres.com\/\">C\u00e1mara de comercio de C\u00e1ceres<\/a>.<\/li><li><a href=\"http:\/\/www.camarabadajoz.es\/web\/\">C\u00e1mara de comercio de Badajoz<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The Digital Innovation Hub\u00a0Technologies for Efficiency\u00a0(T4E DIH) is a physical and virtual space in which actions and services of the different agents of Extremadura are concentrated for the development and improvement of products and productive and business processes, through the use of technology.<\/p><p>T4E DIH is framed in the\u00a0<a href=\"https:\/\/ec.europa.eu\/digital-single-market\/en\/news\/communication-digitising-european-industry-reaping-full-benefits-digital-single-market\" target=\"_blank\" rel=\"noopener\">Initiative for the Digitization of European Industry<\/a>.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-t4e-dih-technologies-for-efficiency-digital-innovation-hub-extremadura\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3a11d3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e3a11d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd587db elementor-widget elementor-widget-text-editor\" data-id=\"bd587db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxotic-2019\/\">TaxoTIC 2019<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de\u00a0<a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (TIC) se han convertido en el principal motor de la emergente econom\u00eda digital y, como tal, merec\u00edan ser analizadas en profundidad. El proyecto TaxoTIC se inici\u00f3 en el a\u00f1o 2013 con el objetivo de visibilizar las TIC y a aquellas empresas y profesionales de Extremadura que prestan servicios relacionados con las mismas.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxotic-2019\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddfd7b8 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ddfd7b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b982bf elementor-widget elementor-widget-text-editor\" data-id=\"8b982bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenits-cpd-equipamiento-cientifico-tecnologico\/\">C\u00e9nitS-CPD: Equipamiento cient\u00edfico tecnol\u00f3gico<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>COMPUTAEX ha realizado en los \u00faltimos a\u00f1os una notable ampliaci\u00f3n y renovaci\u00f3n de los equipos de computaci\u00f3n de elevadas prestaciones (HPC) para fortalecer los servicios de supercomputaci\u00f3n ofrecidos. Gracias a la construcci\u00f3n de un nuevo CPD ser\u00e1 posible cubrir las expectativas m\u00e1s inmediatas de C\u00e9nitS, de cara a seguir contribuyendo decididamente al desarrollo regional, permitiendo que la ciencia y tecnolog\u00eda cuenten con un recursos avanzado para poder acometer nuevos retos que hasta\u00a0ahora no han podido ser emprendidos dentro de nuestra regi\u00f3n. No s\u00f3lo el entorno investigador ser\u00e1 m\u00e1s competitivo, sino que tambi\u00e9n el sector productivo se beneficiar\u00e1 de esta instalaci\u00f3n de forma directa, permitiendo que muchas empresas puedan acometer proyectos de innovaci\u00f3n tecnol\u00f3gica en C\u00e9nitS y convertirse en socios tecnol\u00f3gicos del mismo, siendo proveedores y clientes de un centro avanzado, \u00fanico en Extremadura y muy singular en el \u00e1mbito nacional y europeo. En definitiva, el principal objetivo que se pretende conseguir con este proyecto es la creaci\u00f3n del Centro de Proceso de Datos de Supercomputaci\u00f3n de Extremadura, C\u00e9nitS-CPD, donde alojar, proteger y gestionar todos los equipos HPC de los que dispone la Fundaci\u00f3n COMPUTAEX, para fortalecer los servicios de supercomputaci\u00f3n gestionados por su centro C\u00e9nitS.\u00a0<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenits-cpd-equipamiento-cientifico-tecnologico\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b402f89 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b402f89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3983822 elementor-widget elementor-widget-text-editor\" data-id=\"3983822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adquisicion-de-equipamiento-cientifico-tecnologico-de-la-fundacion-computaex\/\">Adquisici\u00f3n de equipamiento cient\u00edfico-tecnol\u00f3gico de la Fundaci\u00f3n COMPUTAEX<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Desde diciembre de 2019, Extremadura cuenta con un nuevo supercomputador,\u00a0<a href=\"https:\/\/computaex.eu\/lusitania-III\">LUSITANIA III<\/a>, alojado en C\u00e1ceres. Esto supone una destacable ampliaci\u00f3n de los recursos de c\u00f3mputo ofrecidos por\u00a0<a href=\"https:\/\/computaex.eu\/descripcion-la-fundacion\">COMPUTAEX<\/a>, aumentando considerablemente la potencia de c\u00e1lculo de la que ya dispon\u00eda. La actuaci\u00f3n llevada a cabo se encuadra dentro de las medidas recogidas en el Programa Operativo del Fondo Europeo de Desarrollo Regional 2014-2020 de Extremadura en el Objetivo Tem\u00e1tico 1 \u201cPotenciar la investigaci\u00f3n, el desarrollo tecnol\u00f3gico y la innovaci\u00f3n\u201d Prioridad de Inversi\u00f3n (PI0102) 1b \u201cLa mejora de las infraestructuras de investigaci\u00f3n e innovaci\u00f3n (I+i) y de la capacidad para desarrollar excelencia en materia de I+i, y el fomento de centros de competencia, en especial los de inter\u00e9s europeo\u201d y dentro del Objetivo Espec\u00edfico 1.1.2 \u201cFortalecimiento de las instituciones de I+D+i y la Estrategia de Investigaci\u00f3n e Innovaci\u00f3n para la Especializaci\u00f3n Inteligente de Extremadura, 2014-2020 (RIS3 Extremadura).<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adquisicion-de-equipamiento-cientifico-tecnologico-de-la-fundacion-computaex\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1097369 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1097369\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f528209 elementor-widget elementor-widget-text-editor\" data-id=\"f528209\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-smartnet5g-desarrollo-de-nuevos-mecanismos-de-gestion-en-redes-programables-de-proxima-generacion\/\">SmartNet5G: Desarrollo de nuevos mecanismos de gesti\u00f3n en redes programables de pr\u00f3xima generaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/gitaca.unex.es\/\" target=\"_blank\" rel=\"noopener\">G\u00cdTACA<\/a>\u00a0(Grupo de Investigaci\u00f3n de Ingenier\u00eda Telem\u00e1tica Aplicada y Comunicaciones Avanzadas) de la Universidad de Extremadura y\u00a0<a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>SmartNet 5G tiene como objetivo general gestionar de forma eficiente servicios de red, as\u00ed como dise\u00f1ar e implementar mecanismos de gesti\u00f3n autom\u00e1tica de la red utilizando para ello t\u00e9cnicas novedosas de virtualizaci\u00f3n de funciones de red en redes programables, que estar\u00e1n presentes en las redes de pr\u00f3xima generaci\u00f3n. SmartNet est\u00e1 concebido para servir de plataforma a empresas del sector TIC y a administraciones p\u00fablicas extreme\u00f1as que gestionan una red de telecomunicaciones y que necesitar\u00e1n adaptarse al nuevo entorno 5G. Este contexto, de las redes de pr\u00f3xima generaci\u00f3n, estar\u00e1 gobernado por redes de muy alta velocidad y alta fiabilidad en el que el aumento de las conexiones ser\u00e1 exponencial y la generaci\u00f3n de tr\u00e1fico se producir\u00e1 desde multitud de dispositivos y con tecnolog\u00edas heterog\u00e9neas. SmartNet5G prestar\u00e1 especial atenci\u00f3n a la gesti\u00f3n de las redes inal\u00e1mbricas y m\u00f3viles, dada su creciente relevancia en la actualidad y en los pr\u00f3ximos a\u00f1os.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"SmartNet5G: Desarrollo de nuevos mecanismos de gesti\u00f3n en redes programables de pr\u00f3xima generaci\u00f3n\" href=\"http:\/\/10.128.3.28\/proyecto-smartnet5g-desarrollo-de-nuevos-mecanismos-de-gestion-en-redes-programables-de-proxima-generacion\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7deacbd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7deacbd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebbbcdf elementor-widget elementor-widget-text-editor\" data-id=\"ebbbcdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-5g-clops-cross-layer-optimization-in-5g-networks\/\">5G-CLOPS: Cross-Layer Optimization in 5G Networks<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>\u00a0Universidad de Granada (<a href=\"https:\/\/www.ugr.es\/\" target=\"_blank\" rel=\"noopener\">UGR<\/a>), Universidad de Extremadura (<a href=\"https:\/\/www.unex.es\/\" target=\"_blank\" rel=\"noopener\">UEX<\/a>), Fundaci\u00f3n\u00a0<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>This ground-breaking proposal precisely suggests an holistic approach in which network resources allocation in the UE-BS (User Equipments and Base Stations) association is undertaken by taking into consideration not only the propagation channel condition but also the operation of the IP mobility management protocols that allow a seamless mobility and avoid service disruption during the user\u2019s movement among heterogeneous networks. This cross-layer solution could lead to a better utilisation of the network resources and to an optimised network performance. The goal is to devise a set of specialized metaheuristic algorithms for 5G networks capable of scheduling ultradense networks (UDNs) efficiently and engineering mechanisms for the automatic service management of SDN\/NFV-based (Software-Defined Network \/ Network Function Virtualization) access networks.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"5G-CLOPS: Cross-Layer Optimization in 5G Networks\" href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-5g-clops-cross-layer-optimization-in-5g-networks\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7af8f1e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7af8f1e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c3efce elementor-widget elementor-widget-text-editor\" data-id=\"1c3efce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-go2edge-disenando-las-futuras-redes-sistemas-y-servicios-de-computacion-seguros-en-el-extremo\/\">Go2Edge: dise\u00f1ando las futuras redes, sistemas y servicios de computaci\u00f3n seguros en el extremo<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Universidad de Valladolid.<\/li><li>Universidad Carlos III de Madrid.<\/li><li>Universitat Polit\u00e8cnica de Catalunya.<\/li><li>Universidad Polit\u00e9cnica de Cartagena.<\/li><li>Universidad Polit\u00e9cnica de Madrid.<\/li><li>Universitat de Girona.<\/li><li>Universitat Polit\u00e8cnica de Val\u00e8ncia.<\/li><li>Universidad de Salamanca.<\/li><li>Universidad de Granada.<\/li><li>Universidad de Vigo.<\/li><li>Centre Tecnol\u00f2gic de Telecomunicacions de Catalunya.<\/li><li>Barcelona Supercomputing Center.<\/li><li>Fundaci\u00f3n Computaci\u00f3n y Tecnolog\u00edas Avanzadas de Extremadura.<\/li><li>Instituto Nacional de Ciberseguridad.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Red tem\u00e1tica de excelencia formada por 15 entidades para combinar su experiencia, coordinar esfuerzos de investigaci\u00f3n y compartir resultados sobre tecnolog\u00edas que permiten acercar los recursos computacionales y de almacenamiento al extremo de la red. Para ello se desarrolla una visi\u00f3n multidisciplinar con capacidades complementarias e intereses diversos en las tecnolog\u00edas involucradas: computaci\u00f3n distribuida; cloud y fog computing; redes de comunicaciones; ciberseguridad; y aplicaciones finales que permitan explotar estas tecnolog\u00edas.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"Go2Edge: dise\u00f1ando las futuras redes, sistemas y servicios de computaci\u00f3n seguros en el extremo\" href=\"http:\/\/10.128.3.28\/proyecto-go2edge-disenando-las-futuras-redes-sistemas-y-servicios-de-computacion-seguros-en-el-extremo\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a58a27 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7a58a27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-926b914 elementor-widget elementor-widget-text-editor\" data-id=\"926b914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-ai-dih-spanish-digital-innovation-hub-for-hpc\/\">AI DIH: Spanish Digital Innovation Hub for HPC<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En el marco de sus iniciativas de digitalizaci\u00f3n de la industria (DEI), la Comisi\u00f3n Europea est\u00e1 apostando por los hubs de innovaci\u00f3n digital (DIHs, Digital Innovation Hubs), promoviendo la cooperaci\u00f3n y la creaci\u00f3n de redes entre ellos, como medio de apoyo a la transformaci\u00f3n digital de las empresas. As\u00ed, se cre\u00f3 un programa de capacitaci\u00f3n para el establecimiento de una red de colaboraci\u00f3n entre DIHs centrada en la Inteligencia Artificial, con el fin de servir de apoyo para la preparaci\u00f3n de pol\u00edticas relevantes para futuros programas como, por ejemplo, el de Europa Digital. Se persigue as\u00ed reforzar la competitividad de la Uni\u00f3n Europea en tecnolog\u00edas digitales y garantizar que cualquier empresa europea, independientemente de su sector, ubicaci\u00f3n o tama\u00f1o, pueda aprovechar los beneficios de la innovaci\u00f3n digital.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-ai-dih-spanish-digital-innovation-hub-for-hpc\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01f24e2 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"01f24e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec1134b elementor-widget elementor-widget-text-editor\" data-id=\"ec1134b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-conecta-pyme-4-0\/\">Conecta PYME 4.0<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Direcci\u00f3n General de Empresa, Consejer\u00eda de Econom\u00eda, Ciencia y Agenda Digital, Junta de Extremadura.<\/li><li>Direcci\u00f3n General de Formaci\u00f3n Profesional y Formaci\u00f3n para el Empleo, Consejer\u00eda de Educaci\u00f3n y Empleo, Junta de Extremadura.<\/li><li>CIEBI\/BIC &#8211; Centro de Innova\u00e7\u00e2o Empresarial da Beira Interior.<\/li><li>Extremadura Avante.<\/li><li>Instituto Pedro Nunes.<\/li><li>Universidad de Evora.<\/li><li>Fundaci\u00f3n COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto \u201cLa transformaci\u00f3n digital como estrategia de gesti\u00f3n del cambio hacia la pyme conectada en la regi\u00f3n Euroace (proyecto\u00a0<a href=\"https:\/\/conectapyme40.com\/\" target=\"_blank\" rel=\"noopener\">0743_CONECTA_PYME_4_0_4_E<\/a>)\u201d, se enmarca dentro del eje prioritario 2\u201d Crecimiento integrador a trav\u00e9s de una cooperaci\u00f3n transfronteriza a favor de la competitividad empresarial\u201d, Objetivo tem\u00e1tico 3 \u201cMejorar la competitividad de las peque\u00f1as y medianas empresas\u201d.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-conecta-pyme-4-0\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f93074 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"4f93074\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f1854e elementor-widget elementor-widget-text-editor\" data-id=\"2f1854e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-optimization-of-five-active-flow-control-parameters-on-a-sd7003-wing-profile-at-several-angles-of-attack-from-4-to-16-and-at-reynolds-number-60000\/\">Optimization of five Active Flow Control parameters on a SD7003 wing profile at several angles of attack from 4 to 16 and at Reynolds number 60000<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Josep M Bergada Granyo.\u00a0<a href=\"https:\/\/www.upc.edu\/\" target=\"_blank\" rel=\"noopener\">Universitat Politecnica de Catalunya<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Proyecto asignado a trav\u00e9s de la\u00a0<a href=\"https:\/\/www.res.es\/\" target=\"_blank\" rel=\"noopener\">Red Espa\u00f1ola de Supercomputaci\u00f3n<\/a>.<\/p><p>Increasing airfoils efficiency will reduce CO2 emissions, being a key point when considering the rise in air traffic expected in the future. During taking off, landing and under several airplane maneuvering, airfoils work near stall conditions, therefore using (AFC) to increase lift and security under these critical operating conditions is crucial. The present research is using and in-house code linked with the OpenFoam package, to optimize for six angles of attack, five (AFC) operating parameters, the momentum coefficient, jet inclination angle, frequency, groove width and location. The baseline cases and some of the optimized ones, will be run in LES to assess the (AFC) advantages. This knowledge will help manufacturers to decide where to locate (AFC) devices and which parameters need to be tuned for each angle of attack.\u00a0<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-optimization-of-five-active-flow-control-parameters-on-a-sd7003-wing-profile-at-several-angles-of-attack-from-4-to-16-and-at-reynolds-number-60000\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fbffbb e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9fbffbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81cf147 elementor-widget elementor-widget-text-editor\" data-id=\"81cf147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto\/\">Red-Integra<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"https:\/\/www.ayto-caceres.es\/\" target=\"_blank\" rel=\"noopener\">Ayuntamiento de C\u00e1ceres<\/a>\u00a0(coordinador).<\/li><li>C\u00e2mara Municipal de Portalegre.<\/li><li>Munic\u00edpio de Castelo Branco.<\/li><li>Fundaci\u00f3n\u00a0<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>&#8211;<a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>.<\/li><li>Ayuntamiento de Plasencia.<\/li><li>Tri\u00e1ngulo Urbano Ib\u00e9rico Rayano Triurbir AEIE (Agrupaci\u00f3n Europea de Inter\u00e9s Econ\u00f3mico).<\/li><li>Universidad de Extremadura (<a href=\"https:\/\/www.unex.es\/\" target=\"_blank\" rel=\"noopener\">UEX<\/a>).<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Resulta de especial importancia valorizar, divulgar y promover el patrimonio hist\u00f3rico, cultural y paisaj\u00edstico disponibles, para as\u00ed lograr su integraci\u00f3n con el sector econ\u00f3mico. En ese sentido, Triurbir se identifica con el nombre de Tri\u00e1ngulo Urbano Ib\u00e9rico Rayano, asociaci\u00f3n formada por las ciudades espa\u00f1olas de Plasencia y C\u00e1ceres y por las ciudades portuguesas de Castelo Branco y Portalegre, cuyo objetivo es el desarrollo y la dinamizaci\u00f3n de los municipios aprovechando las ayudas y programas de desarrollo transfronterizo ofrecidos por la Uni\u00f3n Europea. C\u00e1ceres, como miembro de esa asociaci\u00f3n, identifica dos ejes de gran importancia: el Turismo y la Innovaci\u00f3n, a trav\u00e9s de los cuales se afrontar\u00e1n los desaf\u00edos del futuro y la elaboraci\u00f3n de proyectos de financiaci\u00f3n europea con el horizonte del a\u00f1o 2020.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"Red-Integra\" href=\"http:\/\/10.128.3.28\/proyecto\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cefc6ed e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cefc6ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c38352d elementor-widget elementor-widget-text-editor\" data-id=\"c38352d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-taxonomtic-2018\/\">TaxonomTIC 2018<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (TIC) se han convertido en el principal motor de la emergente econom\u00eda digital y, como tal, merec\u00edan ser analizadas en profundidad. El proyecto TaxonomTIC se inici\u00f3 en el a\u00f1o 2013 con el objetivo de visibilizar las TIC y a aquellas empresas y profesionales de Extremadura que prestan servicios relacionados con las mismas.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-taxonomtic-2018\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d87e746 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d87e746\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db2628c elementor-widget elementor-widget-text-editor\" data-id=\"db2628c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estudio-y-analisis-de-nuevos-mecanismos-para-redes-inalambricas-de-proxima-generacion-haciendo-uso-de-tecnicas-de-computacion-de-altas-prestaciones\/\">Estudio y an\u00e1lisis de nuevos mecanismos para redes inal\u00e1mbricas de pr\u00f3xima generaci\u00f3n haciendo uso de t\u00e9cnicas de computaci\u00f3n de altas prestaciones<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Jos\u00e9 Javier Rico Palomo y Javier Carmona Murillo, Universidad de Extremadura; y Jes\u00fas Calle Cancho, C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En los \u00faltimos a\u00f1os, las redes inal\u00e1mbricas han experimentado un gran desarrollo debido al aumento exponencial de dispositivos m\u00f3viles. Adem\u00e1s, seg\u00fan varios informes de las principales empresas del sector TIC, se prev\u00e9 que el volumen de tr\u00e1fico de datos se multiplique por 1000 en el a\u00f1o 2020. Por ello, se est\u00e1n realizando avances en la infraestructura de red existente para dar cobertura a la creciente demanda de capacidad que se producir\u00e1 en un futuro cercano, considerando despliegues de celdas de cobertura muy densos en las redes de pr\u00f3xima generaci\u00f3n (5G).<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estudio-y-analisis-de-nuevos-mecanismos-para-redes-inalambricas-de-proxima-generacion-haciendo-uso-de-tecnicas-de-computacion-de-altas-prestaciones\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88f12da e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"88f12da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e36fc34 elementor-widget elementor-widget-text-editor\" data-id=\"e36fc34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-identificacion-de-patrones-de-comportamiento-en-el-funcionamiento-ordinario-de-aerogeneradores-de-un-parque-eolico-mediante-tecnicas-de-advanced-analytics-basadas-en-big-data\/\">Identificaci\u00f3n de patrones de comportamiento en el funcionamiento ordinario de aerogeneradores de un parque e\u00f3lico mediante t\u00e9cnicas de Advanced Analytics basadas en Big Data<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de\u00a0<a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><li><a href=\"https:\/\/canalyticals.com\/\" target=\"_blank\" rel=\"noopener\">Canalyticals Big Data Experts<\/a>, S.L.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El objetivo principal del proyecto\u00a0es analizar la informaci\u00f3n extra\u00edda del conjunto de equipos que conforman los parques e\u00f3licos, extrayendo aquellos datos que afectan de forma directa a su funcionamiento ordinario, para identificar y analizar todas las variables que pueden afectar de manera real a la vida \u00fatil de los aerogeneradores, as\u00ed como a las causas de sus aver\u00edas. De este modo, se persigue identificar patrones de comportamiento en el funcionamiento de equipos, que a su vez ayuden en la toma de decisiones para la reducci\u00f3n de fallas, favoreciendo el aumento de vida \u00fatil de los equipos evaluados, dentro de los principios de econom\u00eda sostenible y circular.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-identificacion-de-patrones-de-comportamiento-en-el-funcionamiento-ordinario-de-aerogeneradores-de-un-parque-eolico-mediante-tecnicas-de-advanced-analytics-basadas-en-big-data\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e5510a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7e5510a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30be5b5 elementor-widget elementor-widget-text-editor\" data-id=\"30be5b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-implementacion-de-un-sistema-para-el-control-de-consumos-energeticos-en-entornos-hpc\/\">Implementaci\u00f3n de un Sistema para el Control de Consumos Energ\u00e9ticos en Entornos HPC<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Manuel Jos\u00e9 Casillas, C\u00e9nitS-COMPUTAEX. Trabajo de Fin de Grado en Ingenier\u00eda Inform\u00e1tica en Ingenier\u00eda de Computadores, Universidad de Extremadura. Septiembre de 2018.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El prop\u00f3sito de este proyecto es la monitorizaci\u00f3n de trabajos ejecutados sobre el supercomputador LUSITANIA II. Debido a la gran relevancia que posee la correcta administraci\u00f3n de los recursos disponibles en el supercomputador, obtener la capacidad de gestionar sus recursos de forma inteligente se ha convertido en una actividad prioritaria.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-implementacion-de-un-sistema-para-el-control-de-consumos-energeticos-en-entornos-hpc\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e160b9 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1e160b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2ee915 elementor-widget elementor-widget-text-editor\" data-id=\"d2ee915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mecanismos-de-monitorizacion-y-analisis-de-trafico-en-redes-de-proxima-generacion\/\">Mecanismos de Monitorizaci\u00f3n y An\u00e1lisis de Tr\u00e1fico en Redes de Pr\u00f3xima Generaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Daniel Gonz\u00e1lez S\u00e1nchez. Trabajo de Fin de Grado en Ingenier\u00eda en Telem\u00e1tica, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Currently, communication networks are formed by a heterogeneous set of technologies and protocols in constant evolution, characterized by a great complexity. The current network protocols provide a great performance and reliability, increase the connectivity and the security but each protocol solves a specific problem without a global abstraction.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mecanismos-de-monitorizacion-y-analisis-de-trafico-en-redes-de-proxima-generacion\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d15ec12 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d15ec12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb69ce elementor-widget elementor-widget-text-editor\" data-id=\"4bb69ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2017\/\">TaxonomTIC 2017<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto TaxonomTIC (subproyecto del proyecto CENITAL) dio comienzo en el a\u00f1o 2013 y su objetivo principal consist\u0131\u0301a en conocer y entender las TIC (Tecnolog\u0131\u0301as de la Informaci\u00f3n y de la comunicaci\u00f3n) desde el punto de vista de las empresas y profesionales que proveen servicios TIC, cuyas actividades se constituyen como un potente motor econ\u00f3mico dentro del nuevo ecosistema socio-econ\u00f3mico y que merece la consideraci\u00f3n de sector.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2017\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-993e0ac e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"993e0ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da824e9 elementor-widget elementor-widget-text-editor\" data-id=\"da824e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-publicidad-marketing-digital-y-diseno-web\/\">Publicidad, marketing digital y dise\u00f1o web<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>.<\/li><li><a href=\"http:\/\/synopsis103.com\/\" target=\"_blank\" rel=\"noopener\">Synopsis 103<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El programa de Innovaci\u00f3n y Talento (PIT), promovido por la Consejer\u00eda de Educaci\u00f3n y Empleo de la Junta de Extremadura, y destinado a la contrataci\u00f3n de desempleados menores de 30 a\u00f1os, combina la formaci\u00f3n de tecn\u00f3logos con las pr\u00e1cticas profesionales en empresas privadas. As\u00ed, su objetivo es facilitar la inserci\u00f3n laboral de j\u00f3venes y potenciar las capacidades del talento de la regi\u00f3n extreme\u00f1a en las siguientes \u00e1reas estrat\u00e9gicas: agroalimentaria, tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC), turismo, salud, energ\u00edas limpias, investigaci\u00f3n b\u00e1sica, humanidades y ciencias sociales, econom\u00eda verde, econom\u00eda circular y bioeconom\u00eda.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-publicidad-marketing-digital-y-diseno-web\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe3599c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"fe3599c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc76f9d elementor-widget elementor-widget-text-editor\" data-id=\"fc76f9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-analisis-de-un-sistema-de-gobierno-para-federaciones-de-centros-de-procesamiento-de-datos-con-computacion-de-alto-rendimiento\/\">An\u00e1lisis de un sistema de gobierno para federaciones de centros de procesamiento de datos con computaci\u00f3n de alto rendimiento<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Javier Rubio Bravo, C\u00e9nitS-COMPUTAEX.\u00a0Trabajo Final de M\u00e1ster en Ingenier\u00eda de Telecomunicaci\u00f3n.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En los \u00faltimos a\u00f1os, las Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n (TIC) se han convertido en parte de la sociedad, cambiando m\u00faltiples aspectos como la forma de vida, las relaciones o el desempe\u00f1o de la actividad profesional. La denominada Sociedad de la Informaci\u00f3n o del Conocimiento est\u00e1 fuertemente influenciada por la aparici\u00f3n de los servicios en la nube (Cloud Computing). Dichos servicios, que se proporcionan a trav\u00e9s de Internet a los usuarios finales, se ofrecen desde centros de procesamiento de datos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-analisis-de-un-sistema-de-gobierno-para-federaciones-de-centros-de-procesamiento-de-datos-con-computacion-de-alto-rendimiento\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f3138c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0f3138c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-209090a elementor-widget elementor-widget-text-editor\" data-id=\"209090a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-evaluacion-de-la-movilidad-ip-y-posibilidades-de-integracion-en-redes-programables-5g\/\">Evaluaci\u00f3n de la movilidad IP y posibilidades de integraci\u00f3n en redes programables 5G<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Jos\u00e9 Manuel Mendoza Rubio, C\u00e9nitS-COMPUTAEX. Trabajo de Fin de Grado en Ingenier\u00eda Telem\u00e1tica, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En los \u00faltimos a\u00f1os, la generalizaci\u00f3n de los dispositivos de comunicaciones inal\u00e1mbricos y el desarrollo de multitud de servicios y aplicaciones han hecho que las redes inal\u00e1mbricas y m\u00f3viles se hayan convertido en la parte m\u00e1s atractiva y din\u00e1mica en el acceso de los usuarios a las tecnolog\u00edas de la informaci\u00f3n y las comunicaciones (TIC). Seg\u00fan las previsiones de las principales empresas del sector, se espera que el tr\u00e1fico de datos en este tipo de redes se multiplique casi por 10 en el a\u00f1o 2020 y que tres cuartas partes de todo este tr\u00e1fico sea tr\u00e1fico multimedia. Un requerimiento fundamental para poder dar soporte a este crecimiento de datos en las redes de pr\u00f3xima generaci\u00f3n es el de la gesti\u00f3n eficiente de la movilidad de los usuarios. Por tanto, es necesario dise\u00f1ar nuevas t\u00e9cnicas que permitan mantener las conexiones activas en situaciones cambiantes.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-evaluacion-de-la-movilidad-ip-y-posibilidades-de-integracion-en-redes-programables-5g\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f0a6bf e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7f0a6bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba4b451 elementor-widget elementor-widget-text-editor\" data-id=\"ba4b451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/\">Optimization of Algorithms and Parallel Applications in Heterogeneous Systems Through the Combined Use of Formal Models of Computing and Communications.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Juan Antonio Rico Gallego (Principal Investigator). University of Extremadura.<\/li><li>Juan Carlos D\u00edaz Mart\u00edn University of Extremadura.<\/li><li>Juan Luis Garc\u00eda Zapata. University of Extremadura.<\/li><li>Javier Corral Garc\u00eda. COMPUTAEX Foundation.<\/li><li>Jes\u00fas Calle Cancho. COMPUTAEX Foundation.<\/li><li>Carmen Calvo Jurado. University of Extremadura.<\/li><li>Jes\u00fas \u00c1lvarez Llorente. University of Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The hardware systems used in high-performance parallel computing are heterogeneous. Data centers and big facilities have incorporated machines that combine multi-core processors and accelerators (GPUs, etc.) connected through different communication channels, mainly shared memory and high-performance networks such as Infinband. The objective of this proposal is twofold: improving the current supercomputing performance, increasingly heterogeneous, and at the same <a href=\"http:\/\/10.128.3.28\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/\">time, reducing its energy consumption.<\/a><\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c14e0d4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"c14e0d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f6d0d3 elementor-widget elementor-widget-text-editor\" data-id=\"2f6d0d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-contribucion-al-desarrollo-de-discretizaciones-y-optimizacion-eficientes-para-el-analisis-y-diseno-de-filtros-antenas-y-agrupaciones-de-antenas\/\">Contribuci\u00f3n al desarrollo de discretizaciones y optimizaci\u00f3n eficientes para el an\u00e1lisis y dise\u00f1o de filtros, antenas y agrupaciones de antenas<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Investigador principal : Jes\u00fas Rubio Ruiz<\/li><li>Investigadores participantes: Rafael G\u00f3mez Alcal\u00e1, Juan F. Izquierdo Le\u00f3n, Yolanda Campos Roca.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Contribuci\u00f3n al an\u00e1lisis de circuitos y antenas de microondas mediante el m\u00e9todo de elementos finitos.\u00a0<\/li><\/ul><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-contribucion-al-desarrollo-de-discretizaciones-y-optimizacion-eficientes-para-el-analisis-y-diseno-de-filtros-antenas-y-agrupaciones-de-antenas\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dca94ec e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"dca94ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b54c8d6 elementor-widget elementor-widget-text-editor\" data-id=\"b54c8d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-deployment-of-next-generation-services-in-the-scientific-and-technological-network-of-extremadura\/\">Deployment of next generation services in the Scientific and Technological Network of Extremadura<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>\u00a0Jes\u00fas Calle Cancho, C\u00e9nitS-COMPUTAEX. Trabajo Final de M\u00e1ster Universitario en Direcci\u00f3n TIC, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>With the continuous development of network communications over the past few years, the achievement of an efficient orchestration and network management has revealed as one of the major challenges in next-generation networks environments. Furthermore, advances in mobile technologies and the user-driven growth of an increasingly diverse range of services has triggered the requirements to create a new generation of efficient network management mechanisms and architectures able to support these new mobile technologies, services and applications. The configuration and installation of traditional networks require a high degree of knowledge because many network elements have to be treated. Moreover the interactions between networks nodes (switches, routers, etc) are complex. Most cloud applications are distributed and often involve significant network activity to perform their operations. Network operators and service and product providers require a new network solution to efficiently for supporting the increasing demands of this changing network landscape.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-deployment-of-next-generation-services-in-the-scientific-and-technological-network-of-extremadura\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cfe6d6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5cfe6d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d89072d elementor-widget elementor-widget-text-editor\" data-id=\"d89072d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-sistema-de-gobierno-de-federaciones-de-cpd\/\">Sistema de Gobierno de Federaciones de CPD<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Su finalidad es maximizar la eficiencia de los equipos inform\u00e1ticos y de climatizaci\u00f3n, minimizando el consumo energ\u00e9tico de todos ellos, mediante el desarrollo de un sistema inteligente para gestionar una federaci\u00f3n de CPD .<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-sistema-de-gobierno-de-federaciones-de-cpd\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c664257 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"c664257\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7de36 elementor-widget elementor-widget-text-editor\" data-id=\"1f7de36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2016\/\">TaxonomTIC 2016<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto TaxonomTIC, dio comienzo en el a\u00f1o 2013 y su objetivo principal consist\u00eda en conocer y entender las TIC desde su origen, y no s\u00f3lo desde el punto de vista del usuario final, ya que existen empresas y profesionales cuyas actividades se constituyen como un potente motor econ\u00f3mico dentro del nuevo ecosistema socio-econ\u00f3mico y que merece la consideraci\u00f3n de sector.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2016\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef4bd4a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ef4bd4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71b414c elementor-widget elementor-widget-text-editor\" data-id=\"71b414c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital-2016\/\">CENITAL 2016<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto CENITAL 2016 fue propuesto como continuaci\u00f3n del proyecto\u00a0<a href=\"http:\/\/www.cenits.es\/proyectos\/cenital-2015\">CENITAL-2015<\/a>, que ofreci\u00f3 unos notables resultados. CENITAL 2016 centr\u00f3 especialmente las actividades de la Fundaci\u00f3n\u00a0<a href=\"https:\/\/computaex.eu\/descripcion-la-fundacion\">COMPUTAEX<\/a>, enfoc\u00e1ndolas en aspectos emergentes de las tecnolog\u00edas m\u00e1s avanzadas en materia de c\u00f3mputo y comunicaciones.\u00a0<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital-2016\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-779819f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"779819f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55fefa7 elementor-widget elementor-widget-text-editor\" data-id=\"55fefa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital-2015\/\">CENITAL 2015<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto CENITAL 2015 fue propuesto como continuaci\u00f3n del proyecto\u00a0<a href=\"http:\/\/www.cenits.es\/proyectos\/cenital-2\">CENITAL-2<\/a>, que dio unos\u00a0notables resultados. As\u00ed, CENITAL 2015\u00a0centr\u00f3 especialmente las actividades de la\u00a0<a href=\"https:\/\/computaex.eu\/descripcion-la-fundacion\">COMPUTAEX Foundation<\/a>\u00a0para enfocarse en los aspectos emergentes de las tecnolog\u00edas m\u00e1s avanzadas en materia de c\u00f3mputo y comunicaciones.\u00a0<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital-2015\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2281ecd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2281ecd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dca7cfc elementor-widget elementor-widget-text-editor\" data-id=\"dca7cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-accesibilidad-web\/\">Accesibilidad web<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El imparable avance de las TIC (Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones), as\u00ed como el contexto sociocultural y econ\u00f3mico bajo el cual est\u00e1n sustentadas, exige una serie de conocimientos y habilidades, tanto instrumentales como cognitivas, que permitan poner en pr\u00e1ctica nuevas formas de comunicaci\u00f3n, con las cuales \u00a0los ciudadanos podr\u00e1n adaptarse a la Sociedad de la Informaci\u00f3n mediante el uso de la informaci\u00f3n relevante.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-accesibilidad-web\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05b5610 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"05b5610\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02b2e29 elementor-widget elementor-widget-text-editor\" data-id=\"02b2e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-consumar\/\">ConSumar<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El consumo energ\u00e9tico es uno de los principales gastos que deben afrontar, tanto los ciudadanos como las empresas. Las nuevas tecnolog\u00edas juegan un papel principal a la hora de establecer sistemas de control y seguimiento con vistas a gestionar el consumo y la sostenibilidad energ\u00e9tica. La adecuada planificaci\u00f3n de los equipos con gran consumo puede suponer un ahorro importante. El proyecto ConSumar busca el desarrollo de herramientas que, basadas en t\u00e9cnicas de Big Data, permita a los consumidores una mejor planificaci\u00f3n del gasto energ\u00e9tico a trav\u00e9s de la predicci\u00f3n de los costes, relacionando el precio de la energ\u00eda con los datos clim\u00e1ticos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-consumar\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e97d634 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e97d634\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8903caa elementor-widget elementor-widget-text-editor\" data-id=\"8903caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-consumar\/\">\u200bConSumar<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>&#8211;<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Energy consumption is one of the main expenses that citizens and businesses must face. New technologies play a major role when establishing control and monitoring systems to manage consumption and energy sustainability. Proper planning of large consumption equipment can mean significant savings. The aim of the ConSumar project is to develop tools that, based on Big Data techniques, allow consumers to improve the planning of their energy expenditure by predicting costs, relating the price of energy with climate data.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-consumar\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c239c92 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"c239c92\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a13072d elementor-widget elementor-widget-text-editor\" data-id=\"a13072d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2015\/\">TaxonomTIC 2015<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto TaxonomTIC dio comienzo en el a\u00f1o 2013 y su objetivo principal consist\u00eda en la creaci\u00f3n de un observatorio del Sector TIC en la regi\u00f3n. Este observatorio permitir\u00eda identificar qu\u00e9 son las TIC, los elementos que las componen, describirlos y clasificarlos, para poder estudiar su impacto en Extremadura y generar una fuente de informaci\u00f3n adicional, que permita conocer qu\u00e9 profesionales, empresas u organismos se encuentran relacionados con este sector y cu\u00e1les se apoyan en dichas entidades para ofrecer servicios TIC.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2015\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9235f40 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9235f40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dbc39a elementor-widget elementor-widget-text-editor\" data-id=\"3dbc39a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adecuacion-del-cpd-de-lusitania-ii\/\">Adecuaci\u00f3n del CPD de LUSITANIA II<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>C\u00e9nitS-COMPUTAEX.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Inicialmente el desarrollo y despliegue del nuevo\u00a0supercomputador de Extremadura, LUSITANIA II, arranc\u00f3 tras la aplicaci\u00f3n de los resultados obtenidos en el proyecto Smart Green Data Center (SGDC) para la instalaci\u00f3n del supercomputador en un CPD (Centro de Proceso de Datos) al aire libre. Esto permiti\u00f3 evaluar el comportamiento de la supercomputaci\u00f3n en campos tan dispares como el de la movilidad, la modularidad y la monitorizaci\u00f3n, siendo capaz de poner a disposici\u00f3n de la comunidad investigadora un supercomputador en un CPD logrando la eficacia de sus partes m\u00e1s importantes (c\u00f3mputo, climatizaci\u00f3n y suministro energ\u00e9tico) maximizando la eficiencia y minimizando los impactos que experimentan los edificios que albergan los CPD (consumo energ\u00e9tico, vibraciones, radiaciones, etc.).<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adecuacion-del-cpd-de-lusitania-ii\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2ada58 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f2ada58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0d7ae elementor-widget elementor-widget-text-editor\" data-id=\"2e0d7ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital-2\/\">CENITAL-2<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>CENITAL-2, como continuidad de CENITAL, fue un proyecto de innovaci\u00f3n e investigaci\u00f3n desarrollado bajo el Programa Operativo FEDER Extremadura 2007-2013, dentro del Eje 1 \u00abDesarrollo de la Econom\u00eda del Conocimiento\u00bb. Su objetivo fue centrar especialmente las actividades de la Fundaci\u00f3n para enfocarse en los aspectos emergentes de las\u00a0tecnolog\u00edas m\u00e1s avanzadas en materia de c\u00f3mputo y comunicaciones.<\/p><p><strong>Los trabajos se estructuraron en los siguientes subproyectos y actividades:<\/strong><\/p><ul><li><a href=\"https:\/\/computaex.eu\/proyectos\/taxonomtic-2014\"><strong>TaxonomTIC 2014<\/strong><\/a>: con el prop\u00f3sito de seguir analizando el impacto y el futuro del sector TIC (Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n) extreme\u00f1o de forma objetiva, el equipo de C\u00e9nitS, tomando como punto de partida el an\u00e1lisis realizado durante el a\u00f1o 2013, llev\u00f3 a cabo un nuevo estudio centrado en tres aspectos claves. En primer lugar, se estableci\u00f3 una comparativa del sector en Extremadura respecto de Espana y Europa, con el objetivo de identificar las diferencias existentes y determinar las causas de las mismas. Por otro lado, se estudi\u00f3 y analiz\u00f3 la visi\u00f3n que se tiene del sector a trav\u00e9s de los responsables t\u00e9cnicos m\u00e1s cualificados, ya que la opini\u00f3n de estos directivos de empresas TIC es fundamental para obtener un conocimiento mas profundo del propio sector. Finalmente, se desarroll\u00f3 una plataforma open data que contiene todos los datos extra\u00eddos\u00a0del sector TIC extreme\u00f1o durante los a\u00f1os 2013 y 2014, con el fin de hacer publica la informaci\u00f3n generada en el proyecto, as\u00ed como ofrecer informaci\u00f3n a empresas del sector TIC extreme\u00f1o para dar a conocer los servicios que estas proporcionan a la sociedad.<\/li><\/ul><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital-2\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f48f01 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3f48f01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f309b8 elementor-widget elementor-widget-text-editor\" data-id=\"0f309b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-diseno-de-un-sistema-de-gestion-por-procesos-de-negocio-en-cenits-computaex\/\">Dise\u00f1o de un sistema de gesti\u00f3n por procesos de negocio en C\u00e9nitS\/COMPUTAEX<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Felipe Lemus Prieto, C\u00e9nitS-COMPUTAEX. M\u00e1ster Universitario en Direcci\u00f3n TIC, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Hoy en d\u00eda, es un hecho innegable que las organizaciones est\u00e1n inmersas en mercados y entornos globalizados; entorno donde cualquier organizaci\u00f3n que desee tener \u00e9xito, o, al menos, sobrevivir, necesita obtener buenos resultados empresariales.<\/p><p>Para lograr estos buenos resultados comerciales, las organizaciones necesitan gestionar adecuadamente su actividades y recursos para alinearlos con los objetivos de negocio, lo que ha desembocado en la necesidad de utilizar herramientas y metodolog\u00edas que permitan a las organizaciones configurar su sistema de gesti\u00f3n.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-diseno-de-un-sistema-de-gestion-por-procesos-de-negocio-en-cenits-computaex\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-712aca5 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"712aca5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f8528 elementor-widget elementor-widget-text-editor\" data-id=\"c6f8528\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-despliegue-de-un-testbed-de-redes-definidas-por-software-para-la-gestion-de-recursos-de-red-en-un-cpd\/\">Despliegue de un testbed de redes definidas por software para la gesti\u00f3n de recursos de red en un CPD<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Laura Amarilla Cardoso, C\u00e9nitS-COMPUTAEX. Trabajo Final de M\u00e1ster en Ingenier\u00eda de Telecomunicaci\u00f3n, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El aumento de los dispositivos m\u00f3viles y los contenidos, la virtualizaci\u00f3n de servidores, y la llegada de los servicios en la nube son algunas de las tendencias que impulsan a la industria del networking a reexaminar las arquitecturas de red tradicionales. El modelo de red predominante hoy en d\u00eda no est\u00e1 optimizado para satisfacer los requerimientos actuales y futuros de los operadores de telecomunicaciones, empresas y usuarios finales. La mayor parte de las redes convencionales presentan una arquitectura est\u00e1tica inadecuada para los requisitos actuales, como, por ejemplo, las necesidades de almacenamiento de los centros de datos empresariales. Al reconocer el problema, la comunidad del networking trabaja para desarrollar nuevos modelos de red que se adapten mejor a los requisitos que son necesarios para los nuevos servicios y aplicaciones.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-despliegue-de-un-testbed-de-redes-definidas-por-software-para-la-gestion-de-recursos-de-red-en-un-cpd\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e26064 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"8e26064\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8886af elementor-widget elementor-widget-text-editor\" data-id=\"d8886af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-2\/\">Gesti\u00f3n de la movilidad en redes de transporte de paquetes para la mejora de la calidad de servicio en la convergencia entre las redes fijas y m\u00f3viles<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>David Miguel Cort\u00e9s Polo, C\u00e9nitS-COMPUTAEX. Tesis Doctoral, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Durante el a\u00f1o 2015, se present\u00f3 esta tesis doctoral, realizada por David Cort\u00e9s, Administrador de redes y comunicaciones de C\u00e9nitS, y dirigida por Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez, Director General de la Fundaci\u00f3n COMPUTAEX.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-2\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12fb735 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"12fb735\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3afc094 elementor-widget elementor-widget-text-editor\" data-id=\"3afc094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-degusta-san-juan-s-l\/\">Degusta San Juan S.L.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.degustasanjuan.com\/\">DEGUSTA SAN JUAN<\/a>\u00a0es una empresa dedicada a la consumici\u00f3n y venta al por menor de productos alimenticios y bebidas t\u00edpicos de Extremadura. Las ventas son realizadas, en general, a cualquier cliente, pero en particular est\u00e1n interesados en los visitantes de C\u00e1ceres. La empresa dispone de una gran variedad de productos, siendo los m\u00e1s importantes los embutidos y los vinos. En esta empresa tambi\u00e9n se pueden encontrar: jamones, quesos, aceites, piment\u00f3n, miel, mermeladas, pat\u00e9s, dulces, conservas y cosm\u00e9tica elaborada con aceite.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-degusta-san-juan-s-l\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d053ef1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d053ef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72b7ab5 elementor-widget elementor-widget-text-editor\" data-id=\"72b7ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 14pt; color: #000000;\"><a style=\"font-family: Raleway, Helvetica, Arial, sans-serif; font-weight: 600; color: #000000;\" href=\"http:\/\/10.128.3.28\/proyecto-instituto-stetica-s-l\/\">Instituto Stetica S.L.<\/a><\/span><\/p><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.institutostetica.com\/\">INSTITUTO STETICA<\/a>\u00a0es un centro de cirug\u00eda pl\u00e1stica y est\u00e9tica que ofrece diferentes servicios: depilaci\u00f3n y tratamientos con l\u00e1ser; nutrici\u00f3n; medicina est\u00e9tica; tratamientos de alopecia; cirug\u00eda pl\u00e1stica y est\u00e9tica corporal; y cirug\u00eda vascular.<\/p><p>El plan de innovaci\u00f3n llevado a cabo con\u00a0<a href=\"http:\/\/www.institutostetica.com\/\">INSTITUTO STETICA<\/a>\u00a0ha consistido en: la creaci\u00f3n de un gestor de contenidos adaptado, un asesoramiento para el cumplimiento de los est\u00e1ndares web de usabilidad y accesibilidad (con compatibilidad con dispositivos m\u00f3viles), el desarrollo de una estrategia social media, as\u00ed como una mejora de posicionamiento web, junto con la incursi\u00f3n profesional en las principales redes sociales.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-instituto-stetica-s-l\/\">Leer m\u00e1s<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1778734 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1778734\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f50ca0 elementor-widget elementor-widget-text-editor\" data-id=\"0f50ca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/\">Afimec Centro de Formaci\u00f3n Profesional<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.afimec.es\/\">AFIMEC<\/a>\u00a0es una empresa que dedica su actividad principal a la ense\u00f1anza, abarcando a numerosos colectivos y campos de la formaci\u00f3n. Para ello, y desde sus inicios se ha ido consolidando un grupo humano altamente profesional y cualificado para el desarrollo de su actividad.\u00a0<a href=\"http:\/\/www.afimec.es\/\">AFIMEC Formaci\u00f3n<\/a>, posee dos sedes (Badajoz y Almendralejo) donde realizan sus actividades e imparten cursos de formaci\u00f3n a sus alumnos.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80ad457 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"80ad457\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6897aa9 elementor-widget elementor-widget-text-editor\" data-id=\"6897aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/bobimex-s-l\/\">Bobimex S.L.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.bobimex.com\/\">BOBIMEX<\/a>\u00a0es una empresa que se dedica a distribuci\u00f3n, instalaciones y reparaciones centr\u00e1ndose en: la venta y suministro de material industrial; instalaciones de aire comprimido certificadas; y reparaci\u00f3n y mantenimiento de m\u00e1quinas el\u00e9ctricas.<\/p><p>En este vale se ha realizado el desarrollo de un sistema de innovaci\u00f3n que mejorase la productividad y la competitividad de las actividades de la empresa, mediante un estudio sobre la implantaci\u00f3n de una herramienta para gestionar toda la organizaci\u00f3n y de un sistema inform\u00e1tico de apoyo a la gesti\u00f3n de las relaciones con los clientes, la venta y el marketing.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/bobimex-s-l\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2872856 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2872856\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-400c2a9 elementor-widget elementor-widget-text-editor\" data-id=\"400c2a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-isatex-cee\/\">Isatex, CEE.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.isatex.es\/\">ISATEX<\/a>\u00a0es una empresa que dedica su actividad a la personalizaci\u00f3n de ropa y obsequios mediante t\u00e9cnicas de bordado, serigraf\u00eda, sublimaci\u00f3n, vinilos de impresi\u00f3n y corte, tampograf\u00eda y transfers. Tambi\u00e9n ofrecen servicios de fotograf\u00eda e impresi\u00f3n digital en gran formato.<\/p><p>Para este proyecto de innovaci\u00f3n se ha realizado un asesoramiento en campa\u00f1a de marketing para la distribuci\u00f3n de productos on-line y se ha creado un nuevo sitio web mediante un gestor de contenidos adaptado a las necesidades de la empresa.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-isatex-cee\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7af872 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f7af872\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e6e1b9 elementor-widget elementor-widget-text-editor\" data-id=\"2e6e1b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-network-languages-formacion-s-c\/\">Network Languages Formaci\u00f3n S.C.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.networklanguages.es\/\">NETWORK LANGUAGES<\/a>\u00a0es una empresa especializada en el aprendizaje de las habilidades comunicativas y en el desarrollo y potenciaci\u00f3n del talento de las personas y organizaciones que desempe\u00f1an su labor en un entorno Internacional. Esta empresa acelera las habilidades de comunicaci\u00f3n en diferentes idiomas para empresas, organizaciones o profesionales que trabajan en entornos internacionales.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-network-languages-formacion-s-c\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5367c95 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5367c95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e61fbe elementor-widget elementor-widget-text-editor\" data-id=\"1e61fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-proigam-instalaciones-s-l\/\">Proigam Instalaciones S.L.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.biothermia.es\/\">PROIGAM INSTALACIONES<\/a>\u00a0es una empresa dedicada al estudio, ejecuci\u00f3n y gesti\u00f3n de instalaciones t\u00e9rmicas con propuestas basadas en energ\u00edas renovables. Las propuestas de esta empresa siempre estar\u00e1n basadas en la mayor eficiencia solar, t\u00e9rmica, geotermica, aerot\u00e9rmica o de biomasa seg\u00fan el tipo de instalaci\u00f3n.<\/p><p>Se ha ofrecido asistencia tecnol\u00f3gica para el desarrollo de un proyecto innovador, con servicio de transformaci\u00f3n de datos, representaci\u00f3n de los mismos e implantaci\u00f3n de licencia tecnol\u00f3gica y formaci\u00f3n de empleados para una mejor explotaci\u00f3n del producto.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-proigam-instalaciones-s-l\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-595fd01 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"595fd01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1669e57 elementor-widget elementor-widget-text-editor\" data-id=\"1669e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-omicron-elevadores-s-a\/\">Omicr\u00f3n Elevadores S.A.<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/omicronelevadores.com\/\">OMICRON ELEVADORES<\/a>\u00a0es una empresa dedicada al sector de la elevaci\u00f3n, especializada en proporcionar soluciones de transporte vertical en edificios y teniendo como actividad principal el dise\u00f1o, venta, instalaci\u00f3n, mantenimiento y reparaci\u00f3n de todo tipo de aparatos elevadores tales como ascensores, montacoches, plataformas industriales, salvaescaleras, montacargas, elevadores unifamiliares, etc.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-omicron-elevadores-s-a\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61c1053 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"61c1053\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dcd3e9 elementor-widget elementor-widget-text-editor\" data-id=\"8dcd3e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mentor-e-learning\/\">M\u00e9ntor e-Learning<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/www.mentorsoluciones.com\/\">M\u00c9NTOR E-LEARNING<\/a> es una empresa dedicada a: soluciones de eLearning, dirigidas a empresas, organismos o entidades que desean trasladar su formaci\u00f3n presencial a la modalidad online;\u00a0soluciones de formaci\u00f3n a terceros, dirigidas a quienes ya disponen de un aula virtual propia; y soluciones de consultor\u00eda,\u00a0dirigidas a quienes buscan asesoramiento en el \u00e1mbito de proyectos e-learning.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mentor-e-learning\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16b1f7d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"16b1f7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a503b51 elementor-widget elementor-widget-text-editor\" data-id=\"a503b51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-ultrasecuenciacion-genetica-mediante-tecnicas-de-supercomputacion\/\">Ultrasecuenciaci\u00f3n gen\u00e9tica mediante t\u00e9cnicas de supercomputaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.areasaludcaceres.es\/modulos\/mod_organigrama\/pub\/ficha_servicios.php?id=4\">Servicio de Inmunolog\u00eda y Gen\u00e9tica Molecular del Hospital San Pedro de Alc\u00e1ntara de C\u00e1ceres<\/a>\u00a0and\u00a0<a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Este proyecto, asistencial y de investigaci\u00f3n, est\u00e1 siendo desarrollado por el\u00a0<a href=\"http:\/\/www.areasaludcaceres.es\/modulos\/mod_organigrama\/pub\/ficha_servicios.php?id=4\">Servicio de Inmunolog\u00eda y Gen\u00e9tica Molecular del Hospital San Pedro de Alc\u00e1ntara de C\u00e1ceres<\/a>\u00a0(Servicio Extreme\u00f1o de Salud) en colaboraci\u00f3n con investigadores de la\u00a0<a href=\"http:\/\/www.cenits.es\/descripcion-la-fundacion\">COMPUTAEX Foundation<\/a>. Las nuevas t\u00e9cnicas de secuenciaci\u00f3n masiva de ADN, cuyo uso se est\u00e1 imponiendo en el \u00e1mbito de la gen\u00e9tica y la bioinform\u00e1tica, permiten secuenciar el genoma de un ser humano con una reducci\u00f3n en t\u00e9rminos de tiempo y coste econ\u00f3mico cada vez mayor. Por ello, se hace necesaria la utilizaci\u00f3n de supercomputadores como\u00a0<a href=\"http:\/\/www.cenits.es\/cenits\/lusitania\">LUSITANIA<\/a>, que adem\u00e1s de procesar la ingente cantidad de datos generada, para poder estudiar la informaci\u00f3n contenida en el ADN, permite simular rasgos complejos de genes, estructuras subat\u00f3micas y tridimensionales, as\u00ed como amino\u00e1cidos de las prote\u00ednas.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-ultrasecuenciacion-genetica-mediante-tecnicas-de-supercomputacion\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fd1d6b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7fd1d6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e8ddb3 elementor-widget elementor-widget-text-editor\" data-id=\"4e8ddb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><p><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-factoria-de-innovacion\/\">Factor\u00eda de Innovaci\u00f3n<\/a><\/span><\/p><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.ayto-caceres.es\/\">Ayuntamiento de C\u00e1ceres<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Factor\u00eda de Innovaci\u00f3n es una comunidad virtual de emprendedores, empresarios y personas inquietas, que busca conectar innovaci\u00f3n y talento para generar nuevas oportunidades de negocio, un lugar de encuentro y reuni\u00f3n en el que se puede encontrar informaci\u00f3n sobre lo \u00faltimo en innovaci\u00f3n, creatividad, tecnolog\u00eda, modelos de negocio, posibilidades para pymes y emprendedores. Principalmente agrupa a miembros de la regi\u00f3n de Extremadura y la zona del Alentejo Portugu\u00e9s, aunque se encuentra abierta a m\u00e1s regiones espa\u00f1olas.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-factoria-de-innovacion\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b661590 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b661590\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3315dc elementor-widget elementor-widget-text-editor\" data-id=\"b3315dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-aplicacion-de-tecnicas-big-data-a-la-predictibilidad-de-flujos-de-trafico-urbano-en-ciudades-inteligentes\/\">Aplicaci\u00f3n de t\u00e9cnicas Big Data a la predictibilidad de flujos de tr\u00e1fico urbano en Ciudades Inteligentes<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nits<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/flujostrafico_1.png\" alt=\"\" width=\"385\" height=\"229\" \/><\/p><p>El tr\u00e1fico rodado es uno de los principales problemas a los que se enfrenta la mayor\u00eda de las ciudades. Las nuevas tecnolog\u00edas juegan un papel principal a la hora de establecer sistemas de control y seguimiento de los mismos con vistas a facilitar la movilidad y la sostenibilidad. La adecuada gesti\u00f3n del tr\u00e1fico revierte en un mejor aprovechamiento de las infraestructuras, en una reducci\u00f3n de las emisiones contaminantes a la atm\u00f3sfera, en un menor consumo de carburante, en una mejor gesti\u00f3n del tiempo y en un incremento en la seguridad de los ciudadanos.<br \/>El principal objetivo de este proyecto era poner al servicio de las ciudades extreme\u00f1as entornos de Cloud Computing y Big Data para una gesti\u00f3n eficaz, eficiente y sostenible del tr\u00e1fico rodado.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-aplicacion-de-tecnicas-big-data-a-la-predictibilidad-de-flujos-de-trafico-urbano-en-ciudades-inteligentes\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f2f77f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2f2f77f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-062f420 elementor-widget elementor-widget-text-editor\" data-id=\"062f420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2014\/\"><span style=\"font-size: 14pt;\">TaxonomTIC 2014<\/span><\/a><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de\u00a0<a href=\"\/en\/personal\/\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El objetivo inicial de\u00a0<a href=\"http:\/\/www.cenits.es\/proyectos\/taxonomtic\">TaxonomTIC<\/a>\u00a0consisti\u00f3 en identificar las TIC, los elementos que las componen, describirlos y clasificarlos, para poder estudiar su impacto en Extremadura y servir de fuente de informaci\u00f3n para conocer a los profesionales, empresas y organismos vinculados al sector.<\/p><p>Sin embargo, algunos aspectos importantes no pudieron ser tratados. Por ello, como parte del proyecto CENITAL-2 se ha continuado con el subproyecto\u00a0<a href=\"http:\/\/www.cenits.es\/proyectos\/taxonomtic\">TaxonomTIC<\/a>\u00a0durante el a\u00f1o 2014, enmarcado espec\u00edficamente en el \u00e1rea de excelencia TIC de la\u00a0<a href=\"http:\/\/www.redidi.es\/Publico\/RED-IDI\/ES\/Politica-regional-europea\/Paginas\/default.aspx\">Estrategia RIS3<\/a>\u00a0y cuyo objetivo principal era extender los trabajos realizados en el proyecto durante el a\u00f1o 2013.<\/p><p class=\"rtecenter\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/taxonomtic2014_1.jpg\" alt=\"\" width=\"429\" height=\"269\" \/><\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-taxonomtic-2014\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e124da e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5e124da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf4aee8 elementor-widget elementor-widget-text-editor\" data-id=\"cf4aee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adquisicion-traslado-e-instalacion-de-infraestructura-cientifica-y-tecnologica-para-cenits\/\">Adquisici\u00f3n, traslado e instalaci\u00f3n de infraestructura cient\u00edfica y tecnol\u00f3gica para C\u00e9nitS<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nits<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Proyecto financiado en la convocatoria de\u00a0<a href=\"http:\/\/xn--infraestructura%20cientfico-tecnolgica%20(2010-2011)%20del%20ministerio%20de%20economa%20y%20competitividad-9vj6d60b.\/\">Infraestructura Cient\u00edfico-Tecnol\u00f3gica (2010-2011) del Ministerio de Econom\u00eda y Competitividad.<\/a><\/p><p>Se financia, a trav\u00e9s de esta convocatoria, la adquisici\u00f3n e instalaci\u00f3n de equipamiento cient\u00edfico-tecnol\u00f3gico: en particular se considera la financiaci\u00f3n equipos que se soliciten para uso compartido de varios investigadores y proyectos, de coste superior a 60.000\u20ac, sin perjuicio de que, en casos excepcionales y dada la naturaleza de la solicitud en cuesti\u00f3n, puedan financiarse equipos de coste inferior.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"Adquisici\u00f3n, traslado e instalaci\u00f3n de infraestructura cient\u00edfica y tecnol\u00f3gica para C\u00e9nitS\" href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adquisicion-traslado-e-instalacion-de-infraestructura-cientifica-y-tecnologica-para-cenits\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5894783 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5894783\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc7b04 elementor-widget elementor-widget-text-editor\" data-id=\"edc7b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adecuacion-de-la-red-de-comunicaciones-para-cenits\/\">Adecuaci\u00f3n de la red de comunicaciones para C\u00e9nitS<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nits<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Proyecto presentado a la convocatoria de\u00a0<a href=\"http:\/\/www.idi.mineco.gob.es\/portal\/site\/MICINN\/menuitem.dbc68b34d11ccbd5d52ffeb801432ea0\/?vgnextoid=5459d5567a2ca210VgnVCM1000001d04140aRCRD\">Infraestructura Cient\u00edfico-Tecnol\u00f3gica del Ministerio de Econom\u00eda y Competitividad<\/a>.<\/p><p>Se financia, a trav\u00e9s de esta convocatoria, la adquisici\u00f3n e instalaci\u00f3n de equipamiento cient\u00edfico-tecnol\u00f3gico: en particular se considera la financiaci\u00f3n equipos que se soliciten para uso compartido de varios investigadores y proyectos, de coste superior a 60.000\u20ac, sin perjuicio de que, en casos excepcionales y dada la naturaleza de la solicitud en cuesti\u00f3n, puedan financiarse equipos de coste inferior.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"Adecuaci\u00f3n de la red de comunicaciones para C\u00e9nitS\" href=\"http:\/\/10.128.3.28\/proyectos\/proyecto-adecuacion-de-la-red-de-comunicaciones-para-cenits\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9280c91 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9280c91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e0f618 elementor-widget elementor-widget-text-editor\" data-id=\"0e0f618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-eister-e-infranet-sustainability-training-and-educational-resource\/\">EISTER &#8211; e-Infranet Sustainability Training and Educational Resource<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>\u00a0trabaj\u00f3 en el proyecto e-InfraNet junto a socios de pa\u00edses europeos con experiencia en Green ICT:\u00a0<a href=\"http:\/\/www.howest.be\/\">University College of West Flanders<\/a>\u00a0(Howest, B\u00e9lgica),\u00a0<a href=\"http:\/\/www.ucd.ie\/\">University College\u00a0Dublin<\/a>\u00a0(Dublin, Irlanda),\u00a0<a href=\"http:\/\/www.leedsbeckett.ac.uk\/\">Leeds Metropolitan University<\/a>\u00a0(Leeds, Reino Unido) y\u00a0<a href=\"http:\/\/www.ulisboa.pt\/\">Technical University of Lisbon<\/a>\u00a0(Lisboa, Portugal). Adem\u00e1s de con otros socios expertos en el desarrollo de la educaci\u00f3n a distancia y materiales on-line:\u00a0<a href=\"http:\/\/www.rtu.lv\/es\/\">Riga Technical University<\/a>\u00a0(Riga, Letonia) y\u00a0<a href=\"https:\/\/www.ou.nl\/\">Open Universiteit<\/a>\u00a0(Pa\u00edses Bajos) y con expertos en centros de datos de\u00a0<a href=\"https:\/\/www.kamk.fi\/en\">Kajaani University of Applied Sciences<\/a>\u00a0(Kajaani, Finlandia).<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Este proyecto fue presentado a una call de un proyecto encuadrado dentro\u00a0<a href=\"http:\/\/eur-lex.europa.eu\/legal-content\/ES\/TXT\/?uri=uriserv:i23022\">S\u00e9ptimo Programa Marco<\/a>, el cu\u00e1l agrupa todas las iniciativas comunitarias relativas a la investigaci\u00f3n bajo un mismo techo y desempe\u00f1a un papel crucial en el logro de los objetivos de crecimiento, competitividad y empleo, complementado por el nuevo\u00a0<a href=\"http:\/\/ec.europa.eu\/cip\/index_es.htm\">Programa Marco para la Competitividad y la Innovaci\u00f3n (CIP)<\/a>, programas de educaci\u00f3n y formaci\u00f3n y\u00a0<a href=\"http:\/\/ec.europa.eu\/contracts_grants\/funds_es.htm\">Fondos Estructurales y de Cohesi\u00f3n<\/a>\u00a0en apoyo de la convergencia y la competitividad de las regiones. Constituye tambi\u00e9n un pilar fundamental del\u00a0<a href=\"http:\/\/www.isciii.es\/ISCIII\/es\/contenidos\/fd-internacional\/espacio-europeo-investigacion.shtml\">Espacio Europeo de Investigaci\u00f3n (EEI)<\/a>.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-eister-e-infranet-sustainability-training-and-educational-resource\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62979e1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"62979e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b14b693 elementor-widget elementor-widget-text-editor\" data-id=\"b14b693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-red-nova-sostenible\/\">Red NOVA sostenible<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Contrato conseguido en licitaci\u00f3n p\u00fablica del\u00a0<a href=\"http:\/\/www.ayto-caceres.es\/\">Exmo. Ayuntamiento de C\u00e1ceres<\/a>\u00a0para colaboraci\u00f3n en el proyecto para la\u00a0<a href=\"http:\/\/www.factorinnovation.eu\/\">Factor\u00eda de la Innovaci\u00f3n<\/a>.<\/p><p>The\u00a0<a href=\"http:\/\/www.factorinnovation.eu\/\">Factor\u00eda de Innovaci\u00f3n<\/a>\u00a0es una comunidad virtual de emprendedores, empresarios y personas interesadas en conectar innovaci\u00f3n y talento para generar nuevas oportunidades de negocio.<\/p><\/div><\/div><\/div><\/div><footer><p style=\"text-align: right;\"><a title=\"Red NOVA sostenible\" href=\"http:\/\/10.128.3.28\/proyecto-red-nova-sostenible\/\" rel=\"tag\">Leer m\u00e1s<\/a><\/p><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fb6f7a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3fb6f7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5452ab3 elementor-widget elementor-widget-text-editor\" data-id=\"5452ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><a href=\"http:\/\/10.128.3.28\/proyecto-soporte-en-porting-a-usuarios-del-ciemat-en-la-plataforma-de-lusitania\/\">Soporte en porting a usuarios del CIEMAT en la plataforma de LUSITANIA<\/a><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Antonio Mu\u00f1oz Rold\u00e1n<\/strong>\u00a0perteneciente al Departamento de Inform\u00e1tica del\u00a0<a href=\"http:\/\/www.ciemat.es\/\">CIEMAT<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Soporte, informaci\u00f3n, consultor\u00eda a usuarios del\u00a0<a href=\"http:\/\/www.ciemat.es\/\">CIEMAT<\/a>\u00a0con el objetivo de portar sus c\u00f3digos a la plataforma de\u00a0<a href=\"\/en\/lusitania\/\">LUSITANIA<\/a>.<\/li><li>Codificaci\u00f3n de\u00a0<strong>MCNPX<\/strong>\u00a0en configuraci\u00f3n paralela utilizando la librer\u00eda de paso de mensajes\u00a0<strong>MPI<\/strong>\u00a0y el c\u00f3digo\u00a0<strong>EUTERPE<\/strong>.<\/li><\/ul><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-soporte-en-porting-a-usuarios-del-ciemat-en-la-plataforma-de-lusitania\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div><footer><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40572d4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"40572d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e7bb2c elementor-widget elementor-widget-text-editor\" data-id=\"4e7bb2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-simulacion-de-dispositivos-opticos-integrados\/\">Simulaci\u00f3n de dispositivos \u00f3pticos integrados<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Rafael G\u00f3mez Alcal\u00e1<\/strong>\u00a0del\u00a0<a href=\"http:\/\/tcc.unex.es\/\">Departamento de Tecnolog\u00eda de los Computadores y las Comunicaciones<\/a>\u00a0of the\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Desarrollo de herramientas computacionales que permitan el dise\u00f1o y simulaci\u00f3n de dispositivos y sistemas de comunicaciones \u00f3pticas. El principal problema que surge en este tipo de an\u00e1lisis y dise\u00f1o es la elevada complejidad computacional, lo que requiere el uso de recursos intensivos de computaci\u00f3n.<\/li><li>Con el proyecto se pretende poner a punto un simulador de dispositivos fot\u00f3nicos y optoelectr\u00f3nicos que permita analizar de forma gen\u00e9rica un sistema comercial de comunicaciones \u00f3pticas.<\/li><\/ul><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-simulacion-de-dispositivos-opticos-integrados\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-767e060 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"767e060\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d937b27 elementor-widget elementor-widget-text-editor\" data-id=\"d937b27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-sibe\/\">SIBE<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/\">CETIEX (Centro Tecnol\u00f3gico Industrial de Extremadura)<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto SIBE est\u00e1 orientado a satisfacer una necesidad actual, en Espa\u00f1a y en muchos pa\u00edses, tanto de Iberoam\u00e9rica como de otras regiones del mundo. Se trata de establecer rankings de publicaciones cient\u00edficas, en Econom\u00eda de la Empresa, en lengua espa\u00f1ola, basados en indicios de calidad, generalmente aceptados.<\/p><p>Es un proyecto complejo, que maneja varios campos del conocimiento, en el entorno de la Gesti\u00f3n del Conocimiento: bibliom\u00e9trico, bibliogr\u00e1fico, bases de datos relacionales, trabajo en red, inform\u00e1tica, comunicaciones en tiempo real, y otros. El proyecto ha ido evolucionando, desde antes del a\u00f1o 1995 en que comenz\u00f3, en la Universidad de Extremadura.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-sibe\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f90aba9 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f90aba9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f568b60 elementor-widget elementor-widget-text-editor\" data-id=\"f568b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-proyecto-sysgobex\/\">Proyecto SysGobEx<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El SysGobEx, incluido como proyecto dentro del Plan de reordenaci\u00f3n del Entorno tecnol\u00f3gico de la administraci\u00f3n regional (Plan RETO), es un documento t\u00e9cnico que ten\u00eda como objetivo, por un lado, conseguir una foto fija sobre el entorno tecnol\u00f3gico de la administraci\u00f3n; trazar los objetivos de desarrollo futuro que permita ir tomando las decisiones m\u00e1s oportunas de adaptaci\u00f3n y nuevas incorporaciones de soluciones tecnol\u00f3gicas para la Administraci\u00f3n de acuerdo con la evoluci\u00f3n del sector.<\/p><p>Aunque el documento aborda el estado actual y las perspectivas de futuro de la administraci\u00f3n p\u00fablica solamente, el\u00a0<a href=\"http:\/\/www.gobex.es\/web\/\">Gobierno de Extremadura<\/a>, en su apuesta por la transparencia y el fomento de la calidad empresarial, present\u00f3 el Plan estrat\u00e9gico a los empresarios y profesionales del sector para que tuvieran conocimiento de a d\u00f3nde se dirige la pol\u00edtica tecnol\u00f3gica de la Administraci\u00f3n regional.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-proyecto-sysgobex\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96e580c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"96e580c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8e06a2 elementor-widget elementor-widget-text-editor\" data-id=\"f8e06a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-proyecto-sede\/\">Proyecto SEDE<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La vigilancia estrat\u00e9gica en las empresas es una herramienta de gesti\u00f3n que proporciona, mediante el an\u00e1lisis temprano de la informaci\u00f3n, la capacidad de toma decisiones en un ecosistema empresarial global, teniendo en cuenta sus posibles futuros cambios de escenario.<\/p><p>El uso de la supercomputaci\u00f3n para la aplicaci\u00f3n en la Vigilancia Estrat\u00e9gica, la Inteligencia Competitiva y la Inteligencia de Negocio, a\u00f1ade las opciones de predictibilidad y permite la anticipaci\u00f3n en escenarios de variables muy numerosas y complejas, aportando ventajas competitivas de gran valor empresarial.<\/p><p><a href=\"http:\/\/www.cenits.es\/cenits\">C\u00e9nitS<\/a>\u00a0puso a disposici\u00f3n del proyecto SEDE sus recursos para desarrollar un sistema inform\u00e1tico automatizado y autoconfigurable, basado en la aplicaci\u00f3n de redes neuronales y l\u00f3gica difusa, capaz de medir y representar gr\u00e1ficamente la evoluci\u00f3n de los escenarios empresariales en los diversos entornos estrat\u00e9gicos.<\/p><p>La herramienta fue desarrollada por la empresa\u00a0<a href=\"http:\/\/www.setici.net\/\">SET Inform\u00e1tica, Comunicaci\u00f3n e Ingenier\u00eda<\/a>\u00a0ubicada en Extremadura e\u00a0<a href=\"http:\/\/www.infocenter.es\/\">INFOCENTER<\/a>.\u00a0<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-proyecto-sede\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0a93d0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d0a93d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b57f5f elementor-widget elementor-widget-text-editor\" data-id=\"2b57f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-medianell-virtual-press\/\">Medianell Virtual Press<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Potenciaci\u00f3n y Desarrollo Empresarial S.L. es una empresa de base tecnol\u00f3gica que tiene como objetivo comercializar la mercanc\u00eda m\u00e1s importante del siglo XXI: \u201clos contenidos\u201d.<\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Crear una central de gesti\u00f3n y generaci\u00f3n de contenidos digitales (bases de datos comunes), junto con una red de peri\u00f3dicos digitales que hagan uso de dicha central, y que los contenidos digitales que estos peri\u00f3dicos generan, referentes a su \u00e1mbito de actuaci\u00f3n, entren a su vez a formar parte de la central de contenidos.\u00a0<\/li><\/ul><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-medianell-virtual-press\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ac86a7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3ac86a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f638044 elementor-widget elementor-widget-text-editor\" data-id=\"f638044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-future-internet-eficiencia-en-las-redes-de-altas-prestaciones\/\">Future Internet: eficiencia en las redes de altas prestaciones<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"http:\/\/girtel.upct.es\/projects\/fierro\/\">FIERRO<\/a>\u00a0es una red tem\u00e1tica patrocinada por el\u00a0<a href=\"http:\/\/www.idi.mineco.gob.es\/portal\/site\/MICINN\/\">Ministerio de Ciencia e Innovaci\u00f3n<\/a>\u00a0y formada por 21 Grupos de investigaci\u00f3n de Universidades, Centros de Investigaci\u00f3n y Empresas espa\u00f1olas cuya finalidad consiste en estudiar las limitaciones actuales de las redes IP de altas prestaciones (redes de alta velocidad, metro y troncal) para dise\u00f1ar la Internet del Futuro.<\/p><p>Los retos principales surgen en todas las capas de red ante la esperada demanda de tr\u00e1fico en cuestiones de volumen, granularidad, variabilidad y movilidad, y la necesidad de construir un sistema escalable que soporte dicha demanda.<\/p><p>C\u00e9nitS es uno de los Centros Tecnol\u00f3gicos participantes que aporta su experiencia y sus recursos tecnol\u00f3gicos y humanos a la Red Tem\u00e1tica\u00a0<a href=\"http:\/\/girtel.upct.es\/projects\/fierro\/\">FIERRO<\/a>.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-future-internet-eficiencia-en-las-redes-de-altas-prestaciones\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70cb774 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"70cb774\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a137cf elementor-widget elementor-widget-text-editor\" data-id=\"8a137cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><a href=\"http:\/\/10.128.3.28\/proyecto-electromagnetismo-y-supercomputacion-para-nanoestructuras-plasmonicas-aplicacion-a-nanoantenas-opticas-y-metamateriales\/\"><span style=\"font-size: 14pt;\">Electromagnetismo y supercomputaci\u00f3n para nanoestructuras plasm\u00f3nicas. Aplicaci\u00f3n a nanoantenas \u00f3pticas y metamateriales<\/span><\/a><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Luis Landesa Porras, Jos\u00e9 Manuel Taboada Varela, Francisco Javier Rivero Campos, Luis Bote Curiel y Mario Fern\u00e1ndez Manzano<\/strong>.\u00a0<a href=\"http:\/\/tcc.unex.es\/\">Departamento de Computadores y de las Comunicaciones<\/a>\u00a0of the\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The unprecedented ability of nano metallic (that is plasmonic) structures to concentrate light into deep-subwavelength volumes has propelled their use in a vast array of nanophotonic technologies and research endeavors. The field of plasmonics has grown dramatically over the past decade and still continues growing towards new directions that are continuously emerging. With the ability to produce highly confined optical fields, the conventional rules for light-matter interactions need to be re-examined,and researchers are venturing into new formulations. We are presenting a project, with the primary objective of extending the scope of applications of exact integral-equation (IE) method of moments (MoM) formulations to the electromagnetic analysis of plasmonic nanostructures and artificial materials(metamaterials) in visible and near-infrared frequency bands.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-electromagnetismo-y-supercomputacion-para-nanoestructuras-plasmonicas-aplicacion-a-nanoantenas-opticas-y-metamateriales\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1efd9d8 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1efd9d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9821784 elementor-widget elementor-widget-text-editor\" data-id=\"9821784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-creacion-de-un-ecosistema-de-negocio-en-cloud-computing-gestion-automatizada-de-la-infraestructura\/\">Creaci\u00f3n de un ecosistema de negocio en cloud computing. Gesti\u00f3n automatizada de la infraestructura<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Emilio Jos\u00e9 Mu\u00f1oz Fern\u00e1ndez<\/strong>\u00a0and\u00a0<strong>Juan Francisco Rodr\u00edguez Cardoso<\/strong>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Investigaci\u00f3n exhaustiva sobre el paradigma de cloud computing y sus diferencias con el grid computing.<\/li><li>Estudio y asistencia a la preparaci\u00f3n de la infraestructura de cloud computing montada para la consecuci\u00f3n del proyecto.<\/li><li>Estudio te\u00f3rico y pr\u00e1ctico sobre el manejo de herramientas vanguardistas para la administraci\u00f3n de infraestructuras cloud y software ofrecido por HP.<\/li><li>Adquisici\u00f3n de experiencia en el seguimiento de las fases descritas por un ciclo de vida estructurado.<\/li><li>Investigaci\u00f3n y comparaci\u00f3n de las diferentes alternativas para la construcci\u00f3n del portal para el ecosistema de negocio.<\/li><li>Aprendizaje del manejo de herramientas que asisten el desarrollo de aplicaciones web.<\/li><li>Adquisici\u00f3n de experiencia en el manejo de sistemas gestores de bases de datos.<\/li><li>Introducci\u00f3n a conceptos que mejoran el producto final: generaci\u00f3n autom\u00e1tica de plantillas de servicios.<\/li><li>Construcci\u00f3n de un portal web que constituye el front-end del ecosistema de negocio cloud.<\/li><\/ul><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-creacion-de-un-ecosistema-de-negocio-en-cloud-computing-gestion-automatizada-de-la-infraestructura\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div><footer><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0a6d68 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d0a6d68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51fdc01 elementor-widget elementor-widget-text-editor\" data-id=\"51fdc01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-consumo-energetico-de-operaciones-colectivas-mpi-en-plataformas-multicores\/\">Consumo energ\u00e9tico de operaciones colectivas MPI en plataformas multicores<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>\u00c1lvaro Cort\u00e9s F\u00e1cila<\/strong>\u00a0and\u00a0<strong>Juan Carlos D\u00edaz Mart\u00edn<\/strong>\u00a0del grupo\u00a0<a href=\"https:\/\/gim.unex.es\/\">GIM<\/a>\u00a0(Grupo de Ingenier\u00eda de Medios) del DACC (Departamento de Arquitectura de Computadores y Comunicaciones) de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"form-item form-type-item\">\u00a0<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En los \u00faltimos a\u00f1os, el inter\u00e9s por el ahorro energ\u00e9tico se ha extendido, llegando incluso al \u00e1mbito de la computaci\u00f3n. Las aplicaciones que requieren paralelismo utilizan, habitualmente, una gran cantidad de nodos de computaci\u00f3n, recursos (memoria RAM) e incluso de dispositivos de comunicaci\u00f3n (buses internos, redes, etc). As\u00ed, ha surgido inter\u00e9s en estudiar c\u00f3mo optimizar el uso de los recursos, minimizando al mismo tiempo el impacto energ\u00e9tico de las aplicaciones.<\/p><p>MPI es el est\u00e1ndar de comunicaci\u00f3n en la programaci\u00f3n paralela en supercomputadores. Del conjunto de operaciones disponibles en MPI, el de operaciones colectivas es el m\u00e1s utilizado por las aplicaciones cient\u00edficas. Por lo tanto, una buena estrategia para aumentar el rendimiento de las aplicaciones cient\u00edficas es mejorar las prestaciones de dichas operaciones. Lo mismo ocurre con el consumo energ\u00e9tico asociado a una cierta aplicaci\u00f3n. Para cada operaci\u00f3n colectiva de MPI, existen varios esquemas de implementaci\u00f3n. El objetivo del proyecto es determinar qu\u00e9 esquemas de implementaci\u00f3n de dichas operaciones <a href=\"http:\/\/10.128.3.28\/proyecto-consumo-energetico-de-operaciones-colectivas-mpi-en-plataformas-multicores\/\">son m\u00e1s eficientes energ\u00e9ticamente en una m\u00e1quina multicore.<\/a><\/p><p>Leer m\u00e1s<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dab092 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6dab092\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-552a49a elementor-widget elementor-widget-text-editor\" data-id=\"552a49a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-alojamiento-de-plataformas-virtuales-y-webtv-aldealab-c3\/\">Alojamiento de plataformas virtuales y WebTV (Aldealab c3)<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El Centro de Conocimiento de C\u00e1ceres\u00a0<a href=\"http:\/\/www.factorinnovation.eu\/es\/aldealab\">AldeaLab C3<\/a>\u00a0surge como espacio f\u00edsico y virtual de innovaci\u00f3n especializado en tecnolog\u00edas y medios de difusi\u00f3n, con el fin de impulsar las iniciativas creativas, culturales y de conocimiento a trav\u00e9s de soportes audiovisuales y multimedia en la ciudad de C\u00e1ceres.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-alojamiento-de-plataformas-virtuales-y-webtv-aldealab-c3\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21ed93c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"21ed93c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-883eda1 elementor-widget elementor-widget-text-editor\" data-id=\"883eda1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-analisis-de-imagenes-en-profundidad-en-terapias-de-rehabilitacion-supervisadas-por-robots-autonomos\/\">An\u00e1lisis de im\u00e1genes en profundidad en terapias de rehabilitaci\u00f3n supervisadas por robots aut\u00f3nomos<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Eva Mar\u00eda M\u00f3gena Cisneros, C\u00e9nitS-COMPUTAEX. Trabajo Final de M\u00e1ster en Ingenier\u00eda de Telecomunicaci\u00f3n, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>En un futuro cercano la interacci\u00f3n y el contacto entre humanos y robots se transformar\u00e1n en algo cotidiano. Pero, antes de alcanzar dicho futuro, es imprescindible la realizaci\u00f3n de investigaciones que permitan establecer y dise\u00f1ar algoritmos de tal modo que los robots puedan realizar tareas de forma completamente aut\u00f3noma. Entre estas tareas, destacan aquellas orientadas a la mejora de la salud de las personas como es el caso de liderar terapias de recuperaci\u00f3n f\u00edsica.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-analisis-de-imagenes-en-profundidad-en-terapias-de-rehabilitacion-supervisadas-por-robots-autonomos\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46770a5 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"46770a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-341c581 elementor-widget elementor-widget-text-editor\" data-id=\"341c581\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-software-sensor-for-smart-infrastructures-s4i\/\">Software Sensor for Smart Infrastructures (S4i)<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.setici.net\/\" target=\"_blank\" rel=\"noopener\">Set Inform\u00e1tica, Comunicaciones e Ingenier\u00eda S.L.<\/a>,\u00a0<a href=\"http:\/\/www.ohl.es\/\" target=\"_blank\" rel=\"noopener\">Grupo OHL: Obrascon Huarte Lain S.A.<\/a>,\u00a0<a href=\"http:\/\/www.auditoriza.com\/\">Auditoriza Diagn\u00f3stico de\u00a0Sistemas S.L.P.<\/a>,\u00a0<a href=\"http:\/\/www.unex.es\/investigacion\/grupos\/hypercomp\" target=\"_blank\" rel=\"noopener\">grupo Hypercomp (Universidad de Extremadura)<\/a>,\u00a0<a href=\"https:\/\/computaex.eu\/cenits\" target=\"_blank\" rel=\"noopener\">C\u00e9nitS<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto se\u00a0sit\u00faa en el contexto de la correcta gesti\u00f3n de las infraestructuras de construcci\u00f3n mediante la\u00a0utilizaci\u00f3n de sistemas de monitorizaci\u00f3n y telemetr\u00eda sofisticados, capaces de evaluar el estado de\u00a0salud estructural de las infraestructuras de forma continuada durante toda su vida \u00fatil.\u00a0Este proyecto ha propuesto el desarrollo de un sistema basado en el concepto de Software Sensor, que\u00a0analiza y optimiza las operaciones de construcci\u00f3n, gesti\u00f3n, explotaci\u00f3n y mantenimiento,\u00a0durante todo el ciclo de vida de una infraestructura, aportando informaci\u00f3n que permite\u00a0desplegar diferentes estrategias, con el fin de alargar su vida \u00fatil y garantizar su seguridad durante\u00a0el tiempo que ofrezca servicio.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-software-sensor-for-smart-infrastructures-s4i\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-502fb9d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"502fb9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c69bc elementor-widget elementor-widget-text-editor\" data-id=\"a8c69bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-software-sensor-for-smart-infrastructures-s4i\/\">Software Sensor for Smart Infrastructures (S4i)<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.setici.net\/\" target=\"_blank\" rel=\"noopener\">Set Inform\u00e1tica, Comunicaciones e Ingenier\u00eda S.L.<\/a>,\u00a0<a href=\"http:\/\/www.ohl.es\/\" target=\"_blank\" rel=\"noopener\">Grupo OHL: Obrascon Huarte Lain S.A.<\/a>,\u00a0<a href=\"http:\/\/www.auditoriza.com\/\">Auditoriza Diagn\u00f3stico de\u00a0Sistemas S.L.P.<\/a>,\u00a0<a href=\"http:\/\/www.unex.es\/investigacion\/grupos\/hypercomp\" target=\"_blank\" rel=\"noopener\">grupo Hypercomp (University_of Extremadura)<\/a>,\u00a0<a href=\"https:\/\/computaex.eu\/cenits\" target=\"_blank\" rel=\"noopener\">C\u00e9nitS<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The main objective of the project is the correct management of the construction infrastructures by means of the use of sophisticated monitoring and telemetry systems, which are able to continuously\u00a0evaluate the structural health status of the infrastructures throughout his useful life. This project has proposed the development of a system based on the Sensor Software concept, which analyzes and optimizes the construction, management, operation and maintenance operations throughout the life cycle of an infrastructure, providing information that allows different strategies to be deployed, in order to prolong its useful life and guarantee its safety while offering service.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-software-sensor-for-smart-infrastructures-s4i\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5a581a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"c5a581a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c4f4c elementor-widget elementor-widget-text-editor\" data-id=\"b5c4f4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-investigacion-para-la-obtencion-de-una-nueva-metodologia-y-un-prototipo-tic-para-el-tratamiento-y-procesamiento-de-reclamaciones-de-servicios-de-telecomunicaciones-inretel\/\">Investigaci\u00f3n para la obtenci\u00f3n de una nueva metodolog\u00eda y un prototipo TIC para el tratamiento y procesamiento de reclamaciones de servicios de telecomunicaciones (INRETEL)<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/trecone.com\/\" target=\"_blank\" rel=\"noopener\">Trecone<\/a>,\u00a0<a href=\"http:\/\/areaabogados.com\/\">Grupo\u00a0\u00c1rea de Derecho S.L.P<\/a>,\u00a0<a href=\"http:\/\/www.solucionex.com\/\" target=\"_blank\" rel=\"noopener\">Solucionex Consultor\u00eda y Desarrollo S.L<\/a>.,\u00a0<a href=\"http:\/\/www.ceta-ciemat.es\/\" target=\"_blank\" rel=\"noopener\">Ceta-Ciemat<\/a>,\u00a0<a href=\"http:\/\/www.feval.com\/\" target=\"_blank\" rel=\"noopener\">Feval<\/a>,\u00a0<a href=\"https:\/\/computaex.eu\/%20cenits\" target=\"_blank\" rel=\"noopener\">C\u00e9nitS<\/a>,\u00a0<a href=\"http:\/\/www.ucex.org\/\" target=\"_blank\" rel=\"noopener\">Uni\u00f3n de Consumidores de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto surgi\u00f3 para investigar c\u00f3mo se ejecutan los procesos de\u00a0reclamaci\u00f3n actuales, y cu\u00e1les son los tipos de incidencias m\u00e1s comunes, a trav\u00e9s del an\u00e1lisis\u00a0masivo de usuarios de telecomunicaciones mediante t\u00e9cnicas de Big Data, con el fin de aportar nuevos\u00a0m\u00e9todos y procesos que faciliten la gesti\u00f3n de las reclamaciones a los consumidores.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-investigacion-para-la-obtencion-de-una-nueva-metodologia-y-un-prototipo-tic-para-el-tratamiento-y-procesamiento-de-reclamaciones-de-servicios-de-telecomunicaciones-inretel\/\">Leer m\u00e1s<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-792e14d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"792e14d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f617bd elementor-widget elementor-widget-text-editor\" data-id=\"5f617bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estirpex-2\/\">Estirpex-2<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\" target=\"_blank\" rel=\"noopener\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/estirpex-2_1.png\" alt=\"\" width=\"347\" height=\"380\" \/><\/p><p>El proyecto\u00a0<a href=\"\/en\/proyecto-estirpex\/\" target=\"_blank\" rel=\"noopener\">Estirpex\u00a0<\/a>supuso el despliegue de software libre en la infraestructura de\u00a0<a href=\"\/en\/lusitania\/\">LUSITANIA<\/a>, para procesar la\u00a0secuencia gen\u00e9tica de determinados exomas, almacenar la\u00a0informaci\u00f3n generada y filtrar y visualizar los resultados\u00a0obtenidos; pero tambi\u00e9n, la apertura de una serie de l\u00edneas\u00a0de trabajo destinadas a la optimizaci\u00f3n de los procesos de\u00a0obtenci\u00f3n de informaci\u00f3n de alto nivel, relacionada con los\u00a0estudios de secuenciaci\u00f3n masiva realizados.<\/p><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-estirpex-2\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b929e2 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3b929e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2f0534 elementor-widget elementor-widget-text-editor\" data-id=\"f2f0534\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estirpex-2\/\">Estirpex-2<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/10.128.3.28\/descripcion-cenits\/\" target=\"_blank\" rel=\"noopener\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/estirpex-2_1.png\" alt=\"\" width=\"347\" height=\"380\" \/><\/p><p>The\u00a0<a href=\"\/en\/proyecto-estirpex\/\">Estirpex<\/a>\u00a0project involved the deployment of free software in the infrastructure of\u00a0<a href=\"\/en\/lusitania\/\">LUSITANIA<\/a>, to process the genetic sequence of certain exomes, store the information generated and filter and visualize the results obtained; but also, the opening of a series of lines of work aimed at optimizing the processes of obtaining high-level information, related to the massive sequencing studies carried out.<\/p><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estirpex-2\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a9c716 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1a9c716\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2f4367 elementor-widget elementor-widget-text-editor\" data-id=\"d2f4367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital\/\">CENITAL<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/10.128.3.28\/descripcion-cenits\/\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto CENITAL naci\u00f3 en 2013 para dar respuesta a varios objetivos de la Fundaci\u00f3n COMPUTAEX, estando centrado especialmente en aspectos emergentes de las tecnolog\u00edas m\u00e1s avanzadas en materia de c\u00f3mputo y comunicaciones.\u00a0<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-cenital\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-683a3b3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"683a3b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bc789a elementor-widget elementor-widget-text-editor\" data-id=\"0bc789a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-redes-inalambricas-mimo-de-ultima-generacion-en-zonas-rurales\/\">Redes inal\u00e1mbricas MIMO de \u00faltima generaci\u00f3n en zonas rurales<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Investigador principal:\u00a0<strong>Rafael Marcos Luque Baena<\/strong>. Universidad de Extremadura. Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos.<\/li><li>Juan F. Valenzuela Vald\u00e9s.\u00a0<\/li><li>Francisco Luna Valero.<\/li><li>Victoriano Hern\u00e1ndez Cham.<\/li><li>Juan Carlos Gonz\u00e1lez Mac\u00edas.<\/li><li>Luis Ar\u00e9valo Rosado.<\/li><li>Juan \u00c1ngel Garc\u00eda.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Los sistemas inal\u00e1mbricos que plantean m\u00faltiples entradas y m\u00faltiples\u00a0salidas de la se\u00f1al (MIMO),\u00a0se basan en convertir la propagaci\u00f3n\u00a0multicamino, inicialmente considerada un problema, en la soluci\u00f3n a las\u00a0limitadas capacidades de transmisi\u00f3n, al posibilitar el empleo de canales de\u00a0transmisi\u00f3n en paralelo mediante el aumento del n\u00famero de antenas de transmisi\u00f3n y\/o\u00a0recepci\u00f3n. Al existir una creciente demanda de velocidades de transmisi\u00f3n\u00a0en comunicaciones m\u00f3viles, estos sistemas han recibido una tremenda\u00a0atenci\u00f3n cient\u00edfica en los \u00faltimos a\u00f1os, precisamente porque las primeras\u00a0formulaciones erg\u00f3dicas preve\u00edan incrementos de las capacidades que eran\u00a0linealmente proporcionales al n\u00famero de antenas empleadas, lo que provocaba\u00a0eficiencias espectrales inauditas y de enorme impacto potencial. Sin embargo,\u00a0el incre\u00edble n\u00famero de publicaciones cient\u00edficas sobre MIMO que se\u00a0observan en los \u00faltimos a\u00f1os ha ido mejorando el conocimiento de estos\u00a0sistemas, que se han revelado recientemente como bastante m\u00e1s complejos de\u00a0lo que en principio podr\u00eda parecer.\u00a0<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-redes-inalambricas-mimo-de-ultima-generacion-en-zonas-rurales\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9299d87 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9299d87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4311024 elementor-widget elementor-widget-text-editor\" data-id=\"4311024\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estudio-y-evaluacion-de-los-mecanismos-de-gestion-de-la-movilidad-en-redes-de-proxima-generacion\/\">Estudio y evaluaci\u00f3n de los mecanismos de gesti\u00f3n de la movilidad en redes de pr\u00f3xima generaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Jes\u00fas Calle Cancho, C\u00e9nitS-COMPUTAEX. Trabajo Final de M\u00e1ster en Ingenier\u00eda Inform\u00e1tica, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>With the continuous development of mobile communications and Internet technology, one of the major challenges is to achieve e_cient mobility management in wireless networks.IP mobility management is a key function that allows mobile nodes to continue their communications even when their point of attachment to the IP network changes. Internet protocols do not support mobility and wireless networking does not provide reliable connections to mobile users for real-time communications.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-estudio-y-evaluacion-de-los-mecanismos-de-gestion-de-la-movilidad-en-redes-de-proxima-generacion\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-600fb50 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"600fb50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ef28bd elementor-widget elementor-widget-text-editor\" data-id=\"5ef28bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-calculos-de-eficiencia-condicionada-con-datos-internacionales\/\">C\u00e1lculos de eficiencia condicionada con datos internacionales<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Jos\u00e9 Manuel Cordero Ferrera<\/strong>. Departamento de Econom\u00eda.\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El prop\u00f3sito de la investigaci\u00f3n consiste en la estimaci\u00f3n de \u00edndices de eficiencia condicionada a partir de una muestra de 32.000 observaciones pertenecientes a distintos pa\u00edses.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-calculos-de-eficiencia-condicionada-con-datos-internacionales\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a549bd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1a549bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74e2481 elementor-widget elementor-widget-text-editor\" data-id=\"74e2481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mecanismos-para-la-distribucion-de-contenidos-a-traves-de-redes-moviles\/\">Mecanismos para la distribuci\u00f3n de contenidos a trav\u00e9s de redes m\u00f3viles<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.unex.es\/conoce-la-uex\/estructura-academica\/departamentos\/ficha_personal?idDpto=Y056&amp;personal=1&amp;idPersonal=C158256A2BBF375A0552477A2B814A41\">Javier Carmona Murillo<\/a>.\u00a0<a href=\"http:\/\/www.unex.es\/conoce-la-uex\/estructura-academica\/departamentos\/ficha_estructura?idDpto=Y056&amp;estructura=1\">Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos<\/a>.\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La distribuci\u00f3n eficiente del tr\u00e1fico de v\u00eddeo en Internet es uno de los principales retos en el \u00e1mbito de las tecnolog\u00edas de la informaci\u00f3n y las comunicaciones. Se prev\u00e9 que este tipo de tr\u00e1fico suponga cerca de un 90 por ciento del tr\u00e1fico de los consumidores para 2017 y que las CDNs (Content Delivery Networks) transporten casi dos terceras partes de este tr\u00e1fico multimedia en ese a\u00f1o. Adem\u00e1s, gran parte de este tr\u00e1fico de v\u00eddeo va a ser generado o consumido por dispositivos m\u00f3viles, en concreto, hasta 2017 este tipo de tr\u00e1fico va a incrementarse en 16 veces llegando a ser el 61% del total de datos m\u00f3viles.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-mecanismos-para-la-distribucion-de-contenidos-a-traves-de-redes-moviles\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dffa54c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"dffa54c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1d0018 elementor-widget elementor-widget-text-editor\" data-id=\"f1d0018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"http:\/\/10.128.3.28\/proyecto-optimizacion-de-la-red-de-acceso-conmutada-para-provision-de-qos-a-dispositivos-moviles-mediante-programacion-lineal\/\">Optimizaci\u00f3n de la red de acceso conmutada para provisi\u00f3n de QoS a dispositivos m\u00f3viles mediante programaci\u00f3n lineal<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>David Miguel Cort\u00e9s Polo, C\u00e9nitS-COMPUTAEX. Trabajo Final de M\u00e1ster Universitario en Investigaci\u00f3n, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La gesti\u00f3n del movimiento y la calidad de servicio (QoS) son dos de los puntos claves en el desarrollo tanto presente como futuro de las redes inal\u00e1mbricas. Estas tareas no s\u00f3lo involucran al dominio de la red inal\u00e1mbrica sino que la red de acceso que interconecta los nodos m\u00f3viles con Internet tambi\u00e9n tiene capacidad para mejorar las comunicaciones. Este campo de investigaci\u00f3n es conocido como Convergencia Fija-M\u00f3vil (FMC). El objetivo de esta convergencia es la integraci\u00f3n y la creaci\u00f3n de una infraestructura unificada de las redes cableadas e inal\u00e1mbricas. En esta infraestructura convergente, los usuarios pueden moverse y saltar de una red a otra sin interrupci\u00f3n. En este Trabajo Final de M\u00e1ster, se ha presentado un estudio de los avances recientes y campos de investigaci\u00f3n abiertos en los protocolos de movilidad en conjunci\u00f3n con redes de acceso basadas en MPLS (Multi-Protocol Label Switching), los cuales se plantean ser integrados en una \u00fanica arquitectura como infraestructura convergente. Tambi\u00e9n se describe una nueva aproximaci\u00f3n para optimizar los recursos de la red de acceso. Este algoritmo de optimizaci\u00f3n permite organizar los nodos m\u00f3viles que van a permanecer est\u00e1ticos durante largos periodos de tiempo y planificar el resto de la red de acceso para atender las peticiones del resto de nodos m\u00f3viles que se est\u00e1n moviendo. Para ello se han usado trazas de movimientos de usuarios reales analizando un periodo de diez horas.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"http:\/\/10.128.3.28\/proyecto-optimizacion-de-la-red-de-acceso-conmutada-para-provision-de-qos-a-dispositivos-moviles-mediante-programacion-lineal\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d332268 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d332268\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e74b1c elementor-widget elementor-widget-text-editor\" data-id=\"8e74b1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-estirpex\/\">Estirpex<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Los avances en investigaci\u00f3n en el \u00e1mbito sanitario han sido siempre uno de los principales retos de la humanidad. Uno de los hallazgos m\u00e1s importantes ha sido determinar que el estudio de la secuencia de ADN permite conocer los procesos biol\u00f3gicos fundamentales del organismo y su funcionamiento. Hasta hace escasos a\u00f1os, secuenciar el ADN ten\u00eda un elevado coste econ\u00f3mico y temporal. Ante estos problemas, surgen las tecnolog\u00edas NGS, y con ellas un nuevo paradigma de secuenciaci\u00f3n gen\u00e9tica que permite la secuenciaci\u00f3n del genoma o de secciones de \u00e9ste a gran escala, con una importante disminuci\u00f3n del tiempo y del coste del proceso.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-estirpex\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac54c1d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ac54c1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea95193 elementor-widget elementor-widget-text-editor\" data-id=\"ea95193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-eco-trafic\/\">Eco-Trafic<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El desarrollo sostenible se define normalmente como el que solventa las necesidades del presente sin comprometer las capacidades de las generaciones futuras para satisfacer sus propias necesidades. En este desarrollo, uno de los pilares es el transporte sostenible, es decir, la capacidad de satisfacer la demanda del transporte actual sin comprometer la capacidad de satisfacer las necesidades de futuras generaciones.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-eco-trafic\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae9a2aa e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ae9a2aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46e9e2f elementor-widget elementor-widget-text-editor\" data-id=\"46e9e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-fi4vdi-desarrollo-de-una-red-de-infraestructuras-federadas-para-la-generacion-de-servicios-de-virtualizacion-de-puestos-de-trabajo\/\">FI4VDI &#8211; Desarrollo de una Red de Infraestructuras Federadas para la Generaci\u00f3n de Servicios de Virtualizaci\u00f3n de Puestos de Trabajo<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.fcsc.es\/\">FCSCL<\/a>,\u00a0<a href=\"\/en\/\">COMPUTAEX<\/a>,\u00a0<a href=\"http:\/\/www.udl.es\/\">UDL<\/a>,\u00a0<a href=\"http:\/\/www.univ-montp2.fr\/\">Universit\u00e9 Montpellier 2<\/a>,\u00a0<a href=\"http:\/\/www.inova-ria.pt\/\">Inova-ria<\/a>\u00a0and\u00a0<a href=\"http:\/\/www.pcital.com\/\">Consorcio PCiTAL<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/fi4vdi_1.jpg\" alt=\"\" \/><\/p><p>Las TIC son herramientas de trabajo imprescindibles en el \u00e1mbito empresarial y acad\u00e9mico, tanto privado como p\u00fablico. Se ha detectado que el acceso a la Sociedad de la informaci\u00f3n en las Regiones\u00a0<a href=\"http:\/\/www.interreg-sudoe.eu\/inicio\">SUDOE<\/a>\u00a0es todav\u00eda inferior al necesario para permitir una mejora de los sistemas de producci\u00f3n y de gesti\u00f3n en el sector empresarial y un aumento en la calidad y la excelencia en el acad\u00e9mico. El acceso a las TIC se ha concebido siempre a trav\u00e9s de puestos de trabajo f\u00edsicos mediante la utilizaci\u00f3n de hardware individualizado por parte de cada uno de los usuarios.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-fi4vdi-desarrollo-de-una-red-de-infraestructuras-federadas-para-la-generacion-de-servicios-de-virtualizacion-de-puestos-de-trabajo\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ebef5fd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ebef5fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ebe03 elementor-widget elementor-widget-text-editor\" data-id=\"f5ebe03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-taxonomtic\/\">TaxonomTIC<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Equipo de\u00a0<a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Las Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n (TIC) se han transformado en la herramienta de desarrollo m\u00e1s importante del siglo XXI. El conjunto de empresas y profesionales que proveen dichas tecnolog\u00edas se posicionan como un sector importante en el presente y fundamental para el futuro. La correcta identificaci\u00f3n de las empresas TIC en Extremadura y un estudio de la evoluci\u00f3n e influencia econ\u00f3mica del sector en la regi\u00f3n, constituyen una herramienta valiosa para una adecuada toma de decisiones que potencie y fortalezca el futuro del mismo.<\/p><p>Desde el punto de vista tecnol\u00f3gico y de la innovaci\u00f3n, hist\u00f3ricamente se ha percibido a Ext<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-taxonomtic\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2321e39 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2321e39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e735a59 elementor-widget elementor-widget-text-editor\" data-id=\"e735a59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-green-code\/\">Green Code<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La mejora de la eficiencia energ\u00e9tica en los dispositivos electr\u00f3nicos modernos se ha convertido en un tema recurrente que se aborda tanto en componentes hardware como software. Las optimizaciones en el hardware se logran a trav\u00e9s del dise\u00f1o de circuitos m\u00e1s eficientes y en el software se suelen implementar en el sistema operativo, utilizando distintas t\u00e9cnicas de planificaci\u00f3n que analizan los procesos activos en t\u00e9rminos energ\u00e9ticos mediante green compilers y el c\u00f3digo en tiempo de compilaci\u00f3n.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-green-code\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27ecbcd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"27ecbcd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f34d32 elementor-widget elementor-widget-text-editor\" data-id=\"0f34d32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-sgdc-smart-green-data-center\/\">SGDC &#8211; Smart Green Data Center<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.grupocobra.com\/\">COBRA INSTALACIONES Y SERVICIOS, S. A.<\/a>,\u00a0<a href=\"http:\/\/www.aselcom.com\/\">ASELCOM<\/a>,\u00a0<a href=\"http:\/\/www.teknicam.com\/\">TEKNICAM<\/a>,\u00a0<a href=\"http:\/\/www.setici.net\/\">SET i.c.i<\/a>,\u00a0<a href=\"\/en\/descripcion-cenits\/\">C\u00e9nitS<\/a>,\u00a0<a href=\"http:\/\/www.cetiex.es\/\">CETIEX<\/a>,\u00a0<a href=\"http:\/\/www.intromac.com\/\">INTROMAC<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/smartgreendatacenter.jpeg\" alt=\"\" width=\"443\" height=\"295\" \/><\/p><p>Hoy en d\u00eda, los Datacenters o\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Centro_de_procesamiento_de_datos\">Centros de Proceso de Datos<\/a>\u00a0(CPD) se han convertido en elementos indispensables para el uso cotidiano de las nuevas tecnolog\u00edas y los servicios que se despliegan sobre ellas.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-sgdc-smart-green-data-center\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c55dc0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3c55dc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df98ade elementor-widget elementor-widget-text-editor\" data-id=\"df98ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-mittic-modernizacion-e-innovacion-tecnologica-con-base-tic-en-sectores-estrategicos-y-tradicionales\/\">MITTIC &#8211; Modernizaci\u00f3n e Innovaci\u00f3n Tecnol\u00f3gica con base TIC en sectores estrat\u00e9gicos y tradicionales<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\">Researchers:\u00a0<\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.gobex.es\/\">GobEx<\/a>,\u00a0<a href=\"http:\/\/iprocor.gobex.es\/\">ICMC<\/a>,\u00a0<a href=\"http:\/\/www.intromac.com\/\">INTROMAC<\/a>,\u00a0<a href=\"http:\/\/www.ccmijesususon.com\/\">CCMIJU<\/a>,\u00a0<a href=\"http:\/\/www.feval.com\/\">FEVAL<\/a>,\u00a0<a href=\"https:\/\/computaex.eu\/fundacion\">COMPUTAEX<\/a>,\u00a0<a href=\"http:\/\/www.fundecyt.es\/\">FUNDECYT-PCTEX<\/a>,\u00a0<a href=\"http:\/\/www.ctaex.com\/\">CTAEX<\/a>,\u00a0<a href=\"http:\/\/www.uevora.pt\/\">Universidade de \u00c9vora<\/a>,\u00a0<a href=\"https:\/\/www.ipp.pt\/\">IPP<\/a>,\u00a0<a href=\"http:\/\/www.cebal.pt\/index.php\/en\/\">CEBAL<\/a>,\u00a0<a href=\"http:\/\/cevalor.pt\/\">CEVALOR<\/a>,\u00a0<a href=\"http:\/\/www.ipportalegre.pt\/html1\/home.aspx\">ADR-IPP<\/a>,\u00a0<a href=\"http:\/\/www.cataa.pt\/\">CATAA<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"form-item form-type-item\"><label>Idioma<\/label>Sin definir<\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\">Description:\u00a0<\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/mittic_1.jpg\" alt=\"\" \/><\/p><p>El proyecto MITTIC, Modernizaci\u00f3n e Innovaci\u00f3n tecnol\u00f3gica con base TIC en sectores estrat\u00e9gicos y tradicionales, surge de la necesidad de generar crecimiento econ\u00f3mico y empleo mediante el aumento de la competitividad en sectores tradicionales y estrat\u00e9gicos de la regi\u00f3n Extremadura-Centro-Alentejo; proponiendo e implementando modelos y procesos innovadores de organizaci\u00f3n y producci\u00f3n, basados en la aplicaci\u00f3n de Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-mittic-modernizacion-e-innovacion-tecnologica-con-base-tic-en-sectores-estrategicos-y-tradicionales\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a9226e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2a9226e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b98f043 elementor-widget elementor-widget-text-editor\" data-id=\"b98f043\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-unidad-interactiva-3d\/\">Unidad Interactiva 3D<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Dr. Jes\u00fas Us\u00f3n Gargallo<\/strong>\u00a0&#8211; Coordinador de proyecto.<\/li><li>Personal de las Unidades de Laparoscopia, Microcirug\u00eda, Terapia Celular, etc.<\/li><li><strong>Mario Su\u00e1rez<\/strong>\u00a0&#8211; Especialista en Dise\u00f1o y Animaci\u00f3n 3D.<\/li><li><strong>Daniel Peguero<\/strong>\u00a0&#8211; Especialista en Software.<\/li><li><strong>Pablo Garc\u00eda Tres Palacios<\/strong>\u00a0&#8211; Profesional de Marketing.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El proyecto contempla la creaci\u00f3n de una unidad especializada en aplicaciones multimedia dirigida a un mercado constituido por los profesionales sanitarios que se forman en el\u00a0<a href=\"http:\/\/www.ccmijesususon.com\/\">CCMIJU<\/a>, as\u00ed como usuarios y pacientes que puedan ser objeto de las t\u00e9cnicas que se describen y miembros de la sociedad en general, que tengan inter\u00e9s en conocer de una forma sencilla el procedimiento a seguir en el tratamiento intervencionista en una patolog\u00eda dada.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-unidad-interactiva-3d\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49a0382 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"49a0382\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6828a8c elementor-widget elementor-widget-text-editor\" data-id=\"6828a8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-siatdeco-sistema-de-informacion-para-la-ayuda-a-la-toma-de-decisiones-en-energias-ecologicas\/\">SIATDECO: Sistema de Informaci\u00f3n para la Ayuda a la Toma de Decisiones en Energ\u00edas Ecol\u00f3gicas<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/iprocor.gobex.es\/\">ICMC<\/a>,\u00a0<a href=\"http:\/\/www.cetiex.es\/\">CETIEX<\/a>,\u00a0<a href=\"http:\/\/www.fundecyt.es\/\">FUNDECYT<\/a>\u00a0and\u00a0<a href=\"https:\/\/computaex.eu\/cenits\">C\u00e9nitS<\/a>\u00a0(coordinador del proyecto).<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p class=\"rtecenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/computaex.eu\/sites\/cenits.es\/files\/proyectos\/siatdeco_1.png\" alt=\"\" width=\"435\" height=\"252\" \/><\/p><p>Quiz\u00e1s las fuentes de energ\u00eda ecol\u00f3gicas m\u00e1s representativas son la hidr\u00e1ulica, la solar, la e\u00f3lica y la biomasa. Todas ellas est\u00e1n ofreciendo muy buenos resultados en cuanto a su productividad y, aunque algunas encuentran una cierta contestaci\u00f3n popular en relaci\u00f3n a su impacto medioambiental y est\u00e9tico, representan, sin lugar a dudas, la mejor alternativa a las energ\u00edas tradicionales.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-siatdeco-sistema-de-informacion-para-la-ayuda-a-la-toma-de-decisiones-en-energias-ecologicas\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cad2014 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cad2014\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-937c58f elementor-widget elementor-widget-text-editor\" data-id=\"937c58f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-metodologia-y-framework-para-el-desarrollo-de-aplicaciones-cientificas-en-entornos-hpc\/\">Metodolog\u00eda y Framework para el Desarrollo de Aplicaciones Cient\u00edficas en Entornos HPC<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Javier Corral Garc\u00eda, C\u00e9nitS-COMPUTAEX. Diploma de Estudios Avanzados, Universidad de Extremadura.<\/p><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>Se trata de un proyecto ambicioso de complejidad muy notable, con una propuesta trabajada desde un marco te\u00f3rico y publicada en diversos art\u00edculos en congresos de \u00e1mbito internacional. Dicha propuesta pretende cubrir las necesidades detectadas y aportar nuevas soluciones sobre los desaf\u00edos abiertos en la computaci\u00f3n de alto rendimiento, mediante la creaci\u00f3n de una metodolog\u00eda y un framework basados en componentes y orientados a aspectos, para el desarrollo de aplicaciones cient\u00edficas en entornos de computaci\u00f3n de alto rendimiento, HPC (High-Performance Computing). El objetivo es permitir a investigadores y usuarios generar sus programas de manera m\u00e1s eficiente, con mayor confianza en su funcionalidad y alcanzando destacables reducciones de tiempo, esfuero y coste, mediante la reutilizaci\u00f3n de componentes con c\u00f3digos paralelos ya desarrollados y probados previamente.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-metodologia-y-framework-para-el-desarrollo-de-aplicaciones-cientificas-en-entornos-hpc\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a4979d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1a4979d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b55d2 elementor-widget elementor-widget-text-editor\" data-id=\"c8b55d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-implementacion-del-modelo-cloud-computing-en-un-centro-de-supercomputacion\/\">Implementaci\u00f3n del modelo cloud computing en un centro de supercomputaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Jaime Rivero Ramos. Trabajo Final de M\u00e1ster en Direcci\u00f3n TIC, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>El cloud computing se ha convertido en uno de los principales ejes de la investigaci\u00f3n y la innovaci\u00f3n en el sector de las TIC en los \u00faltimos a\u00f1os; el impacto generado por este modelo de servicio es comparable \u00fanicamente a la revoluci\u00f3n generada por la llegada de internet durante los a\u00f1os 90. En C\u00e9nitS surge la necesidad de investigar este nuevo paradigma, analizar el modelo de negocio y valorar la posibilidad de incorporarlo dentro de su cat\u00e1logo de servicios.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-implementacion-del-modelo-cloud-computing-en-un-centro-de-supercomputacion\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bda37bf e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"bda37bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd0395 elementor-widget elementor-widget-text-editor\" data-id=\"ccd0395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-sistema-de-vigilancia-tecnologica-para-un-centro-de-supercomputacion\/\">Sistema de vigilancia tecnol\u00f3gica para un centro de supercomputaci\u00f3n<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Javier L\u00e1zaro Jare\u00f1o, C\u00e9nitS-COMPUTAEX. Trabajo Final de M\u00e1ster en Direcci\u00f3n TIC, Universidad de Extremadura.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>La investigaci\u00f3n, el desarrollo tecnol\u00f3gico y la innovaci\u00f3n son factores cr\u00edticos en las organizaciones a la hora de determinar su crecimiento econ\u00f3mico, nivel de bienestar y competitividad internacional. La normalizaci\u00f3n y certificaci\u00f3n de estas actividades\u00a0aportan calidad a los procesos productivos, generando mayor confianza en los clientes y mejores productos y servicios. En este trabajo fin de m\u00e1ster se presenta una peque\u00f1a introducci\u00f3n enfocada a comprender qu\u00e9 es un sistema de vigilancia tecnol\u00f3gica, c\u00f3mo debe implementarse e implantarse en una organizaci\u00f3n para que sea eficaz y los distintos procesos que un sistema de vigilancia tecnol\u00f3gica debe incluir.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-sistema-de-vigilancia-tecnologica-para-un-centro-de-supercomputacion\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9721e2b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9721e2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5cbbb elementor-widget elementor-widget-text-editor\" data-id=\"6a5cbbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-engage-banda-ancha-de-alta-velocidad-en-zonas-rurales\/\">ENGAGE: Banda ancha de alta velocidad en zonas rurales<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The\u00a0<a title=\"Estrategia Europa 2020\" href=\"http:\/\/ec.europa.eu\/europe2020\/index_es.htm\">Estrategia Europa 2020<\/a>\u00a0resalt\u00f3 el objetivo de llevar banda ancha b\u00e1sica a todos los europeos para el a\u00f1o 2013 y pretende garantizar que, en 2020, todos los europeos tengan acceso a Internet a mucha mayor velocidad, por encima de 30 Mbps y que el 50% o m\u00e1s de los hogares europeos tenga una suscripci\u00f3n a conexiones de Internet por encima de 100 Mbps.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-engage-banda-ancha-de-alta-velocidad-en-zonas-rurales\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abf4f49 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"abf4f49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55b1ea4 elementor-widget elementor-widget-text-editor\" data-id=\"55b1ea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><a href=\"\/en\/proyecto-supercomputing-electromagnetics-for-plasmonic-nanostructures-application-to-optical-nanoantennas-and-metamaterials\/\">Supercomputing electromagnetics for plasmonic nanostructures. Application to optical nanoantennas and metamaterials<\/a><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a title=\"Jos\u00e9 Manuel Taboada\" href=\"http:\/\/tsc.unex.es\/~tabo\/\">Jos\u00e9 Manuel Taboada<\/a>\u00a0del Departamento de Tecnolog\u00eda de los Computadores y de las Comunicaciones de la\u00a0<a title=\"Universidad de Extremadura\" href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p>The unprecedented ability of nano metallic (that is plasmonic) structures to concentrate light into deep-subwavelength volumes has propelled their use in a vast array of nanophotonic technologies and research endeavors. The field of plasmonics has grown dramatically over the past decade and still continues growing towards new directions that are continuously emerging. With the ability to produce highly confined optical fields, the conventional rules for light-matter interactions need to be re-examined,and researchers are venturing into new formulations. We are presenting a project, with the primary objective of extending the scope of applications of exact integral-equation (IE) method of moments (MoM) formulations to the electromagnetic analysis of plasmonic nanostructures and artificial materials(metamaterials) in visible and near-infrared frequency bands.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-supercomputing-electromagnetics-for-plasmonic-nanostructures-application-to-optical-nanoantennas-and-metamaterials\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2054193 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2054193\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aac90d7 elementor-widget elementor-widget-text-editor\" data-id=\"aac90d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-optimization-of-the-diffused-matrix-format-for-heterogeneous-parallel-computing\/\">Optimization of the Diffused Matrix Format for Heterogeneous Parallel Computing<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.unex.es\/conoce-la-uex\/estructura-academica\/departamentos\/ficha_personal?idDpto=Y054&amp;personal=1&amp;idPersonal=CFFD6014918D3D65E9B703275127E674\">David Valencia Corrales<\/a>.\u00a0<a href=\"http:\/\/www.unex.es\/conoce-la-uex\/estructura-academica\/departamentos\/ficha_estructura?idDpto=Y054&amp;estructura=1\">Departamento de Tecnolog\u00eda de los Computadores y de las Comunicaciones<\/a>.\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><li><a href=\"http:\/\/www.unex.es\/conoce-la-uex\/estructura-academica\/departamentos\/ficha_personal?idDpto=Y054&amp;personal=1&amp;idPersonal=5FD1EF74D084CA33B7FD3A94FBE54BEF\">Alejandro Cristo Garc\u00eda<\/a>.\u00a0<a href=\"http:\/\/www.unex.es\/conoce-la-uex\/estructura-academica\/departamentos\/ficha_estructura?idDpto=Y054&amp;estructura=1\">Departamento de Tecnolog\u00eda de los Computadores y de las Comunicaciones<\/a>.\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Con este proyecto se propone la optimizaci\u00f3n de la estructura\u00a0<strong>Diffused Matrix Format<\/strong>\u00a0(DMF), dise\u00f1ada por el grupo de investigaci\u00f3n\u00a0<strong>GRNPS<\/strong>\u00a0para el almacenamiento de im\u00e1genes adquiridas por sensores a bordo de aviones y sat\u00e9lites.<\/li><li>Debido al gran tama\u00f1o de la informaci\u00f3n recogida por dichos sensores, dicha optimizaci\u00f3n se centrar\u00e1 en la indexaci\u00f3n de la estructura mediante un \u00e1rbol tipo\u00a0<a href=\"http:\/\/en.wikipedia.org\/wiki\/Quadtree\">Quad-Tree<\/a>, el cual permitir\u00e1 dividir la imagen en diferentes regiones (nodos DMF) acorde al n\u00famero de mediciones adquiridas<\/li><li>Esta modificaci\u00f3n de la estructura la convierte en potencial para el procesamiento paralelo heterog\u00e9neo, en donde los nodos con mayor n\u00famero de mediciones pueden ser procesados por las m\u00e1quinas m\u00e1s potentes, y viceversa.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-optimization-of-the-diffused-matrix-format-for-heterogeneous-parallel-computing\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7d5edb e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e7d5edb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40d4144 elementor-widget elementor-widget-text-editor\" data-id=\"40d4144\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-cedin-centro-extremeno-de-diseno-industrial\/\">CEDIN (Centro Extreme\u00f1o de Dise\u00f1o Industrial)<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.cetiex.es\/\">CETIEX<\/a>\u00a0(Centro Tecnol\u00f3gico Industrial de Extremadura)<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><strong>CEDIN<\/strong>\u00a0es un proyecto de innovaci\u00f3n tecnol\u00f3gica que surge tras observar las carencias de las empresas extreme\u00f1as tanto en herramientas de dise\u00f1o como en medios para desarrollar nuevos productos o procesos.<\/p><p>La principal innovaci\u00f3n del proyecto est\u00e1 en la forma en que se utilizan los servicios de dise\u00f1o, ya que mediante una herramienta colaborativa online se les permite a las empresas tener un papel fundamental y m\u00e1s participativo en el desarrollo de sus propios dise\u00f1os.<\/p><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-cedin-centro-extremeno-de-diseno-industrial\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cff6dae e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cff6dae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed84b94 elementor-widget elementor-widget-text-editor\" data-id=\"ed84b94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-simulacion-del-computo-masivo-de-lsp-en-sistemas-interdominio\/\">Simulaci\u00f3n del c\u00f3mputo masivo de LSP en sistemas interdominio<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/www.manolodominguez.com\/\">Manuel Dom\u00ednguez-Dorado<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>El objetivo principal de uso de Lusitania en este proyecto es la reducci\u00f3n del coste temporal y de recursos de memoria requeridos por\u00a0<strong>OpenSimRIPCA<\/strong>.\u00a0<strong>OpenSimRIPCA<\/strong>\u00a0es un simulador de redes\u00a0<strong>MPLS<\/strong>\u00a0(Multiprotocol Label Switching) con soporte para c\u00f3mputo de LSP (Label Switched Paths) en entornos interdominio. Como caracter\u00edstica adicional,\u00a0<strong>OpenSimRIPCA<\/strong>\u00a0incorpora avanzados mecanismos de colaboraci\u00f3n ente\u00a0<strong>PCE<\/strong>\u00a0(Path Computation Elements) adyacentes cuyo rendimiento se desea evaluar.<\/li><li>En este proyecto,\u00a0<strong>OpenSimRIPCA<\/strong>\u00a0se utilizar\u00e1 para computar m\u00e1s de 30 millones de\u00a0<strong>LSP<\/strong>\u00a0interdominio sujetos a m\u00faltiples restricciones de ingenier\u00eda de tr\u00e1fico sobre una topolog\u00eda de red Pan-Europea formada por 28 dominios MPLS interconectados y siguiendo una arquitectura\u00a0<strong>PCE<\/strong>. Se evaluar\u00e1 la capacidad de los mecanismos avanzados implementados en\u00a0<strong>OpenSimRIPCA<\/strong>\u00a0para reducir el tiempo de c\u00f3mputo por\u00a0<strong>LSP<\/strong>\u00a0as\u00ed como el volumen global de recursos empleados para ello.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-simulacion-del-computo-masivo-de-lsp-en-sistemas-interdominio\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85257d0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"85257d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a3818 elementor-widget elementor-widget-text-editor\" data-id=\"c9a3818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-nanogather-analisis-y-diseno-de-nuevos-sensores-en-nanotecnologia\/\">NANOGATHER. An\u00e1lisis y dise\u00f1o de nuevos sensores en nanotecnolog\u00eda<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><a href=\"http:\/\/tsc.unex.es\/~llandesa\/members\/landesa\/landesa.html\">Luis Landesa<\/a>\u00a0and\u00a0<a href=\"http:\/\/tsc.unex.es\/~llandesa\/members\/tabo\/tabo.html\">Jos\u00e9 Manuel Taboada<\/a>\u00a0del Departamento de Tecnolog\u00eda de los Computadores y de las Comunicaciones de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Los nanosensores basados en nanoantenas permiten superar el l\u00edmite de difracci\u00f3n de los dispositivos \u00f3pticos tradicionales, es decir, permiten capturar o dirigir la emisi\u00f3n de luz con precisiones inferiores a la longitud de onda. Esto est\u00e1 abriendo un amplio abanico de nuevas aplicaciones, desde la fabricaci\u00f3n de nuevos detectores con capacidad de observar objetos con precisiones por debajo de la longitud de onda de la luz hasta nuevos dispositivos de comunicaciones de gran ancho de banda y pasando por nuevos dispositivos de almacenamiento de elevada capacidad. Una de las caracter\u00edsticas esenciales de las nanoantenas es la naturaleza plasm\u00f3nica del comportamiento electromagn\u00e9tico de los metales. En el proyecto se pretende conseguir nuevos resultados y nuevas estructuras para mejorar las caracter\u00edsticas de las nanoantenas.<\/li><li>Los objetivos concretos planteados son:<p>\u00a0<\/p><ul><li>Dise\u00f1o de nanoantenas formadas por nanotubos de oro y optimizadas para incrementar sus prestaciones.<\/li><li>An\u00e1lisis de los efectos de las imperfecciones en las nanoantenas.<\/li><li>Estudio del comportamiento electromagn\u00e9tico de nanomateriales.<\/li><\/ul><\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-nanogather-analisis-y-diseno-de-nuevos-sensores-en-nanotecnologia\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfc126b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cfc126b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa307f2 elementor-widget elementor-widget-text-editor\" data-id=\"fa307f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-colaboracion-con-el-observatorio-tecnologico-uex-hp\/\">Colaboraci\u00f3n con el Observatorio Tecnol\u00f3gico UEx-HP<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><p><a href=\"https:\/\/computaex.eu\/\">COMPUTAEX<\/a>\u00a0firm\u00f3 el 7 de mayo un acuerdo con la multinacional\u00a0<a href=\"http:\/\/www.hp.com\/\">HP<\/a>\u00a0mediante el cual la Fundaci\u00f3n albergar\u00e1 la infraestructura de productos hardware que HP aportar\u00e1 para llevar a cabo un Proyecto de Cloud Computing. De este modo\u00a0<a href=\"https:\/\/computaex.eu\/fundacion\">COMPUTAEX<\/a>\u00a0y su centro\u00a0<a href=\"http:\/\/www.cenits.es\/\">C\u00e9nitS<\/a>\u00a0colaboran en el desarrollo del\u00a0<strong>Observatorio Tecnol\u00f3gico<\/strong>\u00a0creado por la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>\u00a0and\u00a0<strong>Hewlett Packard<\/strong>\u00a0para el fomento de la\u00a0<strong>I+D+IT<\/strong>.<\/p><\/div><\/div><\/div><\/div><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-colaboracion-con-el-observatorio-tecnologico-uex-hp\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27ed19f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"27ed19f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8225a35 elementor-widget elementor-widget-text-editor\" data-id=\"8225a35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-algoritmos-paralelos-heterogeneos-para-procesamiento-de-imagenes-multicanal\/\">Algoritmos paralelos heterog\u00e9neos para procesamiento de im\u00e1genes multicanal<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>David Valencia Corrales<\/strong>. Departamento Tecnolog\u00edas de los computadores y de las comunicaciones de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Balanceo de carga eficiente con distribuci\u00f3n heterog\u00e9nea de datos en base a la potencia de c\u00e1lculo disponible.<\/li><li>Evaluaci\u00f3n de patrones de computaci\u00f3n y comunicaci\u00f3n heterog\u00e9neos y eficientes.<\/li><li>Evaluaci\u00f3n de compiladores y librer\u00edas del sistema para mejorar el rendimiento de los algoritmos paralelos con distribuci\u00f3n de carga din\u00e1mica.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-algoritmos-paralelos-heterogeneos-para-procesamiento-de-imagenes-multicanal\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0e323c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"c0e323c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06ad5e7 elementor-widget elementor-widget-text-editor\" data-id=\"06ad5e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-evaluacion-de-azequiampi\/\">Evaluaci\u00f3n de AzequiaMPI<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Juan Carlos D\u00edaz Mart\u00edn<\/strong>\u00a0del grupo GIM (Grupo de Ingenier\u00eda de Medios) del DISIT (Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos) y del DACC (Departamento de Arquitectura de Computadores y Comunicaciones) de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>MPI<\/strong>\u00a0es el est\u00e1ndar de hecho en la programaci\u00f3n de supercomputadores. Las implementaciones actuales del est\u00e1ndar no consiguen escalar adecuadamente en arquitecturas basadas en clusters multicore o\u00a0<strong>NUMA<\/strong>. Las aplicaciones deben ser construidas de forma que exploten el paralelismo en dos niveles: memoria distribuida mediante\u00a0<strong>MPI<\/strong>, y memoria compartida mediante hilos (<strong>Open MP<\/strong>\u00a0o\u00a0<strong>Pthreads<\/strong>), en lo que se denomina sistema h\u00edbrido.<\/li><li>AzequiaMPI es la primera implementaci\u00f3n completa del est\u00e1ndar MPI-1 basada en hilos y explota nativamente este tipo de sistemas. El objetivo fundamental del proyecto es evaluar la implementaci\u00f3n actual en cuanto a rendimiento, escalabilidad y soporte para aplicaciones cient\u00edficas. Para ello se comparar\u00e1n los resultados con otras implementaciones bien conocidas como\u00a0<strong>MPICH2<\/strong>,\u00a0<strong>Intel MPI<\/strong>\u00a0o\u00a0<strong>HP-MPI<\/strong>, y se mejorar\u00e1, en lo posible, su comportamiento en grandes supercomputadores de memoria compartida.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-evaluacion-de-azequiampi\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9198a4f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9198a4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45091ea elementor-widget elementor-widget-text-editor\" data-id=\"45091ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-supercomputacion-y-desarrollo-grid\/\">Supercomputaci\u00f3n y Desarrollo GRID<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Antonio Mu\u00f1oz Rold\u00e1n<\/strong>\u00a0perteneciente al Departamento de Inform\u00e1tica del\u00a0<a href=\"http:\/\/www.ciemat.es\/\">CIEMAT<\/a>.<\/li><li>Financiado por el Centro de Investigaciones Energ\u00e9ticas, Medioambientales y Tecnol\u00f3gicas\u00a0<a href=\"http:\/\/www.ciemat.es\/\">CIEMAT<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Ofrecer soporte a los investigadores del\u00a0<a href=\"http:\/\/www.ciemat.es\/\">CIEMAT<\/a>\u00a0para la parelizaci\u00f3n y portabilidad de sus c\u00f3digos fuentes para aplicar t\u00e9cnicas de supercomputaci\u00f3n.<\/li><li>En particular, en este proyecto se realizar\u00e1n tambi\u00e9n investigaciones en Reconstrucci\u00f3n de Im\u00e1genes por\u00a0<strong>Tomograf\u00eda Axial<\/strong>\u00a0en PET y\u00a0<strong>Simulaciones Monte Carlo<\/strong>\u00a0de Trasporte de electrones.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-supercomputacion-y-desarrollo-grid\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0b33bc e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b0b33bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc06323 elementor-widget elementor-widget-text-editor\" data-id=\"bc06323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-diseno-y-simulacion-de-dispositivos-y-sistemas-de-comunicaciones-opticas\/\">Dise\u00f1o y Simulaci\u00f3n de Dispositivos y Sistemas de Comunicaciones \u00d3pticas<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Rafael G\u00f3mez Alcal\u00e1<\/strong>\u00a0del Departamento de Tecnolog\u00eda de los Computadores y las Comunicaciones de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>Desarrollo de herramientas computacionales que permitan el dise\u00f1o y simulaci\u00f3n de dispositivos y sistemas de comunicaciones \u00f3pticas. El principal problema que surge en este tipo de an\u00e1lisis y dise\u00f1o es la elevada complejidad computacional, lo que requiere el uso de recursos intensivos de computaci\u00f3n.<\/li><li>Con el proyecto se pretende poner a punto un simulador de dispositivos fot\u00f3nicos y optoelectr\u00f3nicos que permita analizar de forma gen\u00e9rica un sistema comercial de comunicaciones \u00f3pticas.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-diseno-y-simulacion-de-dispositivos-y-sistemas-de-comunicaciones-opticas\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88f1af1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"88f1af1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98fbf3e elementor-widget elementor-widget-text-editor\" data-id=\"98fbf3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\"><div class=\"field-items\"><div class=\"field-item even\"><header><h2 class=\"title\"><span style=\"font-size: 14pt;\"><a href=\"\/en\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/\">com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx<\/a><\/span><\/h2><\/header><div class=\"content node-proyecto\"><div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li><strong>Alfonso Gazo Cervero y Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez<\/strong>\u00a0del grupo\u00a0<strong>G\u00cdTACA<\/strong>\u00a0(<a href=\"http:\/\/gitaca.unex.es\/\">Grupo de Ingenier\u00eda Telem\u00e1tica Aplicada y Comunicaciones Avanzadas<\/a>) del\u00a0<strong>DISIT<\/strong>\u00a0(Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos) de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>, en convenio con la empresa Aplicaciones Integrales e Industriales Grupo G5.<\/li><\/ul><\/div><\/div><\/div><div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\"><div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div><div class=\"field-items\"><div class=\"field-item even\"><ul><li>El principal objetivo perseguido con este proyecto es realizar una predicci\u00f3n de la evoluci\u00f3n de las infoestructuras de comunicaciones actuales, proyect\u00e1ndolas a la pr\u00f3xima d\u00e9cada para determinar, mediante t\u00e9cnicas predictivas y con la ayuda de la supercomputaci\u00f3n, las necesidades t\u00e9cnicas e inversoras, en cuanto a topolog\u00edas y tecnolog\u00edas de redes y comunicaciones se refiere. Se usar\u00e1 la supercomputaci\u00f3n para ejecutar los flujos reales de tr\u00e1fico que se producen en la Intranet extreme\u00f1a; en la red acad\u00e9mica espa\u00f1ola\u00a0<a href=\"http:\/\/www.rediris.es\/\">RedIRIS<\/a>; en la red europea\u00a0<strong>GEANT<\/strong>; y en la red americana AT&amp;T. Con estas topolog\u00edas, soportadas sobre el\u00a0<a href=\"https:\/\/computaex.eu\/cenits\/lusitania\">supercomputador LUSITANIA<\/a>, se simular\u00e1n y extrapolar\u00e1n los resultados hacia la predicci\u00f3n de sus evoluciones tecnol\u00f3gicas para poder inferir los requerimientos de necesidades y servicios en los pr\u00f3ximos a\u00f1os.<\/li><li>El segundo gran objetivo del proyecto\u00a0<strong>com.info.com<\/strong>\u00a0es aplicar las lecciones aprendidas en la anterior etapa al despliegue de\u00a0<strong>FTTx<\/strong>( Fiber To The x, donde x es Home, Building, etc.) que se presenta en los \u00faltimos tiempos como la alternativa a la actual conectividad por medio de ADSL. Se prev\u00e9n muy importantes inversiones y esfuerzos en los pr\u00f3ximos a\u00f1os para el despliegue de la fibra \u00f3ptica hasta nuestros hogares y empresas. Planificar las operaciones log\u00edsticas y las inversiones se convierte en una necesidad muy importante para muchas empresas del sector que se enfrentan a elevadas barreras de entrada a este \u00e1rea de negocio por las dificultades que supone poder prever con precisi\u00f3n los costes y necesidades tecnol\u00f3gicas. En este subproyecto proponemos desarrollar un producto software que, recurriendo a la supercomputaci\u00f3n, sirva para analizar todas las posibilidades de despliegue de infoestructuras en zonas concretas antes de acometerlas para optimizar los recursos y los costes.<\/li><\/ul><\/div><\/div><\/div><\/div><p style=\"text-align: right;\"><a href=\"\/en\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/\">Leer mas<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Detecci\u00f3n de Ataques mediante t\u00e9cnicas Side-channel y de Inteligencia Artificial en entornos IoT (DASIA-IoT). Investigadores:\u00a0 Felipe Alejandro Lemus y\u00a0Alejandro Dom\u00ednguez. IdiomaSin definirDescripci\u00f3n:\u00a0 La eclosi\u00f3n de la tecnolog\u00eda Internet de las &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-4854","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciencias Inform\u00e1ticas y de Comunicaciones - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciencias Inform\u00e1ticas y de Comunicaciones - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Detecci\u00f3n de Ataques mediante t\u00e9cnicas Side-channel y de Inteligencia Artificial en entornos IoT (DASIA-IoT). Investigadores:\u00a0 Felipe Alejandro Lemus y\u00a0Alejandro Dom\u00ednguez. IdiomaSin definirDescripci\u00f3n:\u00a0 La eclosi\u00f3n de la tecnolog\u00eda Internet de las ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T08:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/sites\/cenits.es\/files\/proyectos\/flujostrafico_1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"65 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/\",\"name\":\"Ciencias Inform\u00e1ticas y de Comunicaciones - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/computaex.es\\\/sites\\\/cenits.es\\\/files\\\/proyectos\\\/flujostrafico_1.png\",\"datePublished\":\"2025-01-17T09:06:20+00:00\",\"dateModified\":\"2025-08-28T08:14:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/computaex.es\\\/sites\\\/cenits.es\\\/files\\\/proyectos\\\/flujostrafico_1.png\",\"contentUrl\":\"https:\\\/\\\/computaex.es\\\/sites\\\/cenits.es\\\/files\\\/proyectos\\\/flujostrafico_1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/ciencias-informaticas-y-de-comunicaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciencias Inform\u00e1ticas y de Comunicaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciencias Inform\u00e1ticas y de Comunicaciones - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/","og_locale":"en_US","og_type":"article","og_title":"Ciencias Inform\u00e1ticas y de Comunicaciones - Fundaci\u00f3n COMPUTAEX","og_description":"Detecci\u00f3n de Ataques mediante t\u00e9cnicas Side-channel y de Inteligencia Artificial en entornos IoT (DASIA-IoT). Investigadores:\u00a0 Felipe Alejandro Lemus y\u00a0Alejandro Dom\u00ednguez. IdiomaSin definirDescripci\u00f3n:\u00a0 La eclosi\u00f3n de la tecnolog\u00eda Internet de las ...","og_url":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-28T08:14:47+00:00","og_image":[{"url":"https:\/\/computaex.es\/sites\/cenits.es\/files\/proyectos\/flujostrafico_1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"65 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/","url":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/","name":"Ciencias Inform\u00e1ticas y de Comunicaciones - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/#primaryimage"},"image":{"@id":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/computaex.es\/sites\/cenits.es\/files\/proyectos\/flujostrafico_1.png","datePublished":"2025-01-17T09:06:20+00:00","dateModified":"2025-08-28T08:14:47+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/#primaryimage","url":"https:\/\/computaex.es\/sites\/cenits.es\/files\/proyectos\/flujostrafico_1.png","contentUrl":"https:\/\/computaex.es\/sites\/cenits.es\/files\/proyectos\/flujostrafico_1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/ciencias-informaticas-y-de-comunicaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Ciencias Inform\u00e1ticas y de Comunicaciones"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/4854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=4854"}],"version-history":[{"count":31,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/4854\/revisions"}],"predecessor-version":[{"id":9856,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/4854\/revisions\/9856"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=4854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=4854"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=4854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}