{"id":2479,"date":"2024-04-11T09:11:36","date_gmt":"2024-04-11T07:11:36","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2479"},"modified":"2025-08-29T11:56:15","modified_gmt":"2025-08-29T09:56:15","slug":"proyecto-afimec-centro-de-formacion-profesional","status":"publish","type":"page","link":"http:\/\/52.47.32.16\/en\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/","title":{"rendered":"Afimec Centro de Formaci\u00f3n Profesional"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li><a href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX Foundation<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-logo field-type-image field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\"><a class=\"colorbox init-colorbox-processed cboxElement\" title=\"Afimec Centro de Formaci\u00f3n Profesional\" href=\"https:\/\/www.cenits.es\/wp-content\/uploads\/2025\/01\/afimec_logo.jpg\" data-colorbox-gallery=\"\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/afimec_logo.jpg?itok=cqToEnqJ\" alt=\"\" width=\"185\" height=\"183\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Description:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/www.afimec.es\/\">AFIMEC<\/a>\u00a0es una empresa que dedica su actividad principal a la ense\u00f1anza, abarcando a numerosos colectivos y campos de la formaci\u00f3n. Para ello, y desde sus inicios se ha ido consolidando un grupo humano altamente profesional y cualificado para el desarrollo de su actividad.\u00a0<a href=\"http:\/\/www.afimec.es\/\">AFIMEC Formaci\u00f3n<\/a>, posee dos sedes (Badajoz y Almendralejo) donde realizan sus actividades e imparten cursos de formaci\u00f3n a sus alumnos.<\/p>\n<p>Se ha desarrollado un sistema de innovaci\u00f3n que mejorase la productividad y la competitividad de las actividades del centro de formaci\u00f3n, mediante el estudio de implantaci\u00f3n de herramientas cloud para la gesti\u00f3n de toda la organizaci\u00f3n y ahorro de costes con el uso de SaaS (Software as a Service) e IaaS (Infraestructure as a Service) para unificar las infraestructuras inform\u00e1ticas de sus diferentes sedes.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Dispon\u00edan de un\u00a0<strong>ERP<\/strong>\u00a0(Enterprise Resource Planner) que conllevaba una infraestructura com\u00fan para permitir el acceso a los recursos compartidos. Ese servidor requer\u00eda de un tratamiento y estudio muy exhaustivo ya que la informaci\u00f3n que conten\u00eda es muy importante para el grupo empresarial.<\/li>\n<li>Se requer\u00eda el estudio y la evaluaci\u00f3n de mecanismos de copia de seguridad para mantener la informaci\u00f3n del servidor replicada y segura ante posibles ataques a sus servicios o ante fallos.<\/li>\n<li>Se requer\u00eda un estudio de las comunicaciones locales, as\u00ed como los caminos que sigue la informaci\u00f3n para verificar que no exista ning\u00fan punto de fuga o de acceso a la informaci\u00f3n privada de la empresa.<\/li>\n<li>Los responsables de la empresa, expusieron la necesidad de un\u00a0<strong>CRM<\/strong>\u00a0(Customer Relationship Management).<\/li>\n<li>Necesidad de implantar un mecanismo para compartir documentos entre diferentes empresas con las que vienen colaborando.<\/li>\n<li>Necesidad de implementar un mecanismo con permisos para los usuarios de manera que se restrinja el acceso a los documentos.<\/li>\n<li>Inter\u00e9s en la implantaci\u00f3n de pizarras digitales en sus clases que fueran compatibles tanto con plataformas Windows como Linux.<\/li>\n<li>Estudiar la mejora que conllevara la implantaci\u00f3n de una plataforma\u00a0<a href=\"https:\/\/\/en\/moodle.org\/?lang=es\">Moodle<\/a>\u00a0en sus servidores para poder ofrecer los cursos a sus alumnos tanto en local (dentro de sus instalaciones) como en el hogar del alumno.<\/li>\n<li>Necesidad de mantener un gran n\u00famero de licencias para desarrollar las labores docentes en las aulas, buscando el ahorro de las mismas a trav\u00e9s de despliegue de plataformas SAAS (Software as a Service).<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos-alcanzados field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objetivos alcanzados:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Realizaci\u00f3n de un an\u00e1lisis de la infraestructura, evaluaci\u00f3n de los riesgos y desarrollo de una pol\u00edtica de seguridad adecuada al centro.<\/li>\n<li>Desarrollo de pol\u00edticas de seguridad para compartir la informaci\u00f3n.<\/li>\n<li>Creaci\u00f3n de un mecanismo de pol\u00edticas de copias de seguridad, tanto locales, como remotas.<\/li>\n<li>An\u00e1lisis de diferentes\u00a0<strong>CRM<\/strong>\u00a0que puedan ser modificados e implantados como l\u00f3gica de negocio con los clientes del conglomerado de empresas a las que\u00a0<a href=\"http:\/\/www.afimec.es\/\">AFIMEC Formaci\u00f3n<\/a>\u00a0pertenece.<\/li>\n<li>Evaluaci\u00f3n de mejoras para la docencia en las aulas de formaci\u00f3n virtuales a trav\u00e9s de plataformas de cursos virtuales.<\/li>\n<li>An\u00e1lisis de herramientas que permitan el ahorro de costes a la hora de implantar los cursos de formaci\u00f3n sin necesidad de una instalaci\u00f3n dedicada en cada m\u00e1quina.<\/li>\n<li>Estudio de plataformas de pizarra digital que permitan una mayor interacci\u00f3n del profesor y los alumnos con los contenidos en clase.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-financiacion field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Sources of funding:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.extremaduraavante.es\/index.php\/innovacion\/plan-de-innovacion-para-la-pyme\/programa-dime-innovacion-2\/91-plan-de-innovacion-para-la-pyme\">Plan de Innovaci\u00f3n para la PYME<\/a> de la Consejer\u00eda de Empleo, Empresa e Innovaci\u00f3n del Gobierno de Extremadura, gestionado por Extremadura Avante y cofinanciado con Fondo Social Europeo (FSE), Programa Operativo de Extremadura 2007-2013<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Fundaci\u00f3n COMPUTAEX Descripci\u00f3n:\u00a0 AFIMEC\u00a0es una empresa que dedica su actividad principal a la ense\u00f1anza, abarcando a numerosos colectivos y campos de la formaci\u00f3n. Para ello, y desde sus inicios &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[104,81],"tags":[],"class_list":["post-2479","page","type-page","status-publish","hentry","category-ciencias-informaticas-y-de-comunicaciones","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afimec Centro de Formaci\u00f3n Profesional - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afimec Centro de Formaci\u00f3n Profesional - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Fundaci\u00f3n COMPUTAEX Descripci\u00f3n:\u00a0 AFIMEC\u00a0es una empresa que dedica su actividad principal a la ense\u00f1anza, abarcando a numerosos colectivos y campos de la formaci\u00f3n. Para ello, y desde sus inicios ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:56:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/afimec_logo.jpg?itok=cqToEnqJ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/\",\"name\":\"Afimec Centro de Formaci\u00f3n Profesional - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cenits.es\\\/sites\\\/cenits.es\\\/files\\\/styles\\\/proyecto\\\/public\\\/proyectos\\\/afimec_logo.jpg?itok=cqToEnqJ\",\"datePublished\":\"2024-04-11T07:11:36+00:00\",\"dateModified\":\"2025-08-29T09:56:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cenits.es\\\/sites\\\/cenits.es\\\/files\\\/styles\\\/proyecto\\\/public\\\/proyectos\\\/afimec_logo.jpg?itok=cqToEnqJ\",\"contentUrl\":\"https:\\\/\\\/www.cenits.es\\\/sites\\\/cenits.es\\\/files\\\/styles\\\/proyecto\\\/public\\\/proyectos\\\/afimec_logo.jpg?itok=cqToEnqJ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-afimec-centro-de-formacion-profesional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Afimec Centro de Formaci\u00f3n Profesional\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afimec Centro de Formaci\u00f3n Profesional - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/","og_locale":"en_US","og_type":"article","og_title":"Afimec Centro de Formaci\u00f3n Profesional - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Fundaci\u00f3n COMPUTAEX Descripci\u00f3n:\u00a0 AFIMEC\u00a0es una empresa que dedica su actividad principal a la ense\u00f1anza, abarcando a numerosos colectivos y campos de la formaci\u00f3n. Para ello, y desde sus inicios ...","og_url":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T09:56:15+00:00","og_image":[{"url":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/afimec_logo.jpg?itok=cqToEnqJ","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/","name":"Afimec Centro de Formaci\u00f3n Profesional - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/#primaryimage"},"image":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/afimec_logo.jpg?itok=cqToEnqJ","datePublished":"2024-04-11T07:11:36+00:00","dateModified":"2025-08-29T09:56:15+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/#primaryimage","url":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/afimec_logo.jpg?itok=cqToEnqJ","contentUrl":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/afimec_logo.jpg?itok=cqToEnqJ"},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-afimec-centro-de-formacion-profesional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Afimec Centro de Formaci\u00f3n Profesional"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/2479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=2479"}],"version-history":[{"count":5,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/2479\/revisions"}],"predecessor-version":[{"id":5254,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/2479\/revisions\/5254"}],"up":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=2479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=2479"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=2479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}