{"id":1587,"date":"2024-04-03T10:34:01","date_gmt":"2024-04-03T08:34:01","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=1587"},"modified":"2025-07-28T08:55:57","modified_gmt":"2025-07-28T06:55:57","slug":"convenios-y-colaboraciones","status":"publish","type":"page","link":"http:\/\/52.47.32.16\/en\/convenios-y-colaboraciones\/","title":{"rendered":"Agreements and Collaborations"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1587\" class=\"elementor elementor-1587\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb39beb e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"cb39beb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29c4a61 elementor-grid-eael-col-4 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"29c4a61\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-4&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"eael-post-grid-29c4a61\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-29c4a61 eael-post-grid-style-one\" data-layout-mode=\"masonry\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11987 category-2026-colaboracion\" data-id=\"11987\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-abre-la-puerta-de-las-capacidades-avanzadas-de-la-inteligencia-artificial-al-ecosistema-empresarial-extremeno-a-traves-del-proyecto-ai-factory\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"122\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/LOGO-IA-FACTORY__BSC-300x122.png\" class=\"attachment-medium size-medium wp-image-11988\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/LOGO-IA-FACTORY__BSC-300x122.png 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/LOGO-IA-FACTORY__BSC-18x7.png 18w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/LOGO-IA-FACTORY__BSC.png 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-abre-la-puerta-de-las-capacidades-avanzadas-de-la-inteligencia-artificial-al-ecosistema-empresarial-extremeno-a-traves-del-proyecto-ai-factory\/\" title=\"COMPUTAEX abre la puerta de las capacidades avanzadas de la Inteligencia Artificial al ecosistema empresarial extreme\u00f1o a trav\u00e9s del proyecto AI Factory\">COMPUTAEX abre la puerta de las capacidades avanzadas de la Inteligencia Artificial al ecosistema empresarial extreme\u00f1o a trav\u00e9s del proyecto AI Factory<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX, el Centro de Supercomputaci\u00f3n de Extremadura, participa en el...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-abre-la-puerta-de-las-capacidades-avanzadas-de-la-inteligencia-artificial-al-ecosistema-empresarial-extremeno-a-traves-del-proyecto-ai-factory\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"12 de June de 2026\">12 de June de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11935 category-2026-colaboracion\" data-id=\"11935\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/ceta-ciemat-ciiae-y-computaex-establecen-un-marco-de-colaboracion-en-computacion-cientifica-aplicada-al-almacenamiento-energetico-en-extremadura\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-300x200.jpg\" class=\"attachment-medium size-medium wp-image-11936\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-300x200.jpg 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-1024x683.jpg 1024w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-768x512.jpg 768w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-1536x1024.jpg 1536w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-2048x1365.jpg 2048w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/06\/2026_03-18x12.jpg 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/ceta-ciemat-ciiae-y-computaex-establecen-un-marco-de-colaboracion-en-computacion-cientifica-aplicada-al-almacenamiento-energetico-en-extremadura\/\" title=\"CETA-CIEMAT, CIIAE y COMPUTAEX establecen un marco de colaboraci\u00f3n en computaci\u00f3n cient\u00edfica aplicada al almacenamiento energ\u00e9tico en Extremadura\">CETA-CIEMAT, CIIAE y COMPUTAEX establecen un marco de colaboraci\u00f3n en computaci\u00f3n cient\u00edfica aplicada al almacenamiento energ\u00e9tico en Extremadura<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El Director General del Centro de Supercomputaci\u00f3n de Extremadura (COMPUTAEX),...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/ceta-ciemat-ciiae-y-computaex-establecen-un-marco-de-colaboracion-en-computacion-cientifica-aplicada-al-almacenamiento-energetico-en-extremadura\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"8 de June de 2026\">8 de June de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11807 category-colaboracion\" data-id=\"11807\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-acerca-las-vocaciones-stem-a-cerca-de-500-escolares-extremenos-a-traves-del-proyecto-somos-investigadoras\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-11818\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-300x200.jpg 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-1024x683.jpg 1024w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-768x512.jpg 768w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-1536x1024.jpg 1536w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-2048x1365.jpg 2048w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/05\/20260429_Somos-Investigadoras_1-18x12.jpg 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-acerca-las-vocaciones-stem-a-cerca-de-500-escolares-extremenos-a-traves-del-proyecto-somos-investigadoras\/\" title=\"COMPUTAEX acerca las vocaciones STEM a cerca de 500 escolares extreme\u00f1os a trav\u00e9s del proyecto Somos investigadoras\">COMPUTAEX acerca las vocaciones STEM a cerca de 500 escolares extreme\u00f1os a trav\u00e9s del proyecto Somos investigadoras<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Del 27 al 30 de abril, cerca de 500 escolares...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-acerca-las-vocaciones-stem-a-cerca-de-500-escolares-extremenos-a-traves-del-proyecto-somos-investigadoras\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"7 de May de 2026\">7 de May de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11687 category-colaboracion\" data-id=\"11687\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-se-suma-al-programa-nacional-somos-investigadoras-para-fomentar-las-vocaciones-cientificas-en-ninas\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"300\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/Somos-Investigadoras_Cartel_v5-210x300.jpg\" class=\"attachment-medium size-medium wp-image-11692\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/Somos-Investigadoras_Cartel_v5-210x300.jpg 210w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/Somos-Investigadoras_Cartel_v5-8x12.jpg 8w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/Somos-Investigadoras_Cartel_v5.jpg 635w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-se-suma-al-programa-nacional-somos-investigadoras-para-fomentar-las-vocaciones-cientificas-en-ninas\/\" title=\"COMPUTAEX se suma al programa nacional \u201cSomos Investigadoras\u201d para fomentar las vocaciones cient\u00edficas en ni\u00f1as\">COMPUTAEX se suma al programa nacional \u201cSomos Investigadoras\u201d para fomentar las vocaciones cient\u00edficas en ni\u00f1as<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX, el Centro de Supercomputaci\u00f3n de Extremadura, como nodo de...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-se-suma-al-programa-nacional-somos-investigadoras-para-fomentar-las-vocaciones-cientificas-en-ninas\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de April de 2026\">16 de April de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11634 category-colaboracion-cuantica\" data-id=\"11634\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/cuantica\/computaex-celebra-el-world-quantum-day-con-la-participacion-de-mas-de-setenta-alumnos-de-educacion-secundaria-y-formacion-profesional\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-11635\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-300x200.jpg 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-1024x683.jpg 1024w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-768x512.jpg 768w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-1536x1024.jpg 1536w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-2048x1365.jpg 2048w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/2026_04_14_World-Quantum-Day_1-18x12.jpg 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/cuantica\/computaex-celebra-el-world-quantum-day-con-la-participacion-de-mas-de-setenta-alumnos-de-educacion-secundaria-y-formacion-profesional\/\" title=\"COMPUTAEX celebra el World Quantum Day con la participaci\u00f3n de m\u00e1s de setenta alumnos de Educaci\u00f3n Secundaria y Formaci\u00f3n Profesional\">COMPUTAEX celebra el World Quantum Day con la participaci\u00f3n de m\u00e1s de setenta alumnos de Educaci\u00f3n Secundaria y Formaci\u00f3n Profesional<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El Centro de Supercomputaci\u00f3n de Extremadura (COMPUTAEX) ha celebrado esta...<\/p><a href=\"http:\/\/52.47.32.16\/en\/cuantica\/computaex-celebra-el-world-quantum-day-con-la-participacion-de-mas-de-setenta-alumnos-de-educacion-secundaria-y-formacion-profesional\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"14 de April de 2026\">14 de April de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11550 category-colaboracion\" data-id=\"11550\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer-en-la-marcha-por-la-investigacion-2026\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-212x300.jpg\" class=\"attachment-medium size-medium wp-image-11551\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-212x300.jpg 212w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-725x1024.jpg 725w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-768x1085.jpg 768w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-1087x1536.jpg 1087w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-1449x2048.jpg 1449w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel-8x12.jpg 8w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/20260410_Asociacion_Espanola_Cancer_Macha_Investigacion_2026_cartel.jpg 1754w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer-en-la-marcha-por-la-investigacion-2026\/\" title=\"COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer en la \u201cMarcha por la Investigaci\u00f3n 2026\u201d\">COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer en la \u201cMarcha por la Investigaci\u00f3n 2026\u201d<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El Centro de Supercomputaci\u00f3n de Extremadura (COMPUTAEX) participa en la...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer-en-la-marcha-por-la-investigacion-2026\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"10 de April de 2026\">10 de April de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-11150 category-colaboracion\" data-id=\"11150\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-acoge-una-estancia-de-investigacion-del-instituto-de-astronomia-teorica-y-experimental-de-cordoba-argentina\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-300x225.jpeg\" class=\"attachment-medium size-medium wp-image-11152\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-300x225.jpeg 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-1024x768.jpeg 1024w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-768x576.jpeg 768w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-1536x1152.jpeg 1536w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-2048x1536.jpeg 2048w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/03\/20261103_estancia_investigacion_argentina_alvaro_roy-16x12.jpeg 16w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-acoge-una-estancia-de-investigacion-del-instituto-de-astronomia-teorica-y-experimental-de-cordoba-argentina\/\" title=\"COMPUTAEX acoge una estancia de investigaci\u00f3n del Instituto de Astronom\u00eda Te\u00f3rica y Experimental de C\u00f3rdoba, Argentina\">COMPUTAEX acoge una estancia de investigaci\u00f3n del Instituto de Astronom\u00eda Te\u00f3rica y Experimental de C\u00f3rdoba, Argentina<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La computaci\u00f3n de altas prestaciones constituye una de las principales...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-acoge-una-estancia-de-investigacion-del-instituto-de-astronomia-teorica-y-experimental-de-cordoba-argentina\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"11 de March de 2026\">11 de March de 2026<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-10507 category-colaboracion\" data-id=\"10507\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/el-centro-de-supercomputacion-de-extremadura-impulsa-el-interes-por-la-ciencia-y-la-tecnologia-en-la-ix-semana-de-la-ciencia\/\" title=\"El Centro de Supercomputaci\u00f3n de Extremadura impulsa el inter\u00e9s por la ciencia y la tecnolog\u00eda en la IX Semana de la Ciencia\">El Centro de Supercomputaci\u00f3n de Extremadura impulsa el inter\u00e9s por la ciencia y la tecnolog\u00eda en la IX Semana de la Ciencia<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX participar\u00e1 activamente en la IX Semana de la Ciencia...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/el-centro-de-supercomputacion-de-extremadura-impulsa-el-interes-por-la-ciencia-y-la-tecnologia-en-la-ix-semana-de-la-ciencia\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"29 de October de 2025\">29 de October de 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-10213 category-colaboracion\" data-id=\"10213\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/el-director-general-de-computaex-interviene-en-el-spider-deep-tech-matchmaking-hpc-focus\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"82\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/09\/20250929_Spider-Deep-Tech_HPC_-1.png\" class=\"attachment-medium size-medium wp-image-10214\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/el-director-general-de-computaex-interviene-en-el-spider-deep-tech-matchmaking-hpc-focus\/\" title=\"El Director General de COMPUTAEX interviene en el SPIDER Deep Tech Matchmaking\u2013HPC Focus\">El Director General de COMPUTAEX interviene en el SPIDER Deep Tech Matchmaking\u2013HPC Focus<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El Dr. Juan Antonio Rico, Director General de COMPUTAEX, el...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/el-director-general-de-computaex-interviene-en-el-spider-deep-tech-matchmaking-hpc-focus\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"29 de September de 2025\">29 de September de 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-7812 category-colaboracion tags-cursos\" data-id=\"7812\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-el-instituto-gulich-de-argentina-en-un-curso-internacional-de-postgrado-sobre-hpc-y-procesamiento-de-imagenes\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/computacion-cuantica-8-2-225x300.png\" class=\"attachment-medium size-medium wp-image-11733\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/computacion-cuantica-8-2-225x300.png 225w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/computacion-cuantica-8-2-9x12.png 9w, http:\/\/52.47.32.16\/wp-content\/uploads\/2026\/04\/computacion-cuantica-8-2.png 360w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-el-instituto-gulich-de-argentina-en-un-curso-internacional-de-postgrado-sobre-hpc-y-procesamiento-de-imagenes\/\" title=\"COMPUTAEX colabora con el Instituto Gulich de Argentina en un curso internacional de postgrado sobre HPC y procesamiento de im\u00e1genes\">COMPUTAEX colabora con el Instituto Gulich de Argentina en un curso internacional de postgrado sobre HPC y procesamiento de im\u00e1genes<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El Centro de Supercomputaci\u00f3n de Extremadura, COMPUTAEX, colabora con el...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-el-instituto-gulich-de-argentina-en-un-curso-internacional-de-postgrado-sobre-hpc-y-procesamiento-de-imagenes\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/autorcenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/49a2cd163aad7a8e8e31b25a35bd134c1572b66887763763cbfeed53c655829f?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/49a2cd163aad7a8e8e31b25a35bd134c1572b66887763763cbfeed53c655829f?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/autorcenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de July de 2025\">16 de July de 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-7078 category-colaboracion\" data-id=\"7078\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-qsimov-firman-un-convenio-para-el-impulso-de-la-investigacion-cientifica-en-computacion-cuantica-e-inteligencia-artificial\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"83\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/20250324_convenio_qsimov-e1752565774484.png\" class=\"attachment-medium size-medium wp-image-7261\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-qsimov-firman-un-convenio-para-el-impulso-de-la-investigacion-cientifica-en-computacion-cuantica-e-inteligencia-artificial\/\" title=\"COMPUTAEX y QSIMOV firman un convenio para el impulso de la investigaci\u00f3n cient\u00edfica en Computaci\u00f3n Cu\u00e1ntica e Inteligencia Artificial\">COMPUTAEX y QSIMOV firman un convenio para el impulso de la investigaci\u00f3n cient\u00edfica en Computaci\u00f3n Cu\u00e1ntica e Inteligencia Artificial<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX, el Centro de Supercomputaci\u00f3n de Extremadura, y QSIMOV Quantum...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-qsimov-firman-un-convenio-para-el-impulso-de-la-investigacion-cientifica-en-computacion-cuantica-e-inteligencia-artificial\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"24 de March de 2025\">24 de March de 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-7074 category-colaboracion\" data-id=\"7074\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/20250323_marcha_por_la_investigacion_asoc_cancer_2025_3-e1752575891883.jpg\" class=\"attachment-medium size-medium wp-image-7210\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer\/\" title=\"COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer\">COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX, el Centro de Supercomputaci\u00f3n de Extremadura, colabora con la...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de March de 2025\">21 de March de 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-7068 category-colaboracion\" data-id=\"7068\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-e-intromac-trabajan-en-el-desarrollo-de-gemelos-digitales-sobre-edificaciones\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/prototipo_gemelo_digital_intromac_computaex_3-300x226.jpg\" class=\"attachment-medium size-medium wp-image-7215\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/prototipo_gemelo_digital_intromac_computaex_3-300x226.jpg 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/prototipo_gemelo_digital_intromac_computaex_3-1024x771.jpg 1024w, http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/prototipo_gemelo_digital_intromac_computaex_3-768x578.jpg 768w, http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/prototipo_gemelo_digital_intromac_computaex_3-1536x1157.jpg 1536w, http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/07\/prototipo_gemelo_digital_intromac_computaex_3.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-e-intromac-trabajan-en-el-desarrollo-de-gemelos-digitales-sobre-edificaciones\/\" title=\"COMPUTAEX e INTROMAC trabajan en el desarrollo de Gemelos Digitales sobre edificaciones\">COMPUTAEX e INTROMAC trabajan en el desarrollo de Gemelos Digitales sobre edificaciones<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX, el centro de Supercomputaci\u00f3n de Extremadura, ha comenzado a...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-e-intromac-trabajan-en-el-desarrollo-de-gemelos-digitales-sobre-edificaciones\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"10 de March de 2025\">10 de March de 2025<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-3169 category-colaboracion\" data-id=\"3169\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer-aecc\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"131\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/20240411_aecc.jpg\" class=\"attachment-medium size-medium wp-image-3262\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer-aecc\/\" title=\"COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer (AECC)\">COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer (AECC)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La Fundaci\u00f3n\u00a0COMPUTAEX\u00a0colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer (AECC),...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-con-la-asociacion-espanola-contra-el-cancer-aecc\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"29 de April de 2024\">29 de April de 2024<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-3713 category-colaboracion tags-cursos\" data-id=\"3713\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-la-organizacion-e-imparticion-de-un-curso-de-introduccion-al-desarrollo-de-software-cuantico\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"127\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20230612_curso-cuantica.jpg\" class=\"attachment-medium size-medium wp-image-3715\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-la-organizacion-e-imparticion-de-un-curso-de-introduccion-al-desarrollo-de-software-cuantico\/\" title=\"COMPUTAEX colabora en la organizaci\u00f3n e impartici\u00f3n de un curso de introducci\u00f3n al desarrollo de software cu\u00e1ntico\">COMPUTAEX colabora en la organizaci\u00f3n e impartici\u00f3n de un curso de introducci\u00f3n al desarrollo de software cu\u00e1ntico<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Del 12 al 16 de junio, se ha celebrado en...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-la-organizacion-e-imparticion-de-un-curso-de-introduccion-al-desarrollo-de-software-cuantico\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"12 de June de 2023\">12 de June de 2023<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-3729 category-colaboracion\" data-id=\"3729\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-imparte-una-conferencia-sobre-computacion-cuantica-en-las-oficinas-de-nokia-en-munich\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"65\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20230524_nessi.png\" class=\"attachment-medium size-medium wp-image-3730\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-imparte-una-conferencia-sobre-computacion-cuantica-en-las-oficinas-de-nokia-en-munich\/\" title=\"COMPUTAEX imparte una conferencia sobre computaci\u00f3n cu\u00e1ntica en las oficinas de Nokia en Munich\">COMPUTAEX imparte una conferencia sobre computaci\u00f3n cu\u00e1ntica en las oficinas de Nokia en Munich<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX\u00a0ha tenido el honor ser invitada a impartir una conferencia...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-imparte-una-conferencia-sobre-computacion-cuantica-en-las-oficinas-de-nokia-en-munich\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"24 de May de 2023\">24 de May de 2023<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4019 category-colaboracion\" data-id=\"4019\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/evento-de-presentacion-del-ecosistema-de-salud-de-extremadura-de-la-echalliance\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"131\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20210625_echaliance.jpg\" class=\"attachment-medium size-medium wp-image-4020\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/evento-de-presentacion-del-ecosistema-de-salud-de-extremadura-de-la-echalliance\/\" title=\"Evento de presentaci\u00f3n del Ecosistema de Salud de Extremadura de la ECHAlliance\">Evento de presentaci\u00f3n del Ecosistema de Salud de Extremadura de la ECHAlliance<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El pr\u00f3ximo martes 29 de junio tendr\u00e1 lugar la presentaci\u00f3n...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/evento-de-presentacion-del-ecosistema-de-salud-de-extremadura-de-la-echalliance\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"25 de June de 2021\">25 de June de 2021<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4026 category-colaboracion\" data-id=\"4026\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-las-jornadas-nacionales-de-investigacion-en-ciberseguridad-jnic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"69\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20210607_jnic.png\" class=\"attachment-medium size-medium wp-image-4027\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-las-jornadas-nacionales-de-investigacion-en-ciberseguridad-jnic\/\" title=\"C\u00e9nitS colabora en las Jornadas Nacionales de Investigaci\u00f3n en Ciberseguridad (JNIC)\">C\u00e9nitS colabora en las Jornadas Nacionales de Investigaci\u00f3n en Ciberseguridad (JNIC)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El mi\u00e9rcoles 9 y el jueves 10 de junio van...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-las-jornadas-nacionales-de-investigacion-en-ciberseguridad-jnic\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"7 de June de 2021\">7 de June de 2021<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4040 category-colaboracion\" data-id=\"4040\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/presentacion-del-hub-de-innovacion-digital-de-extremadura-tech4e\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"85\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20210420_dih4e.png\" class=\"attachment-medium size-medium wp-image-4041\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/presentacion-del-hub-de-innovacion-digital-de-extremadura-tech4e\/\" title=\"Presentaci\u00f3n del hub de innovaci\u00f3n digital de Extremadura (Tech4E)\">Presentaci\u00f3n del hub de innovaci\u00f3n digital de Extremadura (Tech4E)<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El pr\u00f3ximo martes 27 de abril a las 12:00 horas...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/presentacion-del-hub-de-innovacion-digital-de-extremadura-tech4e\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"28 de April de 2021\">28 de April de 2021<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4052 category-colaboracion\" data-id=\"4052\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-computaex-firma-su-adhesion-al-pacto-por-la-ciencia-y-la-tecnologia-de-extremadura\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"94\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20210302_pacto-ciencia-tecnologia_01.jpg\" class=\"attachment-medium size-medium wp-image-4053\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-computaex-firma-su-adhesion-al-pacto-por-la-ciencia-y-la-tecnologia-de-extremadura\/\" title=\"C\u00e9nitS-COMPUTAEX firma su adhesi\u00f3n al Pacto por la Ciencia y la Tecnolog\u00eda de Extremadura\">C\u00e9nitS-COMPUTAEX firma su adhesi\u00f3n al Pacto por la Ciencia y la Tecnolog\u00eda de Extremadura<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La Consejer\u00eda de Econom\u00eda, Ciencia y Agenda Digital\u00a0de la\u00a0Junta de...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-computaex-firma-su-adhesion-al-pacto-por-la-ciencia-y-la-tecnologia-de-extremadura\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"2 de March de 2021\">2 de March de 2021<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4047 category-colaboracion\" data-id=\"4047\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-las-jornadas-nacionales-de-investigacion-en-ciberseguridad-jnic\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"69\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20210510_jnic.png\" class=\"attachment-medium size-medium wp-image-4035\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-las-jornadas-nacionales-de-investigacion-en-ciberseguridad-jnic\/\" title=\"COMPUTAEX colabora en las Jornadas Nacionales de Investigaci\u00f3n en Ciberseguridad (JNIC).\">COMPUTAEX colabora en las Jornadas Nacionales de Investigaci\u00f3n en Ciberseguridad (JNIC).<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Del 9 al 11 de junio de 2021 se celebrar\u00e1n...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-las-jornadas-nacionales-de-investigacion-en-ciberseguridad-jnic\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de January de 2021\">16 de January de 2021<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4126 category-colaboracion\" data-id=\"4126\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/se-constituye-el-ecosistema-de-salud-de-extremadura-del-que-forma-parte-cenits\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"122\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20200730_logo-echalliance.png\" class=\"attachment-medium size-medium wp-image-4127\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/se-constituye-el-ecosistema-de-salud-de-extremadura-del-que-forma-parte-cenits\/\" title=\"Se constituye el Ecosistema de Salud de Extremadura, del que forma parte C\u00e9nitS\">Se constituye el Ecosistema de Salud de Extremadura, del que forma parte C\u00e9nitS<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El\u00a0Ecosistema de Salud de Extremadura, recientemente constituido, tendr\u00e1 como objetivos...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/se-constituye-el-ecosistema-de-salud-de-extremadura-del-que-forma-parte-cenits\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"30 de July de 2020\">30 de July de 2020<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4147 category-colaboracion\" data-id=\"4147\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/investigadores-de-cenits-han-publicado-el-articulo-a-methodology-for-network-analysis-to-improve-the-cyber-physicals-communications-in-next-generation-networks-en-la-revista-cientifica-internacion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"79\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20200401_h2020.jpg\" class=\"attachment-medium size-medium wp-image-4148\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/investigadores-de-cenits-han-publicado-el-articulo-a-methodology-for-network-analysis-to-improve-the-cyber-physicals-communications-in-next-generation-networks-en-la-revista-cientifica-internacion\/\" title=\"Investigadores de C\u00e9nitS han publicado el art\u00edculo \u00abA methodology for network analysis to improve the cyber-physicals communications in next-generation networks\u00bb en la revista cient\u00edfica internacional Sensors especializada y con factor de impacto 3,031.\">Investigadores de C\u00e9nitS han publicado el art\u00edculo \u00abA methodology for network analysis to improve the cyber-physicals communications in next-generation networks\u00bb en la revista cient\u00edfica internacional Sensors especializada y con factor de impacto 3,031.<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Esta investigaci\u00f3n se centra en la anal\u00edtica del comportamiento de...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/investigadores-de-cenits-han-publicado-el-articulo-a-methodology-for-network-analysis-to-improve-the-cyber-physicals-communications-in-next-generation-networks-en-la-revista-cientifica-internacion\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de January de 2020\">16 de January de 2020<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4265 category-colaboracion\" data-id=\"4265\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-la-catedra-telefonica-de-la-uex-en-un-curso-internacional-de-verano-sobre-agroganaderia\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"65\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20190902_curso-internacional-verano.png\" class=\"attachment-medium size-medium wp-image-4266\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-la-catedra-telefonica-de-la-uex-en-un-curso-internacional-de-verano-sobre-agroganaderia\/\" title=\"C\u00e9nitS colabora con la C\u00e1tedra Telef\u00f3nica de la UEx en un curso internacional de verano sobre agroganader\u00eda\">C\u00e9nitS colabora con la C\u00e1tedra Telef\u00f3nica de la UEx en un curso internacional de verano sobre agroganader\u00eda<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Del 17 al 19 de septiembre, se desarrollar\u00e1 en la\u00a0Escuela...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-la-catedra-telefonica-de-la-uex-en-un-curso-internacional-de-verano-sobre-agroganaderia\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 de September de 2019\">18 de September de 2019<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4306 category-colaboracion\" data-id=\"4306\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/ingenieros-de-computaex-colaboran-en-un-libro-sobre-la-cuarta-revolucion-industrial\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20190401_-_libro-alicia-guerra.jpg\" class=\"attachment-medium size-medium wp-image-4307\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/ingenieros-de-computaex-colaboran-en-un-libro-sobre-la-cuarta-revolucion-industrial\/\" title=\"Ingenieros de COMPUTAEX colaboran en un libro sobre la Cuarta Revoluci\u00f3n Industrial\">Ingenieros de COMPUTAEX colaboran en un libro sobre la Cuarta Revoluci\u00f3n Industrial<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Actualmente, existe una creciente necesidad de avanzar en las estrategias...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/ingenieros-de-computaex-colaboran-en-un-libro-sobre-la-cuarta-revolucion-industrial\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"2 de April de 2019\">2 de April de 2019<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4440 category-colaboracion\" data-id=\"4440\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-la-universidad-de-guadalajara-en-mexico-firman-un-convenio-marco-de-colaboracion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"136\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2018\/07\/20180716-universidad-guadalajara-mexico_0.png\" class=\"attachment-medium size-medium wp-image-6583\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-la-universidad-de-guadalajara-en-mexico-firman-un-convenio-marco-de-colaboracion\/\" title=\"COMPUTAEX y la Universidad de Guadalajara en M\u00e9xico firman un convenio marco de colaboraci\u00f3n\">COMPUTAEX y la Universidad de Guadalajara en M\u00e9xico firman un convenio marco de colaboraci\u00f3n<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El pr\u00f3ximo jueves 19 de julio est\u00e1 previsto que la\u00a0Fundaci\u00f3n...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-la-universidad-de-guadalajara-en-mexico-firman-un-convenio-marco-de-colaboracion\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de July de 2018\">21 de July de 2018<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4547 category-colaboracion\" data-id=\"4547\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-fundesalud-firman-un-convenio-de-colaboracion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"139\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/whatsapp_image_2017-11-21_at_14.33.59.jpg\" class=\"attachment-medium size-medium wp-image-4548\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-fundesalud-firman-un-convenio-de-colaboracion\/\" title=\"\u200bCOMPUTAEX y FUNDESALUD firman un convenio de colaboraci\u00f3n\">\u200bCOMPUTAEX y FUNDESALUD firman un convenio de colaboraci\u00f3n<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La Fundaci\u00f3n\u00a0COMPUTAEX\u00a0(Computaci\u00f3n y Tecnolog\u00edas Avanzadas de Extremadura) y\u00a0FUNDESALUD\u00a0(Fundaci\u00f3n para la...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-y-fundesalud-firman-un-convenio-de-colaboracion\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"23 de November de 2017\">23 de November de 2017<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4566 category-colaboracion\" data-id=\"4566\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-la-catedra-telefonica-de-la-uex\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"54\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/leadimage_cabecera.jpg\" class=\"attachment-medium size-medium wp-image-4567\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-la-catedra-telefonica-de-la-uex\/\" title=\"C\u00e9nitS colabora con la C\u00e1tedra Telef\u00f3nica de la UEx\">C\u00e9nitS colabora con la C\u00e1tedra Telef\u00f3nica de la UEx<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Durante los d\u00edas 13 al 15 de septiembre se desarrollar\u00e1...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-la-catedra-telefonica-de-la-uex\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"7 de September de 2017\">7 de September de 2017<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4576 category-colaboracion\" data-id=\"4576\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-la-busqueda-de-anticancerigenos-junto-a-investigadores-de-la-universidad-miguel-hernandez-de-elche-y-el-instituto-de-salud-carlos-iii-de-mallorca\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"139\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/vicente_galiano.jpg\" class=\"attachment-medium size-medium wp-image-4577\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-la-busqueda-de-anticancerigenos-junto-a-investigadores-de-la-universidad-miguel-hernandez-de-elche-y-el-instituto-de-salud-carlos-iii-de-mallorca\/\" title=\"C\u00e9nitS colabora en la b\u00fasqueda de anticancer\u00edgenos junto a investigadores de la Universidad Miguel Hern\u00e1ndez de Elche y el Instituto de Salud Carlos III de Mallorca\">C\u00e9nitS colabora en la b\u00fasqueda de anticancer\u00edgenos junto a investigadores de la Universidad Miguel Hern\u00e1ndez de Elche y el Instituto de Salud Carlos III de Mallorca<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Un estudio sobre los compuestos anticancer\u00edgenos marinos existentes y el...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-la-busqueda-de-anticancerigenos-junto-a-investigadores-de-la-universidad-miguel-hernandez-de-elche-y-el-instituto-de-salud-carlos-iii-de-mallorca\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"17 de January de 2017\">17 de January de 2017<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4662 category-colaboracion\" data-id=\"4662\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/investigadores-de-la-universidad-miguel-hernandez-de-elche-y-el-centro-cenits-colaboran-en-la-busqueda-de-inhibidores-contra-el-virus-del-dengue\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"75\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/docked_compound_to_dennv_rdrp.jpg\" class=\"attachment-medium size-medium wp-image-4664\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/investigadores-de-la-universidad-miguel-hernandez-de-elche-y-el-centro-cenits-colaboran-en-la-busqueda-de-inhibidores-contra-el-virus-del-dengue\/\" title=\"Investigadores de la Universidad Miguel Hern\u00e1ndez de Elche y el Centro C\u00e9nitS colaboran en la b\u00fasqueda de inhibidores contra el virus del Dengue\">Investigadores de la Universidad Miguel Hern\u00e1ndez de Elche y el Centro C\u00e9nitS colaboran en la b\u00fasqueda de inhibidores contra el virus del Dengue<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Un estudio sobre la b\u00fasqueda de nuevos inhibidores contra el...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/investigadores-de-la-universidad-miguel-hernandez-de-elche-y-el-centro-cenits-colaboran-en-la-busqueda-de-inhibidores-contra-el-virus-del-dengue\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"9 de November de 2016\">9 de November de 2016<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4773 category-colaboracion\" data-id=\"4773\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-la-divulgacion-de-las-posibilidades-de-big-data\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"139\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/rouro.jpg\" class=\"attachment-medium size-medium wp-image-4774\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-la-divulgacion-de-las-posibilidades-de-big-data\/\" title=\"C\u00e9nitS colabora en la divulgaci\u00f3n de las posibilidades de Big Data\">C\u00e9nitS colabora en la divulgaci\u00f3n de las posibilidades de Big Data<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El espacio televisivo \u00abTu empleo\u00ab, de\u00a0Canal Extremadura, ha emitido un...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-la-divulgacion-de-las-posibilidades-de-big-data\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"17 de November de 2015\">17 de November de 2015<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5235 category-colaboracion\" data-id=\"5235\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-un-proyecto-educativo-transnacional-sobre-green-ict\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"122\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-einfranet.jpg\" class=\"attachment-medium size-medium wp-image-5236\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-un-proyecto-educativo-transnacional-sobre-green-ict\/\" title=\"COMPUTAEX colabora en un proyecto educativo transnacional sobre Green ICT\">COMPUTAEX colabora en un proyecto educativo transnacional sobre Green ICT<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La\u00a0Fundaci\u00f3n COMPUTAEX\u00a0est\u00e1 trabajando en el proyecto\u00a0e-InfraNet\u00a0junto a socios de pa\u00edses...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-colabora-en-un-proyecto-educativo-transnacional-sobre-green-ict\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"12 de August de 2013\">12 de August de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5306 category-colaboracion\" data-id=\"5306\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-y-su-centro-cenits-presentes-en-el-directorio-de-centros-de-datos-para-espana-y-latinoamerica-2013\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"139\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/directorio-2013-latinoamerica-spain.jpg\" class=\"attachment-medium size-medium wp-image-5307\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-y-su-centro-cenits-presentes-en-el-directorio-de-centros-de-datos-para-espana-y-latinoamerica-2013\/\" title=\"La Fundaci\u00f3n COMPUTAEX y su centro C\u00e9nitS presentes en el Directorio de Centros de Datos para Espa\u00f1a y Latinoam\u00e9rica 2013\">La Fundaci\u00f3n COMPUTAEX y su centro C\u00e9nitS presentes en el Directorio de Centros de Datos para Espa\u00f1a y Latinoam\u00e9rica 2013<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>DatacenterDynamicsFocus, una de las revistas internacionales m\u00e1s importantes del sector...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-y-su-centro-cenits-presentes-en-el-directorio-de-centros-de-datos-para-espana-y-latinoamerica-2013\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"2 de July de 2013\">2 de July de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5576 category-colaboracion\" data-id=\"5576\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/convenio-de-colaboracion-sobre-investigacion-en-ultrasecuenciacion-genetica\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"123\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/20110311-reunion-infanta-uex-computaex5.jpg\" class=\"attachment-medium size-medium wp-image-5577\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/convenio-de-colaboracion-sobre-investigacion-en-ultrasecuenciacion-genetica\/\" title=\"Convenio de colaboraci\u00f3n sobre investigaci\u00f3n en ultrasecuenciaci\u00f3n gen\u00e9tica\">Convenio de colaboraci\u00f3n sobre investigaci\u00f3n en ultrasecuenciaci\u00f3n gen\u00e9tica<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>En la reuni\u00f3n celebrada a fecha 11\/03\/11, a la que...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/convenio-de-colaboracion-sobre-investigacion-en-ultrasecuenciacion-genetica\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de May de 2013\">16 de May de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5492 category-colaboracion\" data-id=\"5492\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-continua-su-colaboracion-con-los-masteres-tic-de-la-universidad-de-extremadura\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"132\" height=\"185\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/Cartel_Master_TIC_UEx.jpg\" class=\"attachment-medium size-medium wp-image-5493\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-continua-su-colaboracion-con-los-masteres-tic-de-la-universidad-de-extremadura\/\" title=\"La Fundaci\u00f3n COMPUTAEX contin\u00faa su colaboraci\u00f3n con los M\u00e1steres TIC de la Universidad de Extremadura\">La Fundaci\u00f3n COMPUTAEX contin\u00faa su colaboraci\u00f3n con los M\u00e1steres TIC de la Universidad de Extremadura<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Los\u00a0M\u00e1steres TIC\u00a0impartidos por la\u00a0Universidad de Extremadura\u00a0surgen para dar respuesta a...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-continua-su-colaboracion-con-los-masteres-tic-de-la-universidad-de-extremadura\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de May de 2013\">16 de May de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5446 category-colaboracion\" data-id=\"5446\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-el-plan-de-sistemas-del-gobierno-de-extremadura\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"139\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/reunion-dgaaee-fundaciones.jpg\" class=\"attachment-medium size-medium wp-image-5448\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-el-plan-de-sistemas-del-gobierno-de-extremadura\/\" title=\"C\u00e9nitS colabora en el Plan de Sistemas del Gobierno de Extremadura\">C\u00e9nitS colabora en el Plan de Sistemas del Gobierno de Extremadura<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El director general de Administraci\u00f3n Electr\u00f3nica y Evaluaci\u00f3n,\u00a0Teodomiro Cayetano, se...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-en-el-plan-de-sistemas-del-gobierno-de-extremadura\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de May de 2013\">16 de May de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5433 category-colaboracion\" data-id=\"5433\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-la-i-jornada-de-computacion-distribuida-inteligente-y-sistemas-complejos\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"90\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/jornada-computacion-distribuida-inteligente-sistemas-complejos-2012.jpg\" class=\"attachment-medium size-medium wp-image-5435\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-la-i-jornada-de-computacion-distribuida-inteligente-y-sistemas-complejos\/\" title=\"La Fundaci\u00f3n COMPUTAEX colabora en la I Jornada de Computaci\u00f3n Distribuida Inteligente y Sistemas Complejos\">La Fundaci\u00f3n COMPUTAEX colabora en la I Jornada de Computaci\u00f3n Distribuida Inteligente y Sistemas Complejos<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El\u00a0Ceta-Ciemat\u00a0junto con la\u00a0Universidad de Extremadura\u00a0organiza la\u00a0I Jornada de Computaci\u00f3n Distribuida...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-la-i-jornada-de-computacion-distribuida-inteligente-y-sistemas-complejos\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"16 de May de 2013\">16 de May de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5443 category-colaboracion\" data-id=\"5443\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-el-seminario-internacional-sobre-tic-desarrollo-economico-inteligente\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"48\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/seminario-regional-ebp.jpg\" class=\"attachment-medium size-medium wp-image-5444\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-el-seminario-internacional-sobre-tic-desarrollo-economico-inteligente\/\" title=\"La Fundaci\u00f3n COMPUTAEX colabora en el Seminario Internacional sobre TIC &#038; Desarrollo Econ\u00f3mico Inteligente\">La Fundaci\u00f3n COMPUTAEX colabora en el Seminario Internacional sobre TIC &#038; Desarrollo Econ\u00f3mico Inteligente<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El\u00a0European Broadband Portal\u00a0promueve el\u00a0Seminario Internacional sobre TIC &amp; Desarrollo Econ\u00f3mico...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-el-seminario-internacional-sobre-tic-desarrollo-economico-inteligente\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"13 de May de 2013\">13 de May de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5425 category-colaboracion\" data-id=\"5425\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-nuevamente-con-datacenterdynamics\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"55\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/datacenter-dynamics-converged-2012.jpg\" class=\"attachment-medium size-medium wp-image-5426\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-nuevamente-con-datacenterdynamics\/\" title=\"La Fundaci\u00f3n COMPUTAEX colabora nuevamente con DatacenterDynamics\">La Fundaci\u00f3n COMPUTAEX colabora nuevamente con DatacenterDynamics<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>DatacenterDynamics Converged 2012\u00a0celebra su quinta edici\u00f3n el d\u00eda 12 de...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-nuevamente-con-datacenterdynamics\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"12 de May de 2013\">12 de May de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5271 category-colaboracion\" data-id=\"5271\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-el-programa-dime\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"36\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/programa-dime.jpg\" class=\"attachment-medium size-medium wp-image-5272\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-el-programa-dime\/\" title=\"La Fundaci\u00f3n COMPUTAEX colabora en el programa DIME\">La Fundaci\u00f3n COMPUTAEX colabora en el programa DIME<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>El\u00a0Programa DIME\u00a0es un proyecto desarrollado por\u00a0Extremadura Avante\u00a0con el que se...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-en-el-programa-dime\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"25 de April de 2013\">25 de April de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5301 category-colaboracion\" data-id=\"5301\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"62\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-fcscl.jpg\" class=\"attachment-medium size-medium wp-image-5304\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/\" title=\"La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n\">La FCSCL y COMPUTAEX formalizan un acuerdo de colaboraci\u00f3n<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La\u00a0Fundaci\u00f3n Centro de Supercomputaci\u00f3n de Castilla y Le\u00f3n\u00a0y la\u00a0Fundaci\u00f3n COMPUTAEX\u00a0han...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fcscl-y-computaex-formalizan-un-acuerdo-de-colaboracion\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"11 de February de 2013\">11 de February de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5312 category-colaboracion\" data-id=\"5312\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-firma-un-convenio-de-colaboracion-con-appentra-solutions\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"117\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/logo-appentra.jpg\" class=\"attachment-medium size-medium wp-image-5313\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-firma-un-convenio-de-colaboracion-con-appentra-solutions\/\" title=\"COMPUTAEX firma un convenio de colaboraci\u00f3n con Appentra Solutions\">COMPUTAEX firma un convenio de colaboraci\u00f3n con Appentra Solutions<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>La\u00a0Fundaci\u00f3n COMPUTAEX\u00a0y\u00a0Appentra Solutions\u00a0han formalizado recientemente el convenio que permitir\u00e1 la...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/computaex-firma-un-convenio-de-colaboracion-con-appentra-solutions\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"18 de January de 2013\">18 de January de 2013<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5373 category-colaboracion\" data-id=\"5373\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"148\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/gen.jpg\" class=\"attachment-medium size-medium wp-image-5374\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/\" title=\"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX\">Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Tras m\u00e1s de un a\u00f1o de trabajo, las investigaciones realizadas...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"25 de September de 2012\">25 de September de 2012<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5751 category-colaboracion\" data-id=\"5751\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/extremadura-y-galicia-colaboran-en-supercomputacion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1-300x169.png\" class=\"attachment-medium size-medium wp-image-3267\" alt=\"\" srcset=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1-300x169.png 300w, http:\/\/52.47.32.16\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png 666w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/extremadura-y-galicia-colaboran-en-supercomputacion\/\" title=\"Extremadura y Galicia colaboran en Supercomputaci\u00f3n\">Extremadura y Galicia colaboran en Supercomputaci\u00f3n<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>C\u00e9nitS\u00a0y el\u00a0CESGA\u00a0trabajar\u00e1n juntos en Ciencia Computacional y servicios de supercomputaci\u00f3n...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/extremadura-y-galicia-colaboran-en-supercomputacion\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de January de 2010\">21 de January de 2010<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5729 category-colaboracion\" data-id=\"5729\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-con-el-observatorio-tecnologico-entre-la-universidad-de-extremadura-y-hewlett-packard\/\" title=\"La Fundaci\u00f3n COMPUTAEX colabora con el Observatorio Tecnol\u00f3gico entre la Universidad de Extremadura y Hewlett Packard\">La Fundaci\u00f3n COMPUTAEX colabora con el Observatorio Tecnol\u00f3gico entre la Universidad de Extremadura y Hewlett Packard<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>COMPUTAEX\u00a0anuncia que ha firmado un acuerdo con HP mediante el...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-fundacion-computaex-colabora-con-el-observatorio-tecnologico-entre-la-universidad-de-extremadura-y-hewlett-packard\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de January de 2010\">21 de January de 2010<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5709 category-colaboracion\" data-id=\"5709\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/intromac-y-computaex-firman-un-acuerdo-para-desarrollar-herramientas-que-faciliten-la-investigacion-en-construccion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"210\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/convenio_intromac_computaex_thumb.jpg\" class=\"attachment-medium size-medium wp-image-5712\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/intromac-y-computaex-firman-un-acuerdo-para-desarrollar-herramientas-que-faciliten-la-investigacion-en-construccion\/\" title=\"INTROMAC y COMPUTAEX firman un acuerdo para desarrollar herramientas que faciliten la investigaci\u00f3n en construcci\u00f3n\">INTROMAC y COMPUTAEX firman un acuerdo para desarrollar herramientas que faciliten la investigaci\u00f3n en construcci\u00f3n<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Ambas organizaciones desarrollar\u00e1n proyectos de inter\u00e9s com\u00fan, dentro de los...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/intromac-y-computaex-firman-un-acuerdo-para-desarrollar-herramientas-que-faciliten-la-investigacion-en-construccion\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de January de 2010\">21 de January de 2010<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5615 category-colaboracion\" data-id=\"5615\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-igo-software-sextante-geoservices-y-prodevelop-en-el-proyecto-glob3\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"46\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/glob3.jpg\" class=\"attachment-medium size-medium wp-image-5617\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-igo-software-sextante-geoservices-y-prodevelop-en-el-proyecto-glob3\/\" title=\"C\u00e9nitS colabora con IGO Software, Sextante Geoservices y Prodevelop en el proyecto Glob3\">C\u00e9nitS colabora con IGO Software, Sextante Geoservices y Prodevelop en el proyecto Glob3<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Glob3\u00a0es un proyecto de software libre orientado al desarrollo de...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/cenits-colabora-con-igo-software-sextante-geoservices-y-prodevelop-en-el-proyecto-glob3\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de January de 2010\">21 de January de 2010<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-5608 category-colaboracion\" data-id=\"5608\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-uex-y-hp-espana-completan-la-primera-implantacion-de-cloud-computing-del-pais\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"91\" src=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/01\/cloud_computing.jpg\" class=\"attachment-medium size-medium wp-image-5609\" alt=\"\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-uex-y-hp-espana-completan-la-primera-implantacion-de-cloud-computing-del-pais\/\" title=\"La UEx y HP Espa\u00f1a completan la primera implantaci\u00f3n de \u00abcloud computing\u00bb del pa\u00eds\">La UEx y HP Espa\u00f1a completan la primera implantaci\u00f3n de \u00abcloud computing\u00bb del pa\u00eds<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Hewlett-Packard\u00a0y la\u00a0Universidad de Extremadura\u00a0completan con \u00e9xito la primera instalaci\u00f3n de...<\/p><a href=\"http:\/\/52.47.32.16\/en\/colaboracion\/la-uex-y-hp-espana-completan-la-primera-implantacion-de-cloud-computing-del-pais\/\" class=\"eael-post-elements-readmore-btn\">Leer m\u00e1s<\/a><\/div>\n                    <\/div><div class=\"eael-entry-footer\"><div class=\"eael-author-avatar\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\"><img alt='COMPUTAEX' src='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' \/><\/a><\/div><div class=\"eael-entry-meta\"><span class=\"eael-posted-by\"><a href=\"http:\/\/52.47.32.16\/en\/author\/admincenits\/\" title=\"Posts by COMPUTAEX\" rel=\"author\">COMPUTAEX<\/a><\/span><span class=\"eael-posted-on\"><time datetime=\"21 de January de 2010\">21 de January de 2010<\/time><\/span><\/div><\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer (AECC) La Fundaci\u00f3n\u00a0COMPUTAEX\u00a0colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer (AECC),&#8230; Leer m\u00e1s admincenits29 de abril de 2024 COMPUTAEX colabora en &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-1587","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convenios y colaboraciones - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convenios y colaboraciones - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer (AECC) La Fundaci\u00f3n\u00a0COMPUTAEX\u00a0colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer (AECC),&#8230; Leer m\u00e1s admincenits29 de abril de 2024 COMPUTAEX colabora en ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T06:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.computaex.es\\\/convenios-y-colaboraciones\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/convenios-y-colaboraciones\\\/\",\"name\":\"Convenios y colaboraciones - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-03T08:34:01+00:00\",\"dateModified\":\"2025-07-28T06:55:57+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.computaex.es\\\/convenios-y-colaboraciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.computaex.es\\\/convenios-y-colaboraciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.computaex.es\\\/convenios-y-colaboraciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convenios y colaboraciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/52.47.32.16\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convenios y colaboraciones - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/","og_locale":"en_US","og_type":"article","og_title":"Convenios y colaboraciones - Fundaci\u00f3n COMPUTAEX","og_description":"COMPUTAEX colabora con la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer (AECC) La Fundaci\u00f3n\u00a0COMPUTAEX\u00a0colabora con la Asociaci\u00f3n Espa\u00f1ola contra el C\u00e1ncer (AECC),&#8230; Leer m\u00e1s admincenits29 de abril de 2024 COMPUTAEX colabora en ...","og_url":"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-07-28T06:55:57+00:00","og_image":[{"width":1024,"height":403,"url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/","url":"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/","name":"Convenios y colaboraciones - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-03T08:34:01+00:00","dateModified":"2025-07-28T06:55:57+00:00","breadcrumb":{"@id":"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.computaex.es\/convenios-y-colaboraciones\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.computaex.es\/convenios-y-colaboraciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Convenios y colaboraciones"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/52.47.32.16\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/1587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/comments?post=1587"}],"version-history":[{"count":14,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/1587\/revisions"}],"predecessor-version":[{"id":8927,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/pages\/1587\/revisions\/8927"}],"wp:attachment":[{"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/media?parent=1587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/categories?post=1587"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/52.47.32.16\/en\/wp-json\/wp\/v2\/tags?post=1587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}